{"id":14920,"date":"2019-07-15T15:23:24","date_gmt":"2019-07-15T13:23:24","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=14920"},"modified":"2019-07-16T12:11:21","modified_gmt":"2019-07-16T10:11:21","slug":"buschini-si-alla-costituente-delle-idee-per-proseguire-lazione-di-rilancio-del-pd","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/15\/buschini-si-alla-costituente-delle-idee-per-proseguire-lazione-di-rilancio-del-pd\/","title":{"rendered":"Buschini: s\u00ec alla costituente delle idee per proseguire l&#8217;azione di rilancio del Pd"},"content":{"rendered":"<p class=\"m_251495767420469689MsoNormal_mailru_css_attribute_postfix\">&#8220;<strong>La costituente delle idee<\/strong> lanciata dal segretario Nicola Zingaretti segna l&#8217;inizio di una nuova fase del nostro partito. L&#8217;apertura alle energie migliori della societ\u00e0 determiner\u00e0 il proseguo del rilancio della nostra azione, necessaria in questa fase di decadimento del Paese&#8221;. <strong>Lo ha dichiarato l&#8217;esponente della direzione nazionale del PD, Mauro Buschini.<\/strong><\/p>\n<h2>Una sfida da vincere<\/h2>\n<p class=\"m_251495767420469689MsoNormal_mailru_css_attribute_postfix\">&#8220;<strong>Ai fallimenti del governo<\/strong> nazionale &#8211; <strong>ha proseguito Buschini &#8211;<\/strong> rispondiamo con una nuova identit\u00e0 per fornire risposte concrete ai bisogni delle persone. Una sfida che dobbiamo vincere per il nostro futuro e per quello dell&#8217;Italia&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-14923\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/costituente-idee.jpeg\" alt=\"costituente idee\" width=\"632\" height=\"421\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/costituente-idee.jpeg 1351w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/costituente-idee-300x200.jpeg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/costituente-idee-768x512.jpeg 768w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/costituente-idee-1024x682.jpeg 1024w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/costituente-idee-500x333.jpeg 500w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/costituente-idee-272x182.jpeg 272w\" sizes=\"auto, (max-width: 632px) 100vw, 632px\" \/><\/p>\n<h2><\/h2>\n<h2>L&#8217;obiettivo di Zingaretti<\/h2>\n<p>&#8220;La Costituente delle Idee &#8211; ha affermato il segretario nazionale del Pd &#8211; \u00e8 <strong>uno strumento per chiamare a raccolta una parte del Paese che vuole combattere<\/strong>. Dovr\u00e0 essere una sfida che giocheremo a livello nazionale, con grandi incontri e forum. Un\u2019occasione per tornare ad incontrare le persone\u201d.<\/p>\n<h3><strong>LE PROPOSTE PER LA COSTITUENTE DELLE IDEE<\/strong><\/h3>\n<p>Occore una \u201csvolta nel concetto stesso del diritto allo studio, che diventi diritto alla conoscenza\u201d, e \u201c<strong>10 miliardi in 3 anni come barriera per 100.000 nuovi assunti nel sistema pubblico<\/strong> o le prestazioni verranno meno\u201d.\u00a0 Ha fatto notare Nicola Zingaretti\u00a0 nel corso all\u2019assemblea nazionale del partito in vista della Costituente delle Idee. \u201cQuello che vogliamo \u00e8 anche un&#8217; Italia pi\u00f9 semplice per vivere e per produrre. Dobbiamo, quindi, riapre insieme la grande riforma federale e delle funzioni dei vari livelli dello Stato&#8221;.<\/p>\n<h2>Un piano di opere pubbliche<\/h2>\n<p>Il PD, inoltre,\u00a0 presenter\u00e0 la propria proposta di autonomia. &#8220;Un\u2019autonomia giusta. Dietro la parola autonomia-\u00a0 ha argomentato Zingaretti &#8211; si pu\u00f2 nascondere di tutto. Quello che occorre \u00e8\u00a0 un&#8217; iniziativa unitaria per migliorare l\u2019Italia non per distruggerla\u201d.\u00a0 E ancora un grande piano di opere pubbliche, \u201c200 miliardi fino al 2030\u00a0 &#8211; ha fatto notare &#8211; con il rilancio anche del partenariato pubblico privato: 170 miliardi sono gi\u00e0 programmati ma \u00e8 tutto fermo soprattutto per controversie politiche\u201d.<\/p>\n<h2>Pi\u00f9 attenzione alla sanit\u00e0<\/h2>\n<p>&#8220;Il Pd &#8211; ha concluso &#8211; guarda anche al ruolo di casse ed enti serve \u201c una stagione di project financing ad esempio rivolta all\u2019ammodernamento della nostra rete ospedaliera\u201d.\u00a0 E in autunno presenteremo anche una grande conferenza sulla forza del Made in italy, per ascoltare e costruire il grande sistema Italia per le imprese\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;La costituente delle idee lanciata dal segretario Nicola Zingaretti segna l&#8217;inizio di una nuova fase del nostro partito. L&#8217;apertura alle<\/p>\n","protected":false},"author":18,"featured_media":14924,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,28],"tags":[5345,330,1388,918,98,3716,562],"class_list":["post-14920","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-politica","tag-costituente-delle-idee","tag-governo","tag-mauro-buschini","tag-nicola-zingaretti","tag-pd","tag-presidente-consiglio-regionale","tag-regione-lazio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Buschini: s\u00ec alla costituente delle idee per proseguire l&#039;azione di rilancio del Pd - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Il presidente del consiglio regionale del Lazio sposa in pieno l&#039;idea lanciata dal segretario del Pd Nicola Zingaretti nel corso dell&#039;assemblea nazionale\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/15\/buschini-si-alla-costituente-delle-idee-per-proseguire-lazione-di-rilancio-del-pd\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Buschini: s\u00ec alla costituente delle idee per proseguire l&#039;azione di rilancio del Pd\" \/>\n<meta property=\"og:description\" content=\"Il presidente del consiglio regionale del Lazio sposa in pieno l&#039;idea lanciata dal segretario del Pd Nicola Zingaretti nel corso dell&#039;assemblea nazionale\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/15\/buschini-si-alla-costituente-delle-idee-per-proseguire-lazione-di-rilancio-del-pd\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-15T13:23:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-16T10:11:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/zingaretti-buschini.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"777\" \/>\n\t<meta property=\"og:image:height\" content=\"437\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/15\\\/buschini-si-alla-costituente-delle-idee-per-proseguire-lazione-di-rilancio-del-pd\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/15\\\/buschini-si-alla-costituente-delle-idee-per-proseguire-lazione-di-rilancio-del-pd\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Buschini: s\u00ec alla costituente delle idee per proseguire l&#8217;azione di rilancio del Pd\",\"datePublished\":\"2019-07-15T13:23:24+00:00\",\"dateModified\":\"2019-07-16T10:11:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/15\\\/buschini-si-alla-costituente-delle-idee-per-proseguire-lazione-di-rilancio-del-pd\\\/\"},\"wordCount\":384,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/15\\\/buschini-si-alla-costituente-delle-idee-per-proseguire-lazione-di-rilancio-del-pd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/zingaretti-buschini.jpg\",\"keywords\":[\"Costituente delle idee\",\"Governo\",\"mauro buschini\",\"nicola zingaretti\",\"Pd\",\"presidente consiglio regionale\",\"regione lazio\"],\"articleSection\":[\"*SLIDE*\",\"Evidenza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/15\\\/buschini-si-alla-costituente-delle-idee-per-proseguire-lazione-di-rilancio-del-pd\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/15\\\/buschini-si-alla-costituente-delle-idee-per-proseguire-lazione-di-rilancio-del-pd\\\/\",\"name\":\"Buschini: s\u00ec alla costituente delle idee per proseguire l'azione di rilancio del Pd - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/15\\\/buschini-si-alla-costituente-delle-idee-per-proseguire-lazione-di-rilancio-del-pd\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/15\\\/buschini-si-alla-costituente-delle-idee-per-proseguire-lazione-di-rilancio-del-pd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/zingaretti-buschini.jpg\",\"datePublished\":\"2019-07-15T13:23:24+00:00\",\"dateModified\":\"2019-07-16T10:11:21+00:00\",\"description\":\"Il presidente del consiglio regionale del Lazio sposa in pieno l'idea lanciata dal segretario del Pd Nicola Zingaretti nel corso dell'assemblea nazionale\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/15\\\/buschini-si-alla-costituente-delle-idee-per-proseguire-lazione-di-rilancio-del-pd\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/15\\\/buschini-si-alla-costituente-delle-idee-per-proseguire-lazione-di-rilancio-del-pd\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/15\\\/buschini-si-alla-costituente-delle-idee-per-proseguire-lazione-di-rilancio-del-pd\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/zingaretti-buschini.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/zingaretti-buschini.jpg\",\"width\":777,\"height\":437},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/15\\\/buschini-si-alla-costituente-delle-idee-per-proseguire-lazione-di-rilancio-del-pd\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Buschini: s\u00ec alla costituente delle idee per proseguire l&#8217;azione di rilancio del Pd\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/15\\\/buschini-si-alla-costituente-delle-idee-per-proseguire-lazione-di-rilancio-del-pd\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/15\\\/buschini-si-alla-costituente-delle-idee-per-proseguire-lazione-di-rilancio-del-pd\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/15\\\/buschini-si-alla-costituente-delle-idee-per-proseguire-lazione-di-rilancio-del-pd\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Buschini: s\u00ec alla costituente delle idee per proseguire l'azione di rilancio del Pd - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Il presidente del consiglio regionale del Lazio sposa in pieno l'idea lanciata dal segretario del Pd Nicola Zingaretti nel corso dell'assemblea nazionale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/15\/buschini-si-alla-costituente-delle-idee-per-proseguire-lazione-di-rilancio-del-pd\/","og_locale":"it_IT","og_type":"article","og_title":"Buschini: s\u00ec alla costituente delle idee per proseguire l'azione di rilancio del Pd","og_description":"Il presidente del consiglio regionale del Lazio sposa in pieno l'idea lanciata dal segretario del Pd Nicola Zingaretti nel corso dell'assemblea nazionale","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/15\/buschini-si-alla-costituente-delle-idee-per-proseguire-lazione-di-rilancio-del-pd\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-07-15T13:23:24+00:00","article_modified_time":"2019-07-16T10:11:21+00:00","og_image":[{"width":777,"height":437,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/zingaretti-buschini.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/15\/buschini-si-alla-costituente-delle-idee-per-proseguire-lazione-di-rilancio-del-pd\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/15\/buschini-si-alla-costituente-delle-idee-per-proseguire-lazione-di-rilancio-del-pd\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Buschini: s\u00ec alla costituente delle idee per proseguire l&#8217;azione di rilancio del Pd","datePublished":"2019-07-15T13:23:24+00:00","dateModified":"2019-07-16T10:11:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/15\/buschini-si-alla-costituente-delle-idee-per-proseguire-lazione-di-rilancio-del-pd\/"},"wordCount":384,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/15\/buschini-si-alla-costituente-delle-idee-per-proseguire-lazione-di-rilancio-del-pd\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/zingaretti-buschini.jpg","keywords":["Costituente delle idee","Governo","mauro buschini","nicola zingaretti","Pd","presidente consiglio regionale","regione lazio"],"articleSection":["*SLIDE*","Evidenza"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/15\/buschini-si-alla-costituente-delle-idee-per-proseguire-lazione-di-rilancio-del-pd\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/15\/buschini-si-alla-costituente-delle-idee-per-proseguire-lazione-di-rilancio-del-pd\/","name":"Buschini: s\u00ec alla costituente delle idee per proseguire l'azione di rilancio del Pd - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/15\/buschini-si-alla-costituente-delle-idee-per-proseguire-lazione-di-rilancio-del-pd\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/15\/buschini-si-alla-costituente-delle-idee-per-proseguire-lazione-di-rilancio-del-pd\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/zingaretti-buschini.jpg","datePublished":"2019-07-15T13:23:24+00:00","dateModified":"2019-07-16T10:11:21+00:00","description":"Il presidente del consiglio regionale del Lazio sposa in pieno l'idea lanciata dal segretario del Pd Nicola Zingaretti nel corso dell'assemblea nazionale","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/15\/buschini-si-alla-costituente-delle-idee-per-proseguire-lazione-di-rilancio-del-pd\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/15\/buschini-si-alla-costituente-delle-idee-per-proseguire-lazione-di-rilancio-del-pd\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/15\/buschini-si-alla-costituente-delle-idee-per-proseguire-lazione-di-rilancio-del-pd\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/zingaretti-buschini.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/zingaretti-buschini.jpg","width":777,"height":437},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/15\/buschini-si-alla-costituente-delle-idee-per-proseguire-lazione-di-rilancio-del-pd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Buschini: s\u00ec alla costituente delle idee per proseguire l&#8217;azione di rilancio del Pd"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/15\/buschini-si-alla-costituente-delle-idee-per-proseguire-lazione-di-rilancio-del-pd\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/15\/buschini-si-alla-costituente-delle-idee-per-proseguire-lazione-di-rilancio-del-pd\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/15\/buschini-si-alla-costituente-delle-idee-per-proseguire-lazione-di-rilancio-del-pd\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/14920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=14920"}],"version-history":[{"count":4,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/14920\/revisions"}],"predecessor-version":[{"id":14928,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/14920\/revisions\/14928"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/14924"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=14920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=14920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=14920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}