{"id":14622,"date":"2019-07-09T18:50:06","date_gmt":"2019-07-09T16:50:06","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=14622"},"modified":"2019-07-10T15:53:51","modified_gmt":"2019-07-10T13:53:51","slug":"frosinone-incendio-mecoris-dai-prelievi-delluniversita-assenza-di-diossina","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/09\/frosinone-incendio-mecoris-dai-prelievi-delluniversita-assenza-di-diossina\/","title":{"rendered":"Frosinone, incendio Mecoris: dai prelievi dell&#8217;Universit\u00e0 assenza di diossina"},"content":{"rendered":"<p>&#8220;<strong>I primi accertamenti e prelievi effettuati dall&#8217;universit\u00e0 di Tor Vergat<\/strong>a, in modo particolare dall&#8217;\u00e9quipe del professor Marco Sciarra, incaricato dal comune di Frosinone, hanno escluso la presenza di diossina rilevante nei terreni esterni all&#8217;azienda Mecoris, ove si era propagato l&#8217;incendio la scorsa settimana nella zona industriale&#8221;. <strong>Lo ha comunicato il sindaco di Frosinone, Nicola Ottaviani.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_9550\" aria-describedby=\"caption-attachment-9550\" style=\"width: 632px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9550\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/nicola-ottaviani-roma-e1554740208411.jpg\" alt=\"nicola ottaviani sindaco frosinone il corriere della provincia\" width=\"632\" height=\"403\" \/><figcaption id=\"caption-attachment-9550\" class=\"wp-caption-text\">Il sindaco di Frosinone Nicola Ottaviani<\/figcaption><\/figure>\n<h2><\/h2>\n<h2>L&#8217;intervento del sindaco<\/h2>\n<p>&#8220;I<strong> risultati saranno formalizzati nelle prossime ore<\/strong> ma, a seguito della consultazione con i medici e i tecnici che stanno supportando nell&#8217;attivit\u00e0 di controllo l&#8217;amministrazione comunale, \u00e8 possibile revocare il divieto di pascolo e di coltivazione sui fondi agricoli, che era stato adottato, in via precauzionale, sulle aree circostanti&#8221;.<\/p>\n<p>Si torna, quindi, alla normalit\u00e0, su tutta l&#8217;area che era stata coinvolta dalla presenza dei fumi, <strong>dopo l&#8217;incendio all&#8217;interno dello stabilimento Mecoris<\/strong>, che aveva costretto l&#8217;amministrazione comunale, in assenza di analisi specifiche, ad adottare una serie di provvedimenti, in via precauzionale, allo scopo di tutelare, nel modo pi\u00f9 opportuno, la salute pubblica e la pubblica incolumit\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;I primi accertamenti e prelievi effettuati dall&#8217;universit\u00e0 di Tor Vergata, in modo particolare dall&#8217;\u00e9quipe del professor Marco Sciarra, incaricato dal<\/p>\n","protected":false},"author":18,"featured_media":13628,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2],"tags":[5035,93,315,4918,639,5230],"class_list":["post-14622","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-cronaca","tag-diossina","tag-frosinone","tag-inquinamento","tag-mecorsi","tag-nicola-ottaviani","tag-universit"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Frosinone, incendio Mecoris: dai prelievi dell&#039;Universit\u00e0 assenza di diossina - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Si torna, quindi, alla normalit\u00e0, su tutta l&#039;area che era stata coinvolta dalla presenza dei fumi, dopo l&#039;incendio all&#039;interno dello stabilimento Mecoris\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/09\/frosinone-incendio-mecoris-dai-prelievi-delluniversita-assenza-di-diossina\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frosinone, incendio Mecoris: dai prelievi dell&#039;Universit\u00e0 assenza di diossina\" \/>\n<meta property=\"og:description\" content=\"Si torna, quindi, alla normalit\u00e0, su tutta l&#039;area che era stata coinvolta dalla presenza dei fumi, dopo l&#039;incendio all&#039;interno dello stabilimento Mecoris\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/09\/frosinone-incendio-mecoris-dai-prelievi-delluniversita-assenza-di-diossina\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-09T16:50:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-10T13:53:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/mecoris-incendio-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/09\\\/frosinone-incendio-mecoris-dai-prelievi-delluniversita-assenza-di-diossina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/09\\\/frosinone-incendio-mecoris-dai-prelievi-delluniversita-assenza-di-diossina\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Frosinone, incendio Mecoris: dai prelievi dell&#8217;Universit\u00e0 assenza di diossina\",\"datePublished\":\"2019-07-09T16:50:06+00:00\",\"dateModified\":\"2019-07-10T13:53:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/09\\\/frosinone-incendio-mecoris-dai-prelievi-delluniversita-assenza-di-diossina\\\/\"},\"wordCount\":197,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/09\\\/frosinone-incendio-mecoris-dai-prelievi-delluniversita-assenza-di-diossina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/mecoris-incendio-1.jpg\",\"keywords\":[\"diossina\",\"Frosinone\",\"inquinamento\",\"Mecorsi\",\"nicola ottaviani\",\"universit\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Cronaca\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/09\\\/frosinone-incendio-mecoris-dai-prelievi-delluniversita-assenza-di-diossina\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/09\\\/frosinone-incendio-mecoris-dai-prelievi-delluniversita-assenza-di-diossina\\\/\",\"name\":\"Frosinone, incendio Mecoris: dai prelievi dell'Universit\u00e0 assenza di diossina - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/09\\\/frosinone-incendio-mecoris-dai-prelievi-delluniversita-assenza-di-diossina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/09\\\/frosinone-incendio-mecoris-dai-prelievi-delluniversita-assenza-di-diossina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/mecoris-incendio-1.jpg\",\"datePublished\":\"2019-07-09T16:50:06+00:00\",\"dateModified\":\"2019-07-10T13:53:51+00:00\",\"description\":\"Si torna, quindi, alla normalit\u00e0, su tutta l'area che era stata coinvolta dalla presenza dei fumi, dopo l'incendio all'interno dello stabilimento Mecoris\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/09\\\/frosinone-incendio-mecoris-dai-prelievi-delluniversita-assenza-di-diossina\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/09\\\/frosinone-incendio-mecoris-dai-prelievi-delluniversita-assenza-di-diossina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/09\\\/frosinone-incendio-mecoris-dai-prelievi-delluniversita-assenza-di-diossina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/mecoris-incendio-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/mecoris-incendio-1.jpg\",\"width\":960,\"height\":720,\"caption\":\"mecoris-incendio-1 il corriere della provincia frosinone\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/09\\\/frosinone-incendio-mecoris-dai-prelievi-delluniversita-assenza-di-diossina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frosinone, incendio Mecoris: dai prelievi dell&#8217;Universit\u00e0 assenza di diossina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/09\\\/frosinone-incendio-mecoris-dai-prelievi-delluniversita-assenza-di-diossina\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/09\\\/frosinone-incendio-mecoris-dai-prelievi-delluniversita-assenza-di-diossina\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/09\\\/frosinone-incendio-mecoris-dai-prelievi-delluniversita-assenza-di-diossina\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Frosinone, incendio Mecoris: dai prelievi dell'Universit\u00e0 assenza di diossina - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Si torna, quindi, alla normalit\u00e0, su tutta l'area che era stata coinvolta dalla presenza dei fumi, dopo l'incendio all'interno dello stabilimento Mecoris","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/09\/frosinone-incendio-mecoris-dai-prelievi-delluniversita-assenza-di-diossina\/","og_locale":"it_IT","og_type":"article","og_title":"Frosinone, incendio Mecoris: dai prelievi dell'Universit\u00e0 assenza di diossina","og_description":"Si torna, quindi, alla normalit\u00e0, su tutta l'area che era stata coinvolta dalla presenza dei fumi, dopo l'incendio all'interno dello stabilimento Mecoris","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/09\/frosinone-incendio-mecoris-dai-prelievi-delluniversita-assenza-di-diossina\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-07-09T16:50:06+00:00","article_modified_time":"2019-07-10T13:53:51+00:00","og_image":[{"width":960,"height":720,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/mecoris-incendio-1.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/09\/frosinone-incendio-mecoris-dai-prelievi-delluniversita-assenza-di-diossina\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/09\/frosinone-incendio-mecoris-dai-prelievi-delluniversita-assenza-di-diossina\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Frosinone, incendio Mecoris: dai prelievi dell&#8217;Universit\u00e0 assenza di diossina","datePublished":"2019-07-09T16:50:06+00:00","dateModified":"2019-07-10T13:53:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/09\/frosinone-incendio-mecoris-dai-prelievi-delluniversita-assenza-di-diossina\/"},"wordCount":197,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/09\/frosinone-incendio-mecoris-dai-prelievi-delluniversita-assenza-di-diossina\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/mecoris-incendio-1.jpg","keywords":["diossina","Frosinone","inquinamento","Mecorsi","nicola ottaviani","universit"],"articleSection":["*PRIMO PIANO*","Cronaca"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/09\/frosinone-incendio-mecoris-dai-prelievi-delluniversita-assenza-di-diossina\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/09\/frosinone-incendio-mecoris-dai-prelievi-delluniversita-assenza-di-diossina\/","name":"Frosinone, incendio Mecoris: dai prelievi dell'Universit\u00e0 assenza di diossina - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/09\/frosinone-incendio-mecoris-dai-prelievi-delluniversita-assenza-di-diossina\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/09\/frosinone-incendio-mecoris-dai-prelievi-delluniversita-assenza-di-diossina\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/mecoris-incendio-1.jpg","datePublished":"2019-07-09T16:50:06+00:00","dateModified":"2019-07-10T13:53:51+00:00","description":"Si torna, quindi, alla normalit\u00e0, su tutta l'area che era stata coinvolta dalla presenza dei fumi, dopo l'incendio all'interno dello stabilimento Mecoris","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/09\/frosinone-incendio-mecoris-dai-prelievi-delluniversita-assenza-di-diossina\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/09\/frosinone-incendio-mecoris-dai-prelievi-delluniversita-assenza-di-diossina\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/09\/frosinone-incendio-mecoris-dai-prelievi-delluniversita-assenza-di-diossina\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/mecoris-incendio-1.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/mecoris-incendio-1.jpg","width":960,"height":720,"caption":"mecoris-incendio-1 il corriere della provincia frosinone"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/09\/frosinone-incendio-mecoris-dai-prelievi-delluniversita-assenza-di-diossina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Frosinone, incendio Mecoris: dai prelievi dell&#8217;Universit\u00e0 assenza di diossina"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/09\/frosinone-incendio-mecoris-dai-prelievi-delluniversita-assenza-di-diossina\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/09\/frosinone-incendio-mecoris-dai-prelievi-delluniversita-assenza-di-diossina\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/09\/frosinone-incendio-mecoris-dai-prelievi-delluniversita-assenza-di-diossina\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/14622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=14622"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/14622\/revisions"}],"predecessor-version":[{"id":14623,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/14622\/revisions\/14623"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/13628"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=14622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=14622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=14622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}