{"id":14505,"date":"2019-07-08T16:52:36","date_gmt":"2019-07-08T14:52:36","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=14505"},"modified":"2019-07-09T16:31:09","modified_gmt":"2019-07-09T14:31:09","slug":"rifiuti-da-roma-alfieri-convoca-la-direzione-provinciale-del-pd","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/08\/rifiuti-da-roma-alfieri-convoca-la-direzione-provinciale-del-pd\/","title":{"rendered":"Rifiuti da Roma, Alfieri convoca la direzione provinciale del Pd"},"content":{"rendered":"<p>&#8220;Domani per le ore 18 ho convocato una Direzione Provinciale straordinaria del PD per affrontare la discussione sull&#8217;emergenza rifiuti della Citt\u00e0 di Roma. Penso sia necessario che il Partito prenda una posizione chiara a tal riguardo con gli organismi dirigenti e assieme ai suoi amministratori&#8221;.<strong> \u00c8 quanto evidenzia Domenico Alfieri, segretario provinciale del partito.<\/strong><\/p>\n<h2>La presa di posizione<\/h2>\n<p>&#8220;L&#8217;arrivo dei rifiuti da Roma anche in provincia di Frosinone &#8211; aveva detto Alfieri gi\u00e0 nei giorni scorsi &#8211; sta sollevando continue proteste da parte di amministratori e cittadini, timorosi di diventare la \u2018discarica di Roma\u2019. Tra l&#8217;altro aveva messo il veto su un\u2019eventuale utilizzo della discarica di Colleferro, &#8220;affinch\u00e9\u00a0 non divenga la nuova pattumiera della Capitale. La Raggi stia attenta \u2013 aveva aggiunto \u2013. <strong>Siamo stanchi e anche arrabbiati<\/strong>. Sar\u00f2 al fianco del sindaco Sanna affinch\u00e9 la discarica di Colle Fagiolara non divenga la nuova pattumiera della Capitale e affinch\u00e9 gli impianti del nostro territorio non siano al suo servizio\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Domani per le ore 18 ho convocato una Direzione Provinciale straordinaria del PD per affrontare la discussione sull&#8217;emergenza rifiuti della<\/p>\n","protected":false},"author":18,"featured_media":10807,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,28,1],"tags":[1280,98,437,3825],"class_list":["post-14505","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-politica","category-news","tag-domenico-alfieri","tag-pd","tag-rifiuti","tag-virginia-raggi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Rifiuti da Roma, Alfieri convoca la direzione provinciale del Pd - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/08\/rifiuti-da-roma-alfieri-convoca-la-direzione-provinciale-del-pd\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rifiuti da Roma, Alfieri convoca la direzione provinciale del Pd\" \/>\n<meta property=\"og:description\" content=\"&#8220;Domani per le ore 18 ho convocato una Direzione Provinciale straordinaria del PD per affrontare la discussione sull&#8217;emergenza rifiuti della\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/08\/rifiuti-da-roma-alfieri-convoca-la-direzione-provinciale-del-pd\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-08T14:52:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-09T14:31:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/Alfieri-il-corriere-della-provincia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/08\\\/rifiuti-da-roma-alfieri-convoca-la-direzione-provinciale-del-pd\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/08\\\/rifiuti-da-roma-alfieri-convoca-la-direzione-provinciale-del-pd\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Rifiuti da Roma, Alfieri convoca la direzione provinciale del Pd\",\"datePublished\":\"2019-07-08T14:52:36+00:00\",\"dateModified\":\"2019-07-09T14:31:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/08\\\/rifiuti-da-roma-alfieri-convoca-la-direzione-provinciale-del-pd\\\/\"},\"wordCount\":169,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/08\\\/rifiuti-da-roma-alfieri-convoca-la-direzione-provinciale-del-pd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/05\\\/Alfieri-il-corriere-della-provincia.jpg\",\"keywords\":[\"domenico alfieri\",\"Pd\",\"rifiuti\",\"Virginia Raggi\"],\"articleSection\":[\"*SLIDE*\",\"Evidenza\",\"News\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/08\\\/rifiuti-da-roma-alfieri-convoca-la-direzione-provinciale-del-pd\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/08\\\/rifiuti-da-roma-alfieri-convoca-la-direzione-provinciale-del-pd\\\/\",\"name\":\"Rifiuti da Roma, Alfieri convoca la direzione provinciale del Pd - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/08\\\/rifiuti-da-roma-alfieri-convoca-la-direzione-provinciale-del-pd\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/08\\\/rifiuti-da-roma-alfieri-convoca-la-direzione-provinciale-del-pd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/05\\\/Alfieri-il-corriere-della-provincia.jpg\",\"datePublished\":\"2019-07-08T14:52:36+00:00\",\"dateModified\":\"2019-07-09T14:31:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/08\\\/rifiuti-da-roma-alfieri-convoca-la-direzione-provinciale-del-pd\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/08\\\/rifiuti-da-roma-alfieri-convoca-la-direzione-provinciale-del-pd\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/08\\\/rifiuti-da-roma-alfieri-convoca-la-direzione-provinciale-del-pd\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/05\\\/Alfieri-il-corriere-della-provincia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/05\\\/Alfieri-il-corriere-della-provincia.jpg\",\"width\":750,\"height\":500,\"caption\":\"Domenico Alfieri\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/08\\\/rifiuti-da-roma-alfieri-convoca-la-direzione-provinciale-del-pd\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rifiuti da Roma, Alfieri convoca la direzione provinciale del Pd\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/08\\\/rifiuti-da-roma-alfieri-convoca-la-direzione-provinciale-del-pd\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/08\\\/rifiuti-da-roma-alfieri-convoca-la-direzione-provinciale-del-pd\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/08\\\/rifiuti-da-roma-alfieri-convoca-la-direzione-provinciale-del-pd\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Rifiuti da Roma, Alfieri convoca la direzione provinciale del Pd - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/08\/rifiuti-da-roma-alfieri-convoca-la-direzione-provinciale-del-pd\/","og_locale":"it_IT","og_type":"article","og_title":"Rifiuti da Roma, Alfieri convoca la direzione provinciale del Pd","og_description":"&#8220;Domani per le ore 18 ho convocato una Direzione Provinciale straordinaria del PD per affrontare la discussione sull&#8217;emergenza rifiuti della","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/08\/rifiuti-da-roma-alfieri-convoca-la-direzione-provinciale-del-pd\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-07-08T14:52:36+00:00","article_modified_time":"2019-07-09T14:31:09+00:00","og_image":[{"width":750,"height":500,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/Alfieri-il-corriere-della-provincia.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/08\/rifiuti-da-roma-alfieri-convoca-la-direzione-provinciale-del-pd\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/08\/rifiuti-da-roma-alfieri-convoca-la-direzione-provinciale-del-pd\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Rifiuti da Roma, Alfieri convoca la direzione provinciale del Pd","datePublished":"2019-07-08T14:52:36+00:00","dateModified":"2019-07-09T14:31:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/08\/rifiuti-da-roma-alfieri-convoca-la-direzione-provinciale-del-pd\/"},"wordCount":169,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/08\/rifiuti-da-roma-alfieri-convoca-la-direzione-provinciale-del-pd\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/Alfieri-il-corriere-della-provincia.jpg","keywords":["domenico alfieri","Pd","rifiuti","Virginia Raggi"],"articleSection":["*SLIDE*","Evidenza","News"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/08\/rifiuti-da-roma-alfieri-convoca-la-direzione-provinciale-del-pd\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/08\/rifiuti-da-roma-alfieri-convoca-la-direzione-provinciale-del-pd\/","name":"Rifiuti da Roma, Alfieri convoca la direzione provinciale del Pd - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/08\/rifiuti-da-roma-alfieri-convoca-la-direzione-provinciale-del-pd\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/08\/rifiuti-da-roma-alfieri-convoca-la-direzione-provinciale-del-pd\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/Alfieri-il-corriere-della-provincia.jpg","datePublished":"2019-07-08T14:52:36+00:00","dateModified":"2019-07-09T14:31:09+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/08\/rifiuti-da-roma-alfieri-convoca-la-direzione-provinciale-del-pd\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/08\/rifiuti-da-roma-alfieri-convoca-la-direzione-provinciale-del-pd\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/08\/rifiuti-da-roma-alfieri-convoca-la-direzione-provinciale-del-pd\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/Alfieri-il-corriere-della-provincia.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/Alfieri-il-corriere-della-provincia.jpg","width":750,"height":500,"caption":"Domenico Alfieri"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/08\/rifiuti-da-roma-alfieri-convoca-la-direzione-provinciale-del-pd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Rifiuti da Roma, Alfieri convoca la direzione provinciale del Pd"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/08\/rifiuti-da-roma-alfieri-convoca-la-direzione-provinciale-del-pd\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/08\/rifiuti-da-roma-alfieri-convoca-la-direzione-provinciale-del-pd\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/08\/rifiuti-da-roma-alfieri-convoca-la-direzione-provinciale-del-pd\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/14505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=14505"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/14505\/revisions"}],"predecessor-version":[{"id":14506,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/14505\/revisions\/14506"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/10807"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=14505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=14505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=14505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}