{"id":14277,"date":"2019-07-04T08:26:59","date_gmt":"2019-07-04T06:26:59","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=14277"},"modified":"2019-07-04T19:14:38","modified_gmt":"2019-07-04T17:14:38","slug":"maxi-truffa-sulle-energie-rinnovabili-6-ordinanze-di-custodia-cautelare","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/04\/maxi-truffa-sulle-energie-rinnovabili-6-ordinanze-di-custodia-cautelare\/","title":{"rendered":"Maxi-truffa sulle energie rinnovabili: 6 misure cautelari"},"content":{"rendered":"<p>I <strong>finanzieri del Nucleo di Polizia Economico-Finanziaria di Frosinone<\/strong>, coordinati dai magistrati del Gruppo reati contro la Pubblica Amministrazione della Procura della Repubblica di Roma, stanno eseguendo, su tutto il territorio nazionale, un provvedimento emesso dal Gip di Roma.<\/p>\n<h2>Operazione &#8216;Bad Energy&#8217;<\/h2>\n<p>Lo stesso ha disposto<strong> 6 misure cautelari personali di interdizione dall\u2019attivit\u00e0 d\u2019impresa e il sequestro preventivo<\/strong>, per un <strong>valore complessivo di 47 milioni di euro<\/strong> nei confronti degli indagati e di <strong>3 societ\u00e0 operanti nel settore delle energie rinnovabili ed efficientamento energetico<\/strong>, con sede nel Lazio e nel Veneto.<\/p>\n<p>I militari della Guardia di Finanza, inoltre, <strong>stanno perquisendo le residenze degli indagati e le sedi delle aziende coinvolte<\/strong>.<\/p>\n<p>Sulla base delle risultanze investigative acquisite <strong>\u00e8 ipotizzato il reato di truffa per il conseguimento di erogazioni pubbliche<\/strong>, aggravata dalla rilevante entit\u00e0 patrimoniale ai danni del G.S.E (Gestore Servizi Energetici) Spa, societ\u00e0 interamente partecipata dal Ministero dell\u2019Economia e delle Finanze.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I finanzieri del Nucleo di Polizia Economico-Finanziaria di Frosinone, coordinati dai magistrati del Gruppo reati contro la Pubblica Amministrazione della<\/p>\n","protected":false},"author":18,"featured_media":3463,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[5110,93,5112,1380,102,462,4568,4938,5111,243,5113],"class_list":["post-14277","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronaca","tag-energie-rinnovabili","tag-frosinone","tag-gse","tag-guardia-di-finanza","tag-lazio","tag-operazione","tag-perquisizioni","tag-polizia-tributaria","tag-servizi-energetici","tag-truffa","tag-veneto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Maxi-truffa sulle energie rinnovabili: 6 misure cautelari - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Si chiama &#039;Bad Energy&#039; l&#039;operazione della Guardia di Finanza che ha portato a scoprire una tuffa da 47 milioni di euro nell&#039;ambito delle energie rinnovabili\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/04\/maxi-truffa-sulle-energie-rinnovabili-6-ordinanze-di-custodia-cautelare\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Maxi-truffa sulle energie rinnovabili: 6 misure cautelari\" \/>\n<meta property=\"og:description\" content=\"Si chiama &#039;Bad Energy&#039; l&#039;operazione della Guardia di Finanza che ha portato a scoprire una tuffa da 47 milioni di euro nell&#039;ambito delle energie rinnovabili\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/04\/maxi-truffa-sulle-energie-rinnovabili-6-ordinanze-di-custodia-cautelare\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-04T06:26:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-04T17:14:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/guardia-finanza.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"3125\" \/>\n\t<meta property=\"og:image:height\" content=\"1792\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/04\\\/maxi-truffa-sulle-energie-rinnovabili-6-ordinanze-di-custodia-cautelare\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/04\\\/maxi-truffa-sulle-energie-rinnovabili-6-ordinanze-di-custodia-cautelare\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Maxi-truffa sulle energie rinnovabili: 6 misure cautelari\",\"datePublished\":\"2019-07-04T06:26:59+00:00\",\"dateModified\":\"2019-07-04T17:14:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/04\\\/maxi-truffa-sulle-energie-rinnovabili-6-ordinanze-di-custodia-cautelare\\\/\"},\"wordCount\":157,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/04\\\/maxi-truffa-sulle-energie-rinnovabili-6-ordinanze-di-custodia-cautelare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/guardia-finanza.jpg\",\"keywords\":[\"energie rinnovabili\",\"Frosinone\",\"gse\",\"guardia di finanza\",\"Lazio\",\"operazione\",\"perquisizioni\",\"polizia tributaria\",\"servizi energetici\",\"truffa\",\"veneto\"],\"articleSection\":[\"Cronaca\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/04\\\/maxi-truffa-sulle-energie-rinnovabili-6-ordinanze-di-custodia-cautelare\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/04\\\/maxi-truffa-sulle-energie-rinnovabili-6-ordinanze-di-custodia-cautelare\\\/\",\"name\":\"Maxi-truffa sulle energie rinnovabili: 6 misure cautelari - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/04\\\/maxi-truffa-sulle-energie-rinnovabili-6-ordinanze-di-custodia-cautelare\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/04\\\/maxi-truffa-sulle-energie-rinnovabili-6-ordinanze-di-custodia-cautelare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/guardia-finanza.jpg\",\"datePublished\":\"2019-07-04T06:26:59+00:00\",\"dateModified\":\"2019-07-04T17:14:38+00:00\",\"description\":\"Si chiama 'Bad Energy' l'operazione della Guardia di Finanza che ha portato a scoprire una tuffa da 47 milioni di euro nell'ambito delle energie rinnovabili\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/04\\\/maxi-truffa-sulle-energie-rinnovabili-6-ordinanze-di-custodia-cautelare\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/04\\\/maxi-truffa-sulle-energie-rinnovabili-6-ordinanze-di-custodia-cautelare\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/04\\\/maxi-truffa-sulle-energie-rinnovabili-6-ordinanze-di-custodia-cautelare\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/guardia-finanza.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/guardia-finanza.jpg\",\"width\":3125,\"height\":1792,\"caption\":\"guardia di finanza autovelox veroli il corriere della provincia ciociaria frosinone\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/04\\\/maxi-truffa-sulle-energie-rinnovabili-6-ordinanze-di-custodia-cautelare\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Maxi-truffa sulle energie rinnovabili: 6 misure cautelari\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/04\\\/maxi-truffa-sulle-energie-rinnovabili-6-ordinanze-di-custodia-cautelare\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/04\\\/maxi-truffa-sulle-energie-rinnovabili-6-ordinanze-di-custodia-cautelare\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/04\\\/maxi-truffa-sulle-energie-rinnovabili-6-ordinanze-di-custodia-cautelare\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Maxi-truffa sulle energie rinnovabili: 6 misure cautelari - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Si chiama 'Bad Energy' l'operazione della Guardia di Finanza che ha portato a scoprire una tuffa da 47 milioni di euro nell'ambito delle energie rinnovabili","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/04\/maxi-truffa-sulle-energie-rinnovabili-6-ordinanze-di-custodia-cautelare\/","og_locale":"it_IT","og_type":"article","og_title":"Maxi-truffa sulle energie rinnovabili: 6 misure cautelari","og_description":"Si chiama 'Bad Energy' l'operazione della Guardia di Finanza che ha portato a scoprire una tuffa da 47 milioni di euro nell'ambito delle energie rinnovabili","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/04\/maxi-truffa-sulle-energie-rinnovabili-6-ordinanze-di-custodia-cautelare\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-07-04T06:26:59+00:00","article_modified_time":"2019-07-04T17:14:38+00:00","og_image":[{"width":3125,"height":1792,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/guardia-finanza.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/04\/maxi-truffa-sulle-energie-rinnovabili-6-ordinanze-di-custodia-cautelare\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/04\/maxi-truffa-sulle-energie-rinnovabili-6-ordinanze-di-custodia-cautelare\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Maxi-truffa sulle energie rinnovabili: 6 misure cautelari","datePublished":"2019-07-04T06:26:59+00:00","dateModified":"2019-07-04T17:14:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/04\/maxi-truffa-sulle-energie-rinnovabili-6-ordinanze-di-custodia-cautelare\/"},"wordCount":157,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/04\/maxi-truffa-sulle-energie-rinnovabili-6-ordinanze-di-custodia-cautelare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/guardia-finanza.jpg","keywords":["energie rinnovabili","Frosinone","gse","guardia di finanza","Lazio","operazione","perquisizioni","polizia tributaria","servizi energetici","truffa","veneto"],"articleSection":["Cronaca"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/04\/maxi-truffa-sulle-energie-rinnovabili-6-ordinanze-di-custodia-cautelare\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/04\/maxi-truffa-sulle-energie-rinnovabili-6-ordinanze-di-custodia-cautelare\/","name":"Maxi-truffa sulle energie rinnovabili: 6 misure cautelari - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/04\/maxi-truffa-sulle-energie-rinnovabili-6-ordinanze-di-custodia-cautelare\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/04\/maxi-truffa-sulle-energie-rinnovabili-6-ordinanze-di-custodia-cautelare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/guardia-finanza.jpg","datePublished":"2019-07-04T06:26:59+00:00","dateModified":"2019-07-04T17:14:38+00:00","description":"Si chiama 'Bad Energy' l'operazione della Guardia di Finanza che ha portato a scoprire una tuffa da 47 milioni di euro nell'ambito delle energie rinnovabili","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/04\/maxi-truffa-sulle-energie-rinnovabili-6-ordinanze-di-custodia-cautelare\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/04\/maxi-truffa-sulle-energie-rinnovabili-6-ordinanze-di-custodia-cautelare\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/04\/maxi-truffa-sulle-energie-rinnovabili-6-ordinanze-di-custodia-cautelare\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/guardia-finanza.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/guardia-finanza.jpg","width":3125,"height":1792,"caption":"guardia di finanza autovelox veroli il corriere della provincia ciociaria frosinone"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/04\/maxi-truffa-sulle-energie-rinnovabili-6-ordinanze-di-custodia-cautelare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Maxi-truffa sulle energie rinnovabili: 6 misure cautelari"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/04\/maxi-truffa-sulle-energie-rinnovabili-6-ordinanze-di-custodia-cautelare\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/04\/maxi-truffa-sulle-energie-rinnovabili-6-ordinanze-di-custodia-cautelare\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/04\/maxi-truffa-sulle-energie-rinnovabili-6-ordinanze-di-custodia-cautelare\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/14277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=14277"}],"version-history":[{"count":4,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/14277\/revisions"}],"predecessor-version":[{"id":14282,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/14277\/revisions\/14282"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/3463"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=14277"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=14277"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=14277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}