{"id":14249,"date":"2019-07-03T17:21:27","date_gmt":"2019-07-03T15:21:27","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=14249"},"modified":"2019-07-03T17:21:27","modified_gmt":"2019-07-03T15:21:27","slug":"gianni-valente-nuovo-coordinatore-della-lega-di-cassino","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/03\/gianni-valente-nuovo-coordinatore-della-lega-di-cassino\/","title":{"rendered":"Gianni Valente nuovo coordinatore della Lega di Cassino"},"content":{"rendered":"<p>\u00c8 <strong>Gianni Valente<\/strong> il <strong>nuovo coordinatore comunale della Lega a Cassino<\/strong>. Lo hanno nominato ieri sera, <strong>nella sede del Carroccio a Pontecorvo<\/strong>, l\u2019onorevole Francesca Gerardi e il senatore Gianfranco Rufa rispettivamente coordinatrice e vice coordinatore provinciale del partito in provincia di Frosinone.<\/p>\n<h2>Le parole del neo coordinatore<\/h2>\n<p>&#8220;Ringrazio i vertici del partito \u2013 ha detto Valente &#8211; e in particolar modo l&#8217;onorevole Gerardi , il senatore Rufa , il coordinatore regionale Zicchieri e il sottosegretario Claudio Durigon per la fiducia accordatami nell&#8217;assegnarmi <strong>questo importante incarico che porter\u00f2 avanti nel pieno rispetto delle linee guida del partito<\/strong>, in stretta collaborazione con il coordinamento provinciale e regionale&#8221;.<\/p>\n<p>&#8220;Mi attiver\u00f2 da subito \u2013 sottolinea ancora Valente \u2013 incontrando i due consiglieri comunali eletti ma anche tutti i candidati della Lega dell&#8217;ultima tornata elettorale perch\u00e9 insieme<strong> dobbiamo organizzare e strutturare in modo moderno e funzionale il partito<\/strong>, costruire un progetto politico di centrodestra incentrato sulla Lega ed essere pronti ai prossimi appuntamenti elettorali&#8221;.<\/p>\n<h2>La Lega Cassino volta pagina<\/h2>\n<p>L\u2019incarico, fanno sapere i vertici della Lega, \u00e8 stato affidato ad un politico di comprovata esperienza che nelle ultime elezioni comunali ha fatto parte del gruppo che ha contribuito fortemente al raggiungimento dell&#8217;ottimo risultato della lista. <strong>Con la nomina del coordinatore cittadino, la Lega di Cassino vuole lasciarsi alle spalle tutte le polemiche degli ultimi mesi<\/strong> e scrivere una nuova pagina politica a beneficio della citt\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c8 Gianni Valente il nuovo coordinatore comunale della Lega a Cassino. Lo hanno nominato ieri sera, nella sede del Carroccio<\/p>\n","protected":false},"author":18,"featured_media":14250,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[216,522,5105,2232,5106,239,295,968,297,915],"class_list":["post-14249","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","tag-cassino","tag-coordinamento","tag-coordinatore-cittadino","tag-gerardi","tag-gianni-valente","tag-incarico","tag-lega","tag-nomina","tag-partito","tag-rufa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gianni Valente nuovo coordinatore della Lega di Cassino - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Il nuovo coordinatore cittadino della Lega di Cassino \u00e8 Gianni Valente. Lo hanno nominato ieri sera a Pontecorvo l&#039;onorevole Gerardi e il senatore Rufa\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/03\/gianni-valente-nuovo-coordinatore-della-lega-di-cassino\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gianni Valente nuovo coordinatore della Lega di Cassino\" \/>\n<meta property=\"og:description\" content=\"Il nuovo coordinatore cittadino della Lega di Cassino \u00e8 Gianni Valente. Lo hanno nominato ieri sera a Pontecorvo l&#039;onorevole Gerardi e il senatore Rufa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/03\/gianni-valente-nuovo-coordinatore-della-lega-di-cassino\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-03T15:21:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/Valente-Gerardi-Rufa-e1562167237368.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/03\\\/gianni-valente-nuovo-coordinatore-della-lega-di-cassino\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/03\\\/gianni-valente-nuovo-coordinatore-della-lega-di-cassino\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Gianni Valente nuovo coordinatore della Lega di Cassino\",\"datePublished\":\"2019-07-03T15:21:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/03\\\/gianni-valente-nuovo-coordinatore-della-lega-di-cassino\\\/\"},\"wordCount\":237,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/03\\\/gianni-valente-nuovo-coordinatore-della-lega-di-cassino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/Valente-Gerardi-Rufa-e1562167237368.jpg\",\"keywords\":[\"Cassino\",\"coordinamento\",\"coordinatore cittadino\",\"gerardi\",\"gianni valente\",\"incarico\",\"Lega\",\"nomina\",\"Partito\",\"Rufa\"],\"articleSection\":[\"*PRIMO PIANO*\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/03\\\/gianni-valente-nuovo-coordinatore-della-lega-di-cassino\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/03\\\/gianni-valente-nuovo-coordinatore-della-lega-di-cassino\\\/\",\"name\":\"Gianni Valente nuovo coordinatore della Lega di Cassino - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/03\\\/gianni-valente-nuovo-coordinatore-della-lega-di-cassino\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/03\\\/gianni-valente-nuovo-coordinatore-della-lega-di-cassino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/Valente-Gerardi-Rufa-e1562167237368.jpg\",\"datePublished\":\"2019-07-03T15:21:27+00:00\",\"description\":\"Il nuovo coordinatore cittadino della Lega di Cassino \u00e8 Gianni Valente. Lo hanno nominato ieri sera a Pontecorvo l'onorevole Gerardi e il senatore Rufa\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/03\\\/gianni-valente-nuovo-coordinatore-della-lega-di-cassino\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/03\\\/gianni-valente-nuovo-coordinatore-della-lega-di-cassino\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/03\\\/gianni-valente-nuovo-coordinatore-della-lega-di-cassino\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/Valente-Gerardi-Rufa-e1562167237368.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/Valente-Gerardi-Rufa-e1562167237368.jpg\",\"width\":632,\"height\":420,\"caption\":\"Da sinistra Gianni Valente, Francesca Gerardi e Gianfranco Rufa\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/03\\\/gianni-valente-nuovo-coordinatore-della-lega-di-cassino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gianni Valente nuovo coordinatore della Lega di Cassino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/03\\\/gianni-valente-nuovo-coordinatore-della-lega-di-cassino\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/03\\\/gianni-valente-nuovo-coordinatore-della-lega-di-cassino\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/03\\\/gianni-valente-nuovo-coordinatore-della-lega-di-cassino\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gianni Valente nuovo coordinatore della Lega di Cassino - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Il nuovo coordinatore cittadino della Lega di Cassino \u00e8 Gianni Valente. Lo hanno nominato ieri sera a Pontecorvo l'onorevole Gerardi e il senatore Rufa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/03\/gianni-valente-nuovo-coordinatore-della-lega-di-cassino\/","og_locale":"it_IT","og_type":"article","og_title":"Gianni Valente nuovo coordinatore della Lega di Cassino","og_description":"Il nuovo coordinatore cittadino della Lega di Cassino \u00e8 Gianni Valente. Lo hanno nominato ieri sera a Pontecorvo l'onorevole Gerardi e il senatore Rufa","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/03\/gianni-valente-nuovo-coordinatore-della-lega-di-cassino\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-07-03T15:21:27+00:00","og_image":[{"width":632,"height":420,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/Valente-Gerardi-Rufa-e1562167237368.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/03\/gianni-valente-nuovo-coordinatore-della-lega-di-cassino\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/03\/gianni-valente-nuovo-coordinatore-della-lega-di-cassino\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Gianni Valente nuovo coordinatore della Lega di Cassino","datePublished":"2019-07-03T15:21:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/03\/gianni-valente-nuovo-coordinatore-della-lega-di-cassino\/"},"wordCount":237,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/03\/gianni-valente-nuovo-coordinatore-della-lega-di-cassino\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/Valente-Gerardi-Rufa-e1562167237368.jpg","keywords":["Cassino","coordinamento","coordinatore cittadino","gerardi","gianni valente","incarico","Lega","nomina","Partito","Rufa"],"articleSection":["*PRIMO PIANO*"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/03\/gianni-valente-nuovo-coordinatore-della-lega-di-cassino\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/03\/gianni-valente-nuovo-coordinatore-della-lega-di-cassino\/","name":"Gianni Valente nuovo coordinatore della Lega di Cassino - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/03\/gianni-valente-nuovo-coordinatore-della-lega-di-cassino\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/03\/gianni-valente-nuovo-coordinatore-della-lega-di-cassino\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/Valente-Gerardi-Rufa-e1562167237368.jpg","datePublished":"2019-07-03T15:21:27+00:00","description":"Il nuovo coordinatore cittadino della Lega di Cassino \u00e8 Gianni Valente. Lo hanno nominato ieri sera a Pontecorvo l'onorevole Gerardi e il senatore Rufa","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/03\/gianni-valente-nuovo-coordinatore-della-lega-di-cassino\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/03\/gianni-valente-nuovo-coordinatore-della-lega-di-cassino\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/03\/gianni-valente-nuovo-coordinatore-della-lega-di-cassino\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/Valente-Gerardi-Rufa-e1562167237368.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/Valente-Gerardi-Rufa-e1562167237368.jpg","width":632,"height":420,"caption":"Da sinistra Gianni Valente, Francesca Gerardi e Gianfranco Rufa"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/03\/gianni-valente-nuovo-coordinatore-della-lega-di-cassino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Gianni Valente nuovo coordinatore della Lega di Cassino"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/03\/gianni-valente-nuovo-coordinatore-della-lega-di-cassino\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/03\/gianni-valente-nuovo-coordinatore-della-lega-di-cassino\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/03\/gianni-valente-nuovo-coordinatore-della-lega-di-cassino\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/14249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=14249"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/14249\/revisions"}],"predecessor-version":[{"id":14251,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/14249\/revisions\/14251"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/14250"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=14249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=14249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=14249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}