{"id":14211,"date":"2019-07-03T15:14:12","date_gmt":"2019-07-03T13:14:12","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=14211"},"modified":"2019-07-03T15:14:12","modified_gmt":"2019-07-03T13:14:12","slug":"premio-rocca-doro-tra-i-premiati-alberto-la-rocca","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/03\/premio-rocca-doro-tra-i-premiati-alberto-la-rocca\/","title":{"rendered":"Premio &#8216;Rocca D&#8217;Oro&#8217;: tra i premiati Alberto La Rocca"},"content":{"rendered":"<p>Nell&#8217;incantevole scenario di piazza Fulli a Serrone,<strong> Alberto La Rocca, <\/strong>fondatore della Delta Lavori Spa di Sora, \u00e8 stato premiato con il riconoscimento &#8216;Rocca d&#8217;Oro&#8217; anno 2019.<\/p>\n<p>Il premio Internazionale Professionalit\u00e0 Rocca d&#8217;Oro 2019 arrivato alla trentesima edizione, \u00e8 organizzato da Giancarlo Flavi, giornalista, impegnato da una molti anni a valorizzare il suo paese natale.<\/p>\n<h2>Madrina e giuria<\/h2>\n<div><strong>Madrina d\u2019eccezione e presentatrice dell\u2019evento \u00e8 stata Claudia Andreatti<\/strong>, ex miss Italia e presentatrice di RAI 2 Mezzogiorno in famiglia, la serata \u00e8 stata allietata dalla Banda Musicale Associazione Nazionale Carabinieri con brani operistici interpretati da tre cantanti d\u2019eccezione: Eva Avola, soprano, Lavinia Bacu, soprano, Dino Valle, baritono del Bellini Theatre Opera di Detroit.<\/div>\n<p>Quest&#8217;anno il presidente della giuria \u00e8 stato il Generale\u00a0<strong>Carlo Felice Corsetti,<\/strong>\u00a0istituito nel 1989 dalla libera Associazione culturale &#8216;Rocca d\u2019Oro&#8217; e dal Comune di Serrone il premio porta alla ribalta eminenti personaggi del mondo della cultura, della politica, dell\u2019arte, dello spettacolo, dello sport, che si sono particolarmente distinti per professionalit\u00e0 nei loro ambiti lavorativi in Italia e nel mondo.<\/p>\n<p>Molti sono stati i personaggi premiati nelle passate edizioni:\u00a0<strong>Nino Manfredi<\/strong>,\u00a0<strong>Franca Valeri,<\/strong>\u00a0la figlia di\u00a0<strong>Tot\u00f2, Maria Teresa Ruta<\/strong>,\u00a0\u00a0Premi Nobel, alti dirigenti dello Stato civili e militari, cardinali.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-14213\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/rocca-doro.jpg\" alt=\"\" width=\"632\" height=\"421\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/rocca-doro.jpg 1280w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/rocca-doro-300x200.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/rocca-doro-768x512.jpg 768w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/rocca-doro-1024x682.jpg 1024w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/rocca-doro-500x333.jpg 500w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/rocca-doro-272x182.jpg 272w\" sizes=\"auto, (max-width: 632px) 100vw, 632px\" \/><\/p>\n<h2><\/h2>\n<h2>Gli altri premiati<\/h2>\n<div>Insieme al fondatore della Delta Lavori SPA sono stati premiati tra gli altri: il prefetto di Frosinone, <strong>Ignazio Portelli<\/strong>; il comandante dei Ros, <strong>Pasquale Angelosanto<\/strong>; il comandante della Regione Carabinieri Forestali Lazio; il rettore dell&#8217;Universit\u00e0 di Cassino e del Lazio Meridionale, <strong>Giovanni Betta<\/strong> e i giornalisti <strong>Filippo Anastasi<\/strong> e <strong>Isabella Di Chio<\/strong>.<\/div>\n<div><\/div>\n<h2>La soddisfazione<\/h2>\n<p>Grande soddisfazione per Alberto La Rocca che, nei saluti di ringraziamento, <strong>ha voluto dedicare il premio ai suoi circa 150 lavoratori<\/strong>: operai, impiegati e collaboratori. Inoltre ha voluto raccontare due degli ultimi successi della Delta Lavori Spa: il &#8216;Lotto 10&#8217;, cio\u00e8 la rampa di accesso dell\u2019A10 a Genova, citt\u00e0 tagliata in due dal crollo del Ponte Morandi &#8211; un\u2019opera diventata essenziale per la circolazione dei mezzi a motore &#8211; e il &#8216;Terminal Intermodale di Matera&#8217; presso il deposito Ferrovie Appulo Lucane,\u00a0\u00a0inserito nelle opere pubbliche realizzate per la capitale europea della Cultura.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nell&#8217;incantevole scenario di piazza Fulli a Serrone, Alberto La Rocca, fondatore della Delta Lavori Spa di Sora, \u00e8 stato premiato<\/p>\n","protected":false},"author":18,"featured_media":14212,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,5],"tags":[2602,3352,5095,425,5094,2402,161],"class_list":["post-14211","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-economia","tag-alberto-la-rocca","tag-delta-lavori","tag-giancarlo-flavi","tag-premio","tag-rocca-doro","tag-serrone","tag-sora"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Premio &#039;Rocca D&#039;Oro&#039;: tra i premiati Alberto La Rocca - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Il premio Internazionale Professionalit\u00e0 Rocca d&#039;Oro 2019 arrivato alla trentesima edizione, \u00e8 organizzato da Giancarlo Flavi\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/03\/premio-rocca-doro-tra-i-premiati-alberto-la-rocca\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Premio &#039;Rocca D&#039;Oro&#039;: tra i premiati Alberto La Rocca\" \/>\n<meta property=\"og:description\" content=\"Il premio Internazionale Professionalit\u00e0 Rocca d&#039;Oro 2019 arrivato alla trentesima edizione, \u00e8 organizzato da Giancarlo Flavi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/03\/premio-rocca-doro-tra-i-premiati-alberto-la-rocca\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-03T13:14:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/Alberto-La-Rocca-premio-rocca-doro.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/03\\\/premio-rocca-doro-tra-i-premiati-alberto-la-rocca\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/03\\\/premio-rocca-doro-tra-i-premiati-alberto-la-rocca\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Premio &#8216;Rocca D&#8217;Oro&#8217;: tra i premiati Alberto La Rocca\",\"datePublished\":\"2019-07-03T13:14:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/03\\\/premio-rocca-doro-tra-i-premiati-alberto-la-rocca\\\/\"},\"wordCount\":363,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/03\\\/premio-rocca-doro-tra-i-premiati-alberto-la-rocca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/Alberto-La-Rocca-premio-rocca-doro.jpg\",\"keywords\":[\"alberto la rocca\",\"delta Lavori\",\"Giancarlo Flavi\",\"premio\",\"Rocca d'oro\",\"serrone\",\"sora\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Economia e Finanza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/03\\\/premio-rocca-doro-tra-i-premiati-alberto-la-rocca\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/03\\\/premio-rocca-doro-tra-i-premiati-alberto-la-rocca\\\/\",\"name\":\"Premio 'Rocca D'Oro': tra i premiati Alberto La Rocca - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/03\\\/premio-rocca-doro-tra-i-premiati-alberto-la-rocca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/03\\\/premio-rocca-doro-tra-i-premiati-alberto-la-rocca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/Alberto-La-Rocca-premio-rocca-doro.jpg\",\"datePublished\":\"2019-07-03T13:14:12+00:00\",\"description\":\"Il premio Internazionale Professionalit\u00e0 Rocca d'Oro 2019 arrivato alla trentesima edizione, \u00e8 organizzato da Giancarlo Flavi\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/03\\\/premio-rocca-doro-tra-i-premiati-alberto-la-rocca\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/03\\\/premio-rocca-doro-tra-i-premiati-alberto-la-rocca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/03\\\/premio-rocca-doro-tra-i-premiati-alberto-la-rocca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/Alberto-La-Rocca-premio-rocca-doro.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/Alberto-La-Rocca-premio-rocca-doro.jpg\",\"width\":1280,\"height\":853,\"caption\":\"Alberto La Rocca premio rocca d'oro il corriere della provincia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/03\\\/premio-rocca-doro-tra-i-premiati-alberto-la-rocca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Premio &#8216;Rocca D&#8217;Oro&#8217;: tra i premiati Alberto La Rocca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/03\\\/premio-rocca-doro-tra-i-premiati-alberto-la-rocca\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/03\\\/premio-rocca-doro-tra-i-premiati-alberto-la-rocca\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/03\\\/premio-rocca-doro-tra-i-premiati-alberto-la-rocca\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Premio 'Rocca D'Oro': tra i premiati Alberto La Rocca - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Il premio Internazionale Professionalit\u00e0 Rocca d'Oro 2019 arrivato alla trentesima edizione, \u00e8 organizzato da Giancarlo Flavi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/03\/premio-rocca-doro-tra-i-premiati-alberto-la-rocca\/","og_locale":"it_IT","og_type":"article","og_title":"Premio 'Rocca D'Oro': tra i premiati Alberto La Rocca","og_description":"Il premio Internazionale Professionalit\u00e0 Rocca d'Oro 2019 arrivato alla trentesima edizione, \u00e8 organizzato da Giancarlo Flavi","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/03\/premio-rocca-doro-tra-i-premiati-alberto-la-rocca\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-07-03T13:14:12+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/Alberto-La-Rocca-premio-rocca-doro.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/03\/premio-rocca-doro-tra-i-premiati-alberto-la-rocca\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/03\/premio-rocca-doro-tra-i-premiati-alberto-la-rocca\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Premio &#8216;Rocca D&#8217;Oro&#8217;: tra i premiati Alberto La Rocca","datePublished":"2019-07-03T13:14:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/03\/premio-rocca-doro-tra-i-premiati-alberto-la-rocca\/"},"wordCount":363,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/03\/premio-rocca-doro-tra-i-premiati-alberto-la-rocca\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/Alberto-La-Rocca-premio-rocca-doro.jpg","keywords":["alberto la rocca","delta Lavori","Giancarlo Flavi","premio","Rocca d'oro","serrone","sora"],"articleSection":["*PRIMO PIANO*","Economia e Finanza"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/03\/premio-rocca-doro-tra-i-premiati-alberto-la-rocca\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/03\/premio-rocca-doro-tra-i-premiati-alberto-la-rocca\/","name":"Premio 'Rocca D'Oro': tra i premiati Alberto La Rocca - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/03\/premio-rocca-doro-tra-i-premiati-alberto-la-rocca\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/03\/premio-rocca-doro-tra-i-premiati-alberto-la-rocca\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/Alberto-La-Rocca-premio-rocca-doro.jpg","datePublished":"2019-07-03T13:14:12+00:00","description":"Il premio Internazionale Professionalit\u00e0 Rocca d'Oro 2019 arrivato alla trentesima edizione, \u00e8 organizzato da Giancarlo Flavi","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/03\/premio-rocca-doro-tra-i-premiati-alberto-la-rocca\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/03\/premio-rocca-doro-tra-i-premiati-alberto-la-rocca\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/03\/premio-rocca-doro-tra-i-premiati-alberto-la-rocca\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/Alberto-La-Rocca-premio-rocca-doro.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/Alberto-La-Rocca-premio-rocca-doro.jpg","width":1280,"height":853,"caption":"Alberto La Rocca premio rocca d'oro il corriere della provincia"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/03\/premio-rocca-doro-tra-i-premiati-alberto-la-rocca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Premio &#8216;Rocca D&#8217;Oro&#8217;: tra i premiati Alberto La Rocca"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/03\/premio-rocca-doro-tra-i-premiati-alberto-la-rocca\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/03\/premio-rocca-doro-tra-i-premiati-alberto-la-rocca\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/03\/premio-rocca-doro-tra-i-premiati-alberto-la-rocca\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/14211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=14211"}],"version-history":[{"count":4,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/14211\/revisions"}],"predecessor-version":[{"id":14233,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/14211\/revisions\/14233"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/14212"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=14211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=14211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=14211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}