{"id":14121,"date":"2019-07-01T19:21:23","date_gmt":"2019-07-01T17:21:23","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=14121"},"modified":"2019-07-02T13:59:06","modified_gmt":"2019-07-02T11:59:06","slug":"chiede-al-padre-di-prestargli-lauto-gli-ruba-soldi-e-risparmi","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/01\/chiede-al-padre-di-prestargli-lauto-gli-ruba-soldi-e-risparmi\/","title":{"rendered":"Chiede al padre di prestargli l\u2019auto: gli ruba soldi e risparmi"},"content":{"rendered":"<p><strong>Ha chiesto al padre di avere in prestito l\u2019auto per andare a fare la spesa<\/strong>. L\u2019uomo, un sessantaseienne di Veroli, preoccupato per non aver avuto pi\u00f9 indietro la macchina, ha sporto denuncia-querela, lo scorso mese di aprile.<\/p>\n<p>Ieri i carabinieri, a conclusione dell\u2019attivit\u00e0 info-investigativa, hanno <strong>denunciato a piede libero il figlio trentunenne<\/strong>.<\/p>\n<p><strong>Le accuse sono di furto e truffa<\/strong>. Il figlio della vittima, peraltro, \u00e8 gi\u00e0 censito per reati contro il patrimonio, la persona ed inerenti gli stupefacenti.<\/p>\n<h2>Cosa \u00e8 accaduto<\/h2>\n<p>Il 9 aprile scorso, il trentunenne aveva chiesto al padre di prestargli la macchina per andare a fare la spesa. Gli ha, per\u00f2, restituito l\u2019auto dopo quattro giorni, ridandogli anche il portafogli che il genitore aveva dimenticato nell\u2019abitacolo.<\/p>\n<p><strong>Il sessantaseienne, per\u00f2, aprendo il portafogli, si \u00e8 reso conto che mancavano 150 euro<\/strong>. Poi, controllando anche la sua Postepay, ha accertato che erano stati eseguiti alcuni movimenti fraudolenti. Le indagini hanno, poi, chiarito che a farli era stato proprio il figlio. E cos\u00ec lo hanno denunciato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ha chiesto al padre di avere in prestito l\u2019auto per andare a fare la spesa. L\u2019uomo, un sessantaseienne di Veroli,<\/p>\n","protected":false},"author":18,"featured_media":2554,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[1263,90,245,5066,932,1337,5067,1766,243,982],"class_list":["post-14121","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronaca","tag-auto","tag-carabinieri","tag-denuncia","tag-figlio","tag-furto","tag-portafogli","tag-postepay","tag-trentunenne","tag-truffa","tag-veroli"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Chiede al padre di prestargli l\u2019auto: gli ruba soldi e risparmi - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Ha chiesto al padre l&#039;auto per andare a fare la spesa: gliel&#039;ha restituita dopo 4 giorni dopo avergli rubato soldi dal portafogli e dalla Postepay\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/01\/chiede-al-padre-di-prestargli-lauto-gli-ruba-soldi-e-risparmi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chiede al padre di prestargli l\u2019auto: gli ruba soldi e risparmi\" \/>\n<meta property=\"og:description\" content=\"Ha chiesto al padre l&#039;auto per andare a fare la spesa: gliel&#039;ha restituita dopo 4 giorni dopo avergli rubato soldi dal portafogli e dalla Postepay\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/01\/chiede-al-padre-di-prestargli-lauto-gli-ruba-soldi-e-risparmi\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-01T17:21:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-02T11:59:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/carabinieri.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"544\" \/>\n\t<meta property=\"og:image:height\" content=\"333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/01\\\/chiede-al-padre-di-prestargli-lauto-gli-ruba-soldi-e-risparmi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/01\\\/chiede-al-padre-di-prestargli-lauto-gli-ruba-soldi-e-risparmi\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Chiede al padre di prestargli l\u2019auto: gli ruba soldi e risparmi\",\"datePublished\":\"2019-07-01T17:21:23+00:00\",\"dateModified\":\"2019-07-02T11:59:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/01\\\/chiede-al-padre-di-prestargli-lauto-gli-ruba-soldi-e-risparmi\\\/\"},\"wordCount\":178,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/01\\\/chiede-al-padre-di-prestargli-lauto-gli-ruba-soldi-e-risparmi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/carabinieri.jpg\",\"keywords\":[\"auto\",\"carabinieri\",\"denuncia\",\"figlio\",\"Furto\",\"portafogli\",\"postepay\",\"trentunenne\",\"truffa\",\"Veroli\"],\"articleSection\":[\"Cronaca\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/01\\\/chiede-al-padre-di-prestargli-lauto-gli-ruba-soldi-e-risparmi\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/01\\\/chiede-al-padre-di-prestargli-lauto-gli-ruba-soldi-e-risparmi\\\/\",\"name\":\"Chiede al padre di prestargli l\u2019auto: gli ruba soldi e risparmi - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/01\\\/chiede-al-padre-di-prestargli-lauto-gli-ruba-soldi-e-risparmi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/01\\\/chiede-al-padre-di-prestargli-lauto-gli-ruba-soldi-e-risparmi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/carabinieri.jpg\",\"datePublished\":\"2019-07-01T17:21:23+00:00\",\"dateModified\":\"2019-07-02T11:59:06+00:00\",\"description\":\"Ha chiesto al padre l'auto per andare a fare la spesa: gliel'ha restituita dopo 4 giorni dopo avergli rubato soldi dal portafogli e dalla Postepay\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/01\\\/chiede-al-padre-di-prestargli-lauto-gli-ruba-soldi-e-risparmi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/01\\\/chiede-al-padre-di-prestargli-lauto-gli-ruba-soldi-e-risparmi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/01\\\/chiede-al-padre-di-prestargli-lauto-gli-ruba-soldi-e-risparmi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/carabinieri.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/carabinieri.jpg\",\"width\":544,\"height\":333,\"caption\":\"carabinieri il corriere della provincia arresto\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/01\\\/chiede-al-padre-di-prestargli-lauto-gli-ruba-soldi-e-risparmi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chiede al padre di prestargli l\u2019auto: gli ruba soldi e risparmi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/01\\\/chiede-al-padre-di-prestargli-lauto-gli-ruba-soldi-e-risparmi\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/01\\\/chiede-al-padre-di-prestargli-lauto-gli-ruba-soldi-e-risparmi\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/01\\\/chiede-al-padre-di-prestargli-lauto-gli-ruba-soldi-e-risparmi\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Chiede al padre di prestargli l\u2019auto: gli ruba soldi e risparmi - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Ha chiesto al padre l'auto per andare a fare la spesa: gliel'ha restituita dopo 4 giorni dopo avergli rubato soldi dal portafogli e dalla Postepay","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/01\/chiede-al-padre-di-prestargli-lauto-gli-ruba-soldi-e-risparmi\/","og_locale":"it_IT","og_type":"article","og_title":"Chiede al padre di prestargli l\u2019auto: gli ruba soldi e risparmi","og_description":"Ha chiesto al padre l'auto per andare a fare la spesa: gliel'ha restituita dopo 4 giorni dopo avergli rubato soldi dal portafogli e dalla Postepay","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/01\/chiede-al-padre-di-prestargli-lauto-gli-ruba-soldi-e-risparmi\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-07-01T17:21:23+00:00","article_modified_time":"2019-07-02T11:59:06+00:00","og_image":[{"width":544,"height":333,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/carabinieri.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/01\/chiede-al-padre-di-prestargli-lauto-gli-ruba-soldi-e-risparmi\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/01\/chiede-al-padre-di-prestargli-lauto-gli-ruba-soldi-e-risparmi\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Chiede al padre di prestargli l\u2019auto: gli ruba soldi e risparmi","datePublished":"2019-07-01T17:21:23+00:00","dateModified":"2019-07-02T11:59:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/01\/chiede-al-padre-di-prestargli-lauto-gli-ruba-soldi-e-risparmi\/"},"wordCount":178,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/01\/chiede-al-padre-di-prestargli-lauto-gli-ruba-soldi-e-risparmi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/carabinieri.jpg","keywords":["auto","carabinieri","denuncia","figlio","Furto","portafogli","postepay","trentunenne","truffa","Veroli"],"articleSection":["Cronaca"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/01\/chiede-al-padre-di-prestargli-lauto-gli-ruba-soldi-e-risparmi\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/01\/chiede-al-padre-di-prestargli-lauto-gli-ruba-soldi-e-risparmi\/","name":"Chiede al padre di prestargli l\u2019auto: gli ruba soldi e risparmi - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/01\/chiede-al-padre-di-prestargli-lauto-gli-ruba-soldi-e-risparmi\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/01\/chiede-al-padre-di-prestargli-lauto-gli-ruba-soldi-e-risparmi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/carabinieri.jpg","datePublished":"2019-07-01T17:21:23+00:00","dateModified":"2019-07-02T11:59:06+00:00","description":"Ha chiesto al padre l'auto per andare a fare la spesa: gliel'ha restituita dopo 4 giorni dopo avergli rubato soldi dal portafogli e dalla Postepay","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/01\/chiede-al-padre-di-prestargli-lauto-gli-ruba-soldi-e-risparmi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/01\/chiede-al-padre-di-prestargli-lauto-gli-ruba-soldi-e-risparmi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/01\/chiede-al-padre-di-prestargli-lauto-gli-ruba-soldi-e-risparmi\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/carabinieri.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/carabinieri.jpg","width":544,"height":333,"caption":"carabinieri il corriere della provincia arresto"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/01\/chiede-al-padre-di-prestargli-lauto-gli-ruba-soldi-e-risparmi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Chiede al padre di prestargli l\u2019auto: gli ruba soldi e risparmi"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/01\/chiede-al-padre-di-prestargli-lauto-gli-ruba-soldi-e-risparmi\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/01\/chiede-al-padre-di-prestargli-lauto-gli-ruba-soldi-e-risparmi\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/01\/chiede-al-padre-di-prestargli-lauto-gli-ruba-soldi-e-risparmi\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/14121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=14121"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/14121\/revisions"}],"predecessor-version":[{"id":14122,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/14121\/revisions\/14122"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/2554"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=14121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=14121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=14121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}