{"id":14000,"date":"2019-06-29T09:00:47","date_gmt":"2019-06-29T07:00:47","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=14000"},"modified":"2019-06-30T10:20:29","modified_gmt":"2019-06-30T08:20:29","slug":"abbruzzese-consideriamo-il-progetto-per-un-palazzo-dello-sport","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/29\/abbruzzese-consideriamo-il-progetto-per-un-palazzo-dello-sport\/","title":{"rendered":"Abbruzzese: consideriamo il progetto per un palazzo dello sport"},"content":{"rendered":"<p>Un <strong>palazzetto dello sport<\/strong>, con una <strong>capienza di almeno 3.500 spettatori<\/strong>, che riunisca in una sorta di \u2018cittadella\u2019 la piscina comunale e campi attrezzati non soltanto fruibili per le diverse discipline sportive ma anche per eventi culturali e musicali.<\/p>\n<p>\u00c8 questa <strong>la proposta del consigliere comunale Mario Abbruzzese<\/strong> che, in una lettera indirizzata al sindaco Enzo Salera, sottolinea come la citt\u00e0 di Cassino abbia &#8220;la necessit\u00e0 immediata di vedere realizzato un vero palazzo dello sport. A tal fine esiste un&#8217;area a destinazione sportiva ideale per la realizzazione di una vera cittadella dello sport, nella quale \u00e8 ubicata una piscina comunale dove, come a lei ben noto, \u00e8 presente da diversi decenni un rudere in cemento armato, a tale scopo destinato&#8221;.<\/p>\n<h2>Il progetto<\/h2>\n<p>L&#8217;idea di Abbruzzese \u00e8 quella di inserire tutta l&#8217;area della ex piscina comunale in una procedura di manifestazione di interesse\u00a0 finalizzata alla realizzazione di un palazzo dello sport, con capienza di almeno 3500 spettatori, ovviamente su iniziativa privata, prevedendo la demolizione della struttura esistente e la riqualificazione dell&#8217;area stessa.<\/p>\n<p>&#8220;Considerando che attualmente la societ\u00e0 di basket della citt\u00e0 milita nel campionato di B2 e che ha affrontato il campionato di Serie A2 a Frosinone, proprio per la mancanza della struttura sportiva \u2013 conclude Abbruzzese &#8211; si chiede di far propria questa idea progettuale, per consentire in un prossimo e immediato futuro\u00a0 la realizzazione di questa struttura che consentirebbe di all&#8217;attuale societ\u00e0 di basket, Virtus Terra di San Benedetto Cassino, di potervi ospitare le\u00a0 eventuali, e ci auguriamo future partite di serie Nazionale, nella citt\u00e0 di Cassino&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un palazzetto dello sport, con una capienza di almeno 3.500 spettatori, che riunisca in una sorta di \u2018cittadella\u2019 la piscina<\/p>\n","protected":false},"author":18,"featured_media":12515,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,28],"tags":[216,5019,3273,5022,1226,5020,5021,1216,903],"class_list":["post-14000","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-politica","tag-cassino","tag-cittadella","tag-enzo-salera","tag-manifestazione-dinteresse","tag-mario-abbruzzese","tag-palazzetto","tag-piscina-comunale","tag-proposta","tag-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Abbruzzese: consideriamo il progetto per un palazzo dello sport - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Il consigliere comunale di Cassino Mario Abbruzzese propone al sindaco Salera di valutare la possibilit\u00e0 di realizzare una cittadella dello sport\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/29\/abbruzzese-consideriamo-il-progetto-per-un-palazzo-dello-sport\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abbruzzese: consideriamo il progetto per un palazzo dello sport\" \/>\n<meta property=\"og:description\" content=\"Il consigliere comunale di Cassino Mario Abbruzzese propone al sindaco Salera di valutare la possibilit\u00e0 di realizzare una cittadella dello sport\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/29\/abbruzzese-consideriamo-il-progetto-per-un-palazzo-dello-sport\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-29T07:00:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-30T08:20:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/mario-abbruzzese-il-corriere-della-provincia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"757\" \/>\n\t<meta property=\"og:image:height\" content=\"502\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/29\\\/abbruzzese-consideriamo-il-progetto-per-un-palazzo-dello-sport\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/29\\\/abbruzzese-consideriamo-il-progetto-per-un-palazzo-dello-sport\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Abbruzzese: consideriamo il progetto per un palazzo dello sport\",\"datePublished\":\"2019-06-29T07:00:47+00:00\",\"dateModified\":\"2019-06-30T08:20:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/29\\\/abbruzzese-consideriamo-il-progetto-per-un-palazzo-dello-sport\\\/\"},\"wordCount\":265,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/29\\\/abbruzzese-consideriamo-il-progetto-per-un-palazzo-dello-sport\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/mario-abbruzzese-il-corriere-della-provincia.jpg\",\"keywords\":[\"Cassino\",\"cittadella\",\"enzo salera\",\"manifestazione d'interesse\",\"mario abbruzzese\",\"palazzetto\",\"piscina comunale\",\"proposta\",\"sport\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Evidenza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/29\\\/abbruzzese-consideriamo-il-progetto-per-un-palazzo-dello-sport\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/29\\\/abbruzzese-consideriamo-il-progetto-per-un-palazzo-dello-sport\\\/\",\"name\":\"Abbruzzese: consideriamo il progetto per un palazzo dello sport - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/29\\\/abbruzzese-consideriamo-il-progetto-per-un-palazzo-dello-sport\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/29\\\/abbruzzese-consideriamo-il-progetto-per-un-palazzo-dello-sport\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/mario-abbruzzese-il-corriere-della-provincia.jpg\",\"datePublished\":\"2019-06-29T07:00:47+00:00\",\"dateModified\":\"2019-06-30T08:20:29+00:00\",\"description\":\"Il consigliere comunale di Cassino Mario Abbruzzese propone al sindaco Salera di valutare la possibilit\u00e0 di realizzare una cittadella dello sport\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/29\\\/abbruzzese-consideriamo-il-progetto-per-un-palazzo-dello-sport\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/29\\\/abbruzzese-consideriamo-il-progetto-per-un-palazzo-dello-sport\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/29\\\/abbruzzese-consideriamo-il-progetto-per-un-palazzo-dello-sport\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/mario-abbruzzese-il-corriere-della-provincia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/mario-abbruzzese-il-corriere-della-provincia.jpg\",\"width\":757,\"height\":502},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/29\\\/abbruzzese-consideriamo-il-progetto-per-un-palazzo-dello-sport\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abbruzzese: consideriamo il progetto per un palazzo dello sport\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/29\\\/abbruzzese-consideriamo-il-progetto-per-un-palazzo-dello-sport\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/29\\\/abbruzzese-consideriamo-il-progetto-per-un-palazzo-dello-sport\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/29\\\/abbruzzese-consideriamo-il-progetto-per-un-palazzo-dello-sport\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Abbruzzese: consideriamo il progetto per un palazzo dello sport - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Il consigliere comunale di Cassino Mario Abbruzzese propone al sindaco Salera di valutare la possibilit\u00e0 di realizzare una cittadella dello sport","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/29\/abbruzzese-consideriamo-il-progetto-per-un-palazzo-dello-sport\/","og_locale":"it_IT","og_type":"article","og_title":"Abbruzzese: consideriamo il progetto per un palazzo dello sport","og_description":"Il consigliere comunale di Cassino Mario Abbruzzese propone al sindaco Salera di valutare la possibilit\u00e0 di realizzare una cittadella dello sport","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/29\/abbruzzese-consideriamo-il-progetto-per-un-palazzo-dello-sport\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-06-29T07:00:47+00:00","article_modified_time":"2019-06-30T08:20:29+00:00","og_image":[{"width":757,"height":502,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/mario-abbruzzese-il-corriere-della-provincia.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/29\/abbruzzese-consideriamo-il-progetto-per-un-palazzo-dello-sport\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/29\/abbruzzese-consideriamo-il-progetto-per-un-palazzo-dello-sport\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Abbruzzese: consideriamo il progetto per un palazzo dello sport","datePublished":"2019-06-29T07:00:47+00:00","dateModified":"2019-06-30T08:20:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/29\/abbruzzese-consideriamo-il-progetto-per-un-palazzo-dello-sport\/"},"wordCount":265,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/29\/abbruzzese-consideriamo-il-progetto-per-un-palazzo-dello-sport\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/mario-abbruzzese-il-corriere-della-provincia.jpg","keywords":["Cassino","cittadella","enzo salera","manifestazione d'interesse","mario abbruzzese","palazzetto","piscina comunale","proposta","sport"],"articleSection":["*PRIMO PIANO*","Evidenza"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/29\/abbruzzese-consideriamo-il-progetto-per-un-palazzo-dello-sport\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/29\/abbruzzese-consideriamo-il-progetto-per-un-palazzo-dello-sport\/","name":"Abbruzzese: consideriamo il progetto per un palazzo dello sport - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/29\/abbruzzese-consideriamo-il-progetto-per-un-palazzo-dello-sport\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/29\/abbruzzese-consideriamo-il-progetto-per-un-palazzo-dello-sport\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/mario-abbruzzese-il-corriere-della-provincia.jpg","datePublished":"2019-06-29T07:00:47+00:00","dateModified":"2019-06-30T08:20:29+00:00","description":"Il consigliere comunale di Cassino Mario Abbruzzese propone al sindaco Salera di valutare la possibilit\u00e0 di realizzare una cittadella dello sport","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/29\/abbruzzese-consideriamo-il-progetto-per-un-palazzo-dello-sport\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/29\/abbruzzese-consideriamo-il-progetto-per-un-palazzo-dello-sport\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/29\/abbruzzese-consideriamo-il-progetto-per-un-palazzo-dello-sport\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/mario-abbruzzese-il-corriere-della-provincia.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/mario-abbruzzese-il-corriere-della-provincia.jpg","width":757,"height":502},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/29\/abbruzzese-consideriamo-il-progetto-per-un-palazzo-dello-sport\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Abbruzzese: consideriamo il progetto per un palazzo dello sport"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/29\/abbruzzese-consideriamo-il-progetto-per-un-palazzo-dello-sport\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/29\/abbruzzese-consideriamo-il-progetto-per-un-palazzo-dello-sport\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/29\/abbruzzese-consideriamo-il-progetto-per-un-palazzo-dello-sport\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/14000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=14000"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/14000\/revisions"}],"predecessor-version":[{"id":14001,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/14000\/revisions\/14001"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/12515"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=14000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=14000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=14000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}