{"id":13854,"date":"2019-06-27T13:50:13","date_gmt":"2019-06-27T11:50:13","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=13854"},"modified":"2019-06-28T14:26:11","modified_gmt":"2019-06-28T12:26:11","slug":"ferentino-cura-e-tutela-del-territorio-ordinanza-del-sindaco-nessuno-sconto-per-chi-non-rispetta-le-regole","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/27\/ferentino-cura-e-tutela-del-territorio-ordinanza-del-sindaco-nessuno-sconto-per-chi-non-rispetta-le-regole\/","title":{"rendered":"Ferentino &#8211; Cura del territorio, l&#8217;ordinanza: nessuno sconto per chi viola le regole"},"content":{"rendered":"<div>\n<p class=\"m_4170221564343218936gmail-m_6251041493066318774ydp635086d8MsoNormal\"><strong>La cura e la tutela del territorio<\/strong> passano attraverso la rigida applicazione di quelli che sono i provvedimenti previsti dalla legge. <strong>Il sindaco di Ferentino Antonio Pompeo<\/strong> ha firmato oggi l\u2019ordinanza con la quale vieta,<strong> fino al 30 settembre<\/strong>, l\u2019accensione dei fuochi per qualsivoglia finalit\u00e0, dalle stoppie alle immondizie, cos\u00ec da evitare possibili rischi di incendi sul territorio.<\/p>\n<h2>La decisione<\/h2>\n<p class=\"m_4170221564343218936gmail-m_6251041493066318774ydp635086d8MsoNormal\">Inoltre, ha ordinato, sempre nello stesso provvedimento, che nelle propriet\u00e0 private si provveda al taglio dei rami sporgenti dai terreni per garantire la <strong>piena sicurezza e la visibilit\u00e0 per automobilisti e pedoni;<\/strong> alla manutenzione e al rispristino dei fossi stradali di scolo; alla regimentazione delle acque piovane per evitare che tracimino sulle strade comunali e provinciali e alla rimozione di alberi che possano causare situazioni di pericolosit\u00e0.<\/p>\n<p class=\"m_4170221564343218936gmail-m_6251041493066318774ydp635086d8MsoNormal\">Infine, il sindaco Pompeo<strong> ha dato mandato alla polizia comunale<\/strong> per la verifica e il rispetto dell\u2019ordinanza attraverso appositi servizi anche in orari serali e con personale in borghese per controllare il fenomeno dell\u2019abbandono incontrollato nelle zona periferiche e nei siti dove tali fenomeni sono maggiormente riscontrabili.<\/p>\n<h2>L&#8217;intervento<\/h2>\n<p class=\"m_4170221564343218936gmail-m_6251041493066318774ydp635086d8MsoNormal\">&#8220;La nostra Citt\u00e0 si \u00e8 sempre contraddistinta per la collaborazione e l\u2019impegno da parte di tutti nella cura del territorio \u2013 ha spiegato il sindaco Antonio Pompeo \u2013 l\u2019educazione civica \u00e8 un valore sentito da tutti e per il quale tutti si impegnano. Purtroppo accadono anche episodi negativi che non siamo pi\u00f9 disposti a tollerare, anche per rispetto di coloro che le regole le applicano.\u00a0\u00a0Come ogni anno ho provveduto a firmare l\u2019ordinanza per il divieto di accensione dei fuochi e per il taglio delle siepi, dei rami e la pulizia dei fossi, affiancata da una puntuale azione di controllo del territorio e repressione, ove necessario&#8221;.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La cura e la tutela del territorio passano attraverso la rigida applicazione di quelli che sono i provvedimenti previsti dalla<\/p>\n","protected":false},"author":18,"featured_media":11881,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2236],"tags":[842,4734,4970,92,4969],"class_list":["post-13854","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-attualita","tag-antonio-pompeo","tag-cura-del-verde","tag-divieto-fuochi","tag-ferentino","tag-ordinasnza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ferentino - Cura del territorio, l&#039;ordinanza: nessuno sconto per chi viola le regole - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Il sindaco Pompeo ha dato mandato alla polizia comunale per la verifica e il rispetto dell\u2019ordinanza attraverso appositi servizi anche in orari serali\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/27\/ferentino-cura-e-tutela-del-territorio-ordinanza-del-sindaco-nessuno-sconto-per-chi-non-rispetta-le-regole\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ferentino - Cura del territorio, l&#039;ordinanza: nessuno sconto per chi viola le regole\" \/>\n<meta property=\"og:description\" content=\"Il sindaco Pompeo ha dato mandato alla polizia comunale per la verifica e il rispetto dell\u2019ordinanza attraverso appositi servizi anche in orari serali\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/27\/ferentino-cura-e-tutela-del-territorio-ordinanza-del-sindaco-nessuno-sconto-per-chi-non-rispetta-le-regole\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-27T11:50:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-28T12:26:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/antonio-pompeo-sindaco-ferentino-e1561993822743.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"484\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/27\\\/ferentino-cura-e-tutela-del-territorio-ordinanza-del-sindaco-nessuno-sconto-per-chi-non-rispetta-le-regole\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/27\\\/ferentino-cura-e-tutela-del-territorio-ordinanza-del-sindaco-nessuno-sconto-per-chi-non-rispetta-le-regole\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Ferentino &#8211; Cura del territorio, l&#8217;ordinanza: nessuno sconto per chi viola le regole\",\"datePublished\":\"2019-06-27T11:50:13+00:00\",\"dateModified\":\"2019-06-28T12:26:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/27\\\/ferentino-cura-e-tutela-del-territorio-ordinanza-del-sindaco-nessuno-sconto-per-chi-non-rispetta-le-regole\\\/\"},\"wordCount\":298,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/27\\\/ferentino-cura-e-tutela-del-territorio-ordinanza-del-sindaco-nessuno-sconto-per-chi-non-rispetta-le-regole\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/05\\\/antonio-pompeo-sindaco-ferentino-e1561993822743.jpg\",\"keywords\":[\"antonio pompeo\",\"cura del verde\",\"divieto fuochi\",\"ferentino\",\"ordinasnza\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/27\\\/ferentino-cura-e-tutela-del-territorio-ordinanza-del-sindaco-nessuno-sconto-per-chi-non-rispetta-le-regole\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/27\\\/ferentino-cura-e-tutela-del-territorio-ordinanza-del-sindaco-nessuno-sconto-per-chi-non-rispetta-le-regole\\\/\",\"name\":\"Ferentino - Cura del territorio, l'ordinanza: nessuno sconto per chi viola le regole - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/27\\\/ferentino-cura-e-tutela-del-territorio-ordinanza-del-sindaco-nessuno-sconto-per-chi-non-rispetta-le-regole\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/27\\\/ferentino-cura-e-tutela-del-territorio-ordinanza-del-sindaco-nessuno-sconto-per-chi-non-rispetta-le-regole\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/05\\\/antonio-pompeo-sindaco-ferentino-e1561993822743.jpg\",\"datePublished\":\"2019-06-27T11:50:13+00:00\",\"dateModified\":\"2019-06-28T12:26:11+00:00\",\"description\":\"Il sindaco Pompeo ha dato mandato alla polizia comunale per la verifica e il rispetto dell\u2019ordinanza attraverso appositi servizi anche in orari serali\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/27\\\/ferentino-cura-e-tutela-del-territorio-ordinanza-del-sindaco-nessuno-sconto-per-chi-non-rispetta-le-regole\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/27\\\/ferentino-cura-e-tutela-del-territorio-ordinanza-del-sindaco-nessuno-sconto-per-chi-non-rispetta-le-regole\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/27\\\/ferentino-cura-e-tutela-del-territorio-ordinanza-del-sindaco-nessuno-sconto-per-chi-non-rispetta-le-regole\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/05\\\/antonio-pompeo-sindaco-ferentino-e1561993822743.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/05\\\/antonio-pompeo-sindaco-ferentino-e1561993822743.jpg\",\"width\":632,\"height\":484,\"caption\":\"Il sindaco di Ferentino Antonio Pompeo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/27\\\/ferentino-cura-e-tutela-del-territorio-ordinanza-del-sindaco-nessuno-sconto-per-chi-non-rispetta-le-regole\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ferentino &#8211; Cura del territorio, l&#8217;ordinanza: nessuno sconto per chi viola le regole\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/27\\\/ferentino-cura-e-tutela-del-territorio-ordinanza-del-sindaco-nessuno-sconto-per-chi-non-rispetta-le-regole\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/27\\\/ferentino-cura-e-tutela-del-territorio-ordinanza-del-sindaco-nessuno-sconto-per-chi-non-rispetta-le-regole\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/27\\\/ferentino-cura-e-tutela-del-territorio-ordinanza-del-sindaco-nessuno-sconto-per-chi-non-rispetta-le-regole\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ferentino - Cura del territorio, l'ordinanza: nessuno sconto per chi viola le regole - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Il sindaco Pompeo ha dato mandato alla polizia comunale per la verifica e il rispetto dell\u2019ordinanza attraverso appositi servizi anche in orari serali","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/27\/ferentino-cura-e-tutela-del-territorio-ordinanza-del-sindaco-nessuno-sconto-per-chi-non-rispetta-le-regole\/","og_locale":"it_IT","og_type":"article","og_title":"Ferentino - Cura del territorio, l'ordinanza: nessuno sconto per chi viola le regole","og_description":"Il sindaco Pompeo ha dato mandato alla polizia comunale per la verifica e il rispetto dell\u2019ordinanza attraverso appositi servizi anche in orari serali","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/27\/ferentino-cura-e-tutela-del-territorio-ordinanza-del-sindaco-nessuno-sconto-per-chi-non-rispetta-le-regole\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-06-27T11:50:13+00:00","article_modified_time":"2019-06-28T12:26:11+00:00","og_image":[{"width":632,"height":484,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/antonio-pompeo-sindaco-ferentino-e1561993822743.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/27\/ferentino-cura-e-tutela-del-territorio-ordinanza-del-sindaco-nessuno-sconto-per-chi-non-rispetta-le-regole\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/27\/ferentino-cura-e-tutela-del-territorio-ordinanza-del-sindaco-nessuno-sconto-per-chi-non-rispetta-le-regole\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Ferentino &#8211; Cura del territorio, l&#8217;ordinanza: nessuno sconto per chi viola le regole","datePublished":"2019-06-27T11:50:13+00:00","dateModified":"2019-06-28T12:26:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/27\/ferentino-cura-e-tutela-del-territorio-ordinanza-del-sindaco-nessuno-sconto-per-chi-non-rispetta-le-regole\/"},"wordCount":298,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/27\/ferentino-cura-e-tutela-del-territorio-ordinanza-del-sindaco-nessuno-sconto-per-chi-non-rispetta-le-regole\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/antonio-pompeo-sindaco-ferentino-e1561993822743.jpg","keywords":["antonio pompeo","cura del verde","divieto fuochi","ferentino","ordinasnza"],"articleSection":["*PRIMO PIANO*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/27\/ferentino-cura-e-tutela-del-territorio-ordinanza-del-sindaco-nessuno-sconto-per-chi-non-rispetta-le-regole\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/27\/ferentino-cura-e-tutela-del-territorio-ordinanza-del-sindaco-nessuno-sconto-per-chi-non-rispetta-le-regole\/","name":"Ferentino - Cura del territorio, l'ordinanza: nessuno sconto per chi viola le regole - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/27\/ferentino-cura-e-tutela-del-territorio-ordinanza-del-sindaco-nessuno-sconto-per-chi-non-rispetta-le-regole\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/27\/ferentino-cura-e-tutela-del-territorio-ordinanza-del-sindaco-nessuno-sconto-per-chi-non-rispetta-le-regole\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/antonio-pompeo-sindaco-ferentino-e1561993822743.jpg","datePublished":"2019-06-27T11:50:13+00:00","dateModified":"2019-06-28T12:26:11+00:00","description":"Il sindaco Pompeo ha dato mandato alla polizia comunale per la verifica e il rispetto dell\u2019ordinanza attraverso appositi servizi anche in orari serali","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/27\/ferentino-cura-e-tutela-del-territorio-ordinanza-del-sindaco-nessuno-sconto-per-chi-non-rispetta-le-regole\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/27\/ferentino-cura-e-tutela-del-territorio-ordinanza-del-sindaco-nessuno-sconto-per-chi-non-rispetta-le-regole\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/27\/ferentino-cura-e-tutela-del-territorio-ordinanza-del-sindaco-nessuno-sconto-per-chi-non-rispetta-le-regole\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/antonio-pompeo-sindaco-ferentino-e1561993822743.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/antonio-pompeo-sindaco-ferentino-e1561993822743.jpg","width":632,"height":484,"caption":"Il sindaco di Ferentino Antonio Pompeo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/27\/ferentino-cura-e-tutela-del-territorio-ordinanza-del-sindaco-nessuno-sconto-per-chi-non-rispetta-le-regole\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Ferentino &#8211; Cura del territorio, l&#8217;ordinanza: nessuno sconto per chi viola le regole"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/27\/ferentino-cura-e-tutela-del-territorio-ordinanza-del-sindaco-nessuno-sconto-per-chi-non-rispetta-le-regole\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/27\/ferentino-cura-e-tutela-del-territorio-ordinanza-del-sindaco-nessuno-sconto-per-chi-non-rispetta-le-regole\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/27\/ferentino-cura-e-tutela-del-territorio-ordinanza-del-sindaco-nessuno-sconto-per-chi-non-rispetta-le-regole\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/13854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=13854"}],"version-history":[{"count":3,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/13854\/revisions"}],"predecessor-version":[{"id":13888,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/13854\/revisions\/13888"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/11881"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=13854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=13854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=13854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}