{"id":13397,"date":"2019-06-20T14:17:34","date_gmt":"2019-06-20T12:17:34","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=13397"},"modified":"2019-06-21T11:26:20","modified_gmt":"2019-06-21T09:26:20","slug":"imprese-a-cena-con-unindustria-incontro-tra-mondo-produttivo-istituzioni-e-universita","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/20\/imprese-a-cena-con-unindustria-incontro-tra-mondo-produttivo-istituzioni-e-universita\/","title":{"rendered":"Imprese a &#8220;Cena con Unindustria&#8221;, incontro tra aziende, istituzioni e universit\u00e0"},"content":{"rendered":"<p><strong>Saranno oltre 1000 gli ospiti<\/strong> che questa sera parteciperanno all\u2019appuntamento annuale della cena di Unindustria presso La Nuvola di Fuksas all\u2019Eur.<\/p>\n<p>Come da tradizione, anche la cena di quest\u2019anno vedr\u00e0 la partecipazione di un\u2019ampissima rappresentanza del gotha dell\u2019economia nazionale e regionale, molti top manager italiani ed esponenti della business community, insieme ad una ampia rappresentanza del mondo politico nazionale, regionale e comunale, sindacale ed accademico.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_13400\" aria-describedby=\"caption-attachment-13400\" style=\"width: 835px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13400 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/stirpe-e-tortoriello.jpg\" alt=\"Stirpe e Tortoriello\" width=\"835\" height=\"437\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/stirpe-e-tortoriello.jpg 835w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/stirpe-e-tortoriello-300x157.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/stirpe-e-tortoriello-768x402.jpg 768w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/stirpe-e-tortoriello-500x262.jpg 500w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/stirpe-e-tortoriello-390x205.jpg 390w\" sizes=\"auto, (max-width: 835px) 100vw, 835px\" \/><figcaption id=\"caption-attachment-13400\" class=\"wp-caption-text\">Filippo Tortoriello e Maurizio Stirpe<\/figcaption><\/figure>\n<h2><\/h2>\n<h2>I presenti<\/h2>\n<p>A fare gli onori di casa il Presidente di Unindustria <strong>Filippo Tortoriello<\/strong> affiancato da tutto il Consiglio di Presidenza dell\u2019Associazione che vedr\u00e0 anche la partecipazione dei Past President di Unindustria <strong>Luigi Abete<\/strong> e <strong>Maurizio Stirpe.<\/strong><\/p>\n<p>Il mondo imprenditoriale sar\u00e0 rappresentato dal Presidente di Confindustria <strong>Vincenzo Boccia<\/strong> e dai suoi Vice <strong>Stefan Pan<\/strong>, <strong>Giovanni Brugnoli <\/strong>e<strong> Alessio Rossi. <\/strong>Inoltre, saranno presenti tra gli altri anche il Presidente di Confindustria Lombardia<strong> Marco Bonometti<\/strong>, il Presidente di Confindustria Piemonte<strong> Fabio Ravanelli, <\/strong>il Presidente dell\u2019Unione degli Industriali della Provincia di Napoli <strong>Vito Grassi <\/strong>ed il Presidente di Farmindustria <strong>Massimo Scaccabarozzi<\/strong>. Sar\u00e0 presente anche <strong>Innocenzo Cipolletta<\/strong> Presidente di Assonime. Il Governo sar\u00e0 rappresentato dal Sottosegretario al Lavoro e alle Politiche Sociali <a href=\"http:\/\/www.governo.it\/governo\/conte-giuseppe\/sottosegretario\/claudio-durigon\"><strong>Claudio Durigon<\/strong><\/a>.<\/p>\n<p>Il Presidente della Regione Lazio<strong> Nicola Zingaretti<\/strong>, accompagnato dal suo Vice <strong>Daniele Leodori <\/strong>e da molti Assessori della sua Giunta parteciper\u00e0 alla cena. Roma Capitale sar\u00e0 rappresentata dal Vice Sindaco <strong>Luca Bergamo<\/strong> insieme a numerosi Assessori della Giunta di Virginia Raggi.<\/p>\n<p>Saranno inoltre presenti tutti i Segretari Generali dei Sindacati di Roma e del Lazio, rispettivamente, <strong>Michele Azzola<\/strong> (CGIL), <strong>Paolo Terrinoni<\/strong> (CISL), <strong>Alberto Civica<\/strong> (UIL) e <strong>Armando Valiani<\/strong> (UGL), insieme ai Presidenti di tutte le Associazioni imprenditoriali di Roma e del Lazio, al Presidente della Camera di Commercio di Roma <strong>Lorenzo Tagliavanti<\/strong>, al mondo universitario con i Rettori delle principali Universit\u00e0 pubbliche e private della Regione. La serata vedr\u00e0 anche un riconoscimento ad una prestigiosissima istituzione della nostra citt\u00e0, <strong>l\u2019Ospedale Pediatrico<\/strong> <strong>Bambino Ges\u00f9<\/strong>, eccellenza del nostro sistema sanitario apprezzata a livello mondiale con un intervento della sua Presidente <strong>Mariella Enoc<\/strong>.<\/p>\n<figure id=\"attachment_13461\" aria-describedby=\"caption-attachment-13461\" style=\"width: 632px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13461\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/stefano-dominella-guillermo-mariotto-edoardo-de-giorgio-890705.jpg\" alt=\"Stefano Dominella a Guillermo Mariotto il corriere della provincia\" width=\"632\" height=\"433\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/stefano-dominella-guillermo-mariotto-edoardo-de-giorgio-890705.jpg 545w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/stefano-dominella-guillermo-mariotto-edoardo-de-giorgio-890705-300x205.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/stefano-dominella-guillermo-mariotto-edoardo-de-giorgio-890705-500x342.jpg 500w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/stefano-dominella-guillermo-mariotto-edoardo-de-giorgio-890705-130x90.jpg 130w\" sizes=\"auto, (max-width: 632px) 100vw, 632px\" \/><figcaption id=\"caption-attachment-13461\" class=\"wp-caption-text\">Stefano Dominella a Guillermo Mariotto<\/figcaption><\/figure>\n<h2>Venti modelle indosseranno creazioni ispirate al Giappone<\/h2>\n<p>La cena dar\u00e0 inoltre uno spazio molto significativo al Club della Creativit\u00e0 di Unindustria, voluto fortemente dal Presidente Filippo Tortoriello e realizzato da <strong>Stefano Dominella<\/strong> Presidente della Sezione Moda e nato per affiancare e sostenere la crescita imprenditoriale dei tanti giovani designer dell\u2019Industria Creativa. Il Giappone sar\u00e0 protagonista della Cena attraverso una suggestiva sfilata che trasformer\u00e0 la Nuvola dell\u2019archistar Massimiliano Fuksas in un bosco di ciliegi in fiore attraverso le creazioni, ispirate al kimono, dei 10 giovani designer del Club della creativit\u00e0.<\/p>\n<p>Tutor d\u2019eccezione sar\u00e0 <strong>Guillermo Mariotto<\/strong> direttore creativo della couture di Gattinoni che presenter\u00e0 ad hoc due creazioni ispirate al Sol Levante. 20 modelle provenienti da ogni parte del mondo, indosseranno spettacolari creazioni sculture omaggio alla cultura nipponica. Anche l\u2019allestimento, con Ikebana su ogni tavolo ed il men\u00f9 della cena saranno caratterizzati da un perfetto connubio tra atmosfere giapponesi e tipicit\u00e0 dei prodotti regionali.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saranno oltre 1000 gli ospiti che questa sera parteciperanno all\u2019appuntamento annuale della cena di Unindustria presso La Nuvola di Fuksas<\/p>\n","protected":false},"author":18,"featured_media":13399,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[2200,1077,918,170,4833],"class_list":["post-13397","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","tag-filippo-tortoriello","tag-maurizio-stirpe","tag-nicola-zingaretti","tag-unindustria","tag-vincenzo-boccia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Imprese a &quot;Cena con Unindustria&quot;, incontro tra aziende, istituzioni e universit\u00e0 - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Oltre 1000 ospiti attesi alla Nuvola di Fuksas per la cena di Unindusria. 20 modelle indosseranno creazioni sculture ispirate al Giappone.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/20\/imprese-a-cena-con-unindustria-incontro-tra-mondo-produttivo-istituzioni-e-universita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Imprese a &quot;Cena con Unindustria&quot;, incontro tra aziende, istituzioni e universit\u00e0\" \/>\n<meta property=\"og:description\" content=\"Oltre 1000 ospiti attesi alla Nuvola di Fuksas per la cena di Unindusria. 20 modelle indosseranno creazioni sculture ispirate al Giappone.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/20\/imprese-a-cena-con-unindustria-incontro-tra-mondo-produttivo-istituzioni-e-universita\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-20T12:17:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-21T09:26:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/nuvola-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"990\" \/>\n\t<meta property=\"og:image:height\" content=\"556\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/20\\\/imprese-a-cena-con-unindustria-incontro-tra-mondo-produttivo-istituzioni-e-universita\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/20\\\/imprese-a-cena-con-unindustria-incontro-tra-mondo-produttivo-istituzioni-e-universita\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Imprese a &#8220;Cena con Unindustria&#8221;, incontro tra aziende, istituzioni e universit\u00e0\",\"datePublished\":\"2019-06-20T12:17:34+00:00\",\"dateModified\":\"2019-06-21T09:26:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/20\\\/imprese-a-cena-con-unindustria-incontro-tra-mondo-produttivo-istituzioni-e-universita\\\/\"},\"wordCount\":522,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/20\\\/imprese-a-cena-con-unindustria-incontro-tra-mondo-produttivo-istituzioni-e-universita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/nuvola-.jpg\",\"keywords\":[\"filippo tortoriello\",\"maurizio stirpe\",\"nicola zingaretti\",\"Unindustria\",\"Vincenzo Boccia\"],\"articleSection\":[\"Economia e Finanza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/20\\\/imprese-a-cena-con-unindustria-incontro-tra-mondo-produttivo-istituzioni-e-universita\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/20\\\/imprese-a-cena-con-unindustria-incontro-tra-mondo-produttivo-istituzioni-e-universita\\\/\",\"name\":\"Imprese a \\\"Cena con Unindustria\\\", incontro tra aziende, istituzioni e universit\u00e0 - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/20\\\/imprese-a-cena-con-unindustria-incontro-tra-mondo-produttivo-istituzioni-e-universita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/20\\\/imprese-a-cena-con-unindustria-incontro-tra-mondo-produttivo-istituzioni-e-universita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/nuvola-.jpg\",\"datePublished\":\"2019-06-20T12:17:34+00:00\",\"dateModified\":\"2019-06-21T09:26:20+00:00\",\"description\":\"Oltre 1000 ospiti attesi alla Nuvola di Fuksas per la cena di Unindusria. 20 modelle indosseranno creazioni sculture ispirate al Giappone.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/20\\\/imprese-a-cena-con-unindustria-incontro-tra-mondo-produttivo-istituzioni-e-universita\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/20\\\/imprese-a-cena-con-unindustria-incontro-tra-mondo-produttivo-istituzioni-e-universita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/20\\\/imprese-a-cena-con-unindustria-incontro-tra-mondo-produttivo-istituzioni-e-universita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/nuvola-.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/nuvola-.jpg\",\"width\":990,\"height\":556},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/20\\\/imprese-a-cena-con-unindustria-incontro-tra-mondo-produttivo-istituzioni-e-universita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Imprese a &#8220;Cena con Unindustria&#8221;, incontro tra aziende, istituzioni e universit\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/20\\\/imprese-a-cena-con-unindustria-incontro-tra-mondo-produttivo-istituzioni-e-universita\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/20\\\/imprese-a-cena-con-unindustria-incontro-tra-mondo-produttivo-istituzioni-e-universita\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/20\\\/imprese-a-cena-con-unindustria-incontro-tra-mondo-produttivo-istituzioni-e-universita\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Imprese a \"Cena con Unindustria\", incontro tra aziende, istituzioni e universit\u00e0 - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Oltre 1000 ospiti attesi alla Nuvola di Fuksas per la cena di Unindusria. 20 modelle indosseranno creazioni sculture ispirate al Giappone.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/20\/imprese-a-cena-con-unindustria-incontro-tra-mondo-produttivo-istituzioni-e-universita\/","og_locale":"it_IT","og_type":"article","og_title":"Imprese a \"Cena con Unindustria\", incontro tra aziende, istituzioni e universit\u00e0","og_description":"Oltre 1000 ospiti attesi alla Nuvola di Fuksas per la cena di Unindusria. 20 modelle indosseranno creazioni sculture ispirate al Giappone.","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/20\/imprese-a-cena-con-unindustria-incontro-tra-mondo-produttivo-istituzioni-e-universita\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-06-20T12:17:34+00:00","article_modified_time":"2019-06-21T09:26:20+00:00","og_image":[{"width":990,"height":556,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/nuvola-.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/20\/imprese-a-cena-con-unindustria-incontro-tra-mondo-produttivo-istituzioni-e-universita\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/20\/imprese-a-cena-con-unindustria-incontro-tra-mondo-produttivo-istituzioni-e-universita\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Imprese a &#8220;Cena con Unindustria&#8221;, incontro tra aziende, istituzioni e universit\u00e0","datePublished":"2019-06-20T12:17:34+00:00","dateModified":"2019-06-21T09:26:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/20\/imprese-a-cena-con-unindustria-incontro-tra-mondo-produttivo-istituzioni-e-universita\/"},"wordCount":522,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/20\/imprese-a-cena-con-unindustria-incontro-tra-mondo-produttivo-istituzioni-e-universita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/nuvola-.jpg","keywords":["filippo tortoriello","maurizio stirpe","nicola zingaretti","Unindustria","Vincenzo Boccia"],"articleSection":["Economia e Finanza"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/20\/imprese-a-cena-con-unindustria-incontro-tra-mondo-produttivo-istituzioni-e-universita\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/20\/imprese-a-cena-con-unindustria-incontro-tra-mondo-produttivo-istituzioni-e-universita\/","name":"Imprese a \"Cena con Unindustria\", incontro tra aziende, istituzioni e universit\u00e0 - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/20\/imprese-a-cena-con-unindustria-incontro-tra-mondo-produttivo-istituzioni-e-universita\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/20\/imprese-a-cena-con-unindustria-incontro-tra-mondo-produttivo-istituzioni-e-universita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/nuvola-.jpg","datePublished":"2019-06-20T12:17:34+00:00","dateModified":"2019-06-21T09:26:20+00:00","description":"Oltre 1000 ospiti attesi alla Nuvola di Fuksas per la cena di Unindusria. 20 modelle indosseranno creazioni sculture ispirate al Giappone.","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/20\/imprese-a-cena-con-unindustria-incontro-tra-mondo-produttivo-istituzioni-e-universita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/20\/imprese-a-cena-con-unindustria-incontro-tra-mondo-produttivo-istituzioni-e-universita\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/20\/imprese-a-cena-con-unindustria-incontro-tra-mondo-produttivo-istituzioni-e-universita\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/nuvola-.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/nuvola-.jpg","width":990,"height":556},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/20\/imprese-a-cena-con-unindustria-incontro-tra-mondo-produttivo-istituzioni-e-universita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Imprese a &#8220;Cena con Unindustria&#8221;, incontro tra aziende, istituzioni e universit\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/20\/imprese-a-cena-con-unindustria-incontro-tra-mondo-produttivo-istituzioni-e-universita\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/20\/imprese-a-cena-con-unindustria-incontro-tra-mondo-produttivo-istituzioni-e-universita\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/20\/imprese-a-cena-con-unindustria-incontro-tra-mondo-produttivo-istituzioni-e-universita\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/13397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=13397"}],"version-history":[{"count":4,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/13397\/revisions"}],"predecessor-version":[{"id":13462,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/13397\/revisions\/13462"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/13399"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=13397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=13397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=13397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}