{"id":1337,"date":"2018-11-09T15:32:20","date_gmt":"2018-11-09T14:32:20","guid":{"rendered":"http:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=1337"},"modified":"2018-11-12T17:41:56","modified_gmt":"2018-11-12T16:41:56","slug":"pompeo-occorre-potenziare-lofferta-di-servizi-sanitari-nel-nostro-territorio","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/09\/pompeo-occorre-potenziare-lofferta-di-servizi-sanitari-nel-nostro-territorio\/","title":{"rendered":"Pompeo: \u201cOccorre potenziare l&#8217;offerta di servizi sanitari nel nostro territorio&#8221;"},"content":{"rendered":"<div dir=\"ltr\">\n<p class=\"m_935529386238182751gmail-yiv1228599189msonormal\">\u201cLa Provincia di Frosinone \u00e8 un territorio composto da 91 comuni, molti dei quali montani, distanti dai centri principali. E\u2019 necessario, dunque, che <strong>l\u2019organizzazione dei servizi sanitari preveda la presenza di presidi che permettano a tutti i cittadini di avere le stesse possibilit\u00e0 di accesso alle cure<\/strong> cos\u00ec come accade nelle altre province\u201d.<\/p>\n<p class=\"m_935529386238182751gmail-yiv1228599189msonormal\">A dichiararlo \u00e8 il presidente dell&#8217;Amministrazione provinciale <strong>Antonio Pompeo<\/strong>, che evidenzia: \u201cLa Regione Lazio in questi ultimi cinque anni ha portato avanti una importante azione finalizzata a risolvere il problema centrale del sistema sanitario: ossia quello della mole enorme di debiti che impediva di potenziare e migliorare l\u2019offerta dei servizi. Di questo va dato merito al <strong>presidente Zingaretti<\/strong> e alla sua amministrazione. Ora per\u00f2 c\u2019\u00e8 da fare un ulteriore passaggio, che rappresenta la vera svolta e la rivoluzione rispetto al passato: prevedere una nuova organizzazione dei servizi che copra in maniera puntuale ed efficace tutti i territori, soprattutto quello della provincia di Frosinone, spesso penalizzato negli anni scorsi\u201d.<\/p>\n<p class=\"m_935529386238182751gmail-yiv1228599189msonormal\">\u201cPurtroppo \u00e8 un dato di fatto che la nostra provincia soffra enormemente da questo punto di vista, lo dimostrano i numeri, in particolare di <strong>coloro che sono costretti a usufruire di strutture che si trovano fuori dai nostri confini<\/strong>, nonostante comunque siano presenti anche delle importanti eccellenze in alcuni settori. Ma non basta, occorre ricalibrare in maniera complessiva l\u2019offerta, venendo incontro alle esigenze e alle richieste che arrivano dai nostri cittadini\u201d.<\/p>\n<p class=\"m_935529386238182751gmail-yiv1228599189msonormal\">\u201cE\u2019 questa la prossima partita da giocare e da vincere \u2013 conclude Antonio Pompeo \u2013 perch\u00e9 rappresenta il discrimine tra la buona amministrazione, e un modello che nel passato ha fatto solo danni, tagliando prestazioni e cure e alimentando sentimenti di antipolitica e di distanza rispetto alle istituzioni che purtroppo oggi scontiamo e dai quali si pu\u00f2 uscire solo dimostrando capacit\u00e0 e attenzione\u201d.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u201cLa Provincia di Frosinone \u00e8 un territorio composto da 91 comuni, molti dei quali montani, distanti dai centri principali. E\u2019<\/p>\n","protected":false},"author":3,"featured_media":1340,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[85,481,83,107],"class_list":["post-1337","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-pompeo","tag-presidi","tag-provincia","tag-sanita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pompeo: \u201cOccorre potenziare l&#039;offerta di servizi sanitari nel nostro territorio&quot; - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"E\u2019 necessario che l\u2019organizzazione dei servizi sanitari preveda la presenza di presidi che permettano a tutti i cittadini di avere le stesse possibilit\u00e0.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/09\/pompeo-occorre-potenziare-lofferta-di-servizi-sanitari-nel-nostro-territorio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pompeo: \u201cOccorre potenziare l&#039;offerta di servizi sanitari nel nostro territorio&quot;\" \/>\n<meta property=\"og:description\" content=\"E\u2019 necessario che l\u2019organizzazione dei servizi sanitari preveda la presenza di presidi che permettano a tutti i cittadini di avere le stesse possibilit\u00e0.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/09\/pompeo-occorre-potenziare-lofferta-di-servizi-sanitari-nel-nostro-territorio\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"http:\/\/www.facebook.com\/TuNews24\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-09T14:32:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-12T16:41:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/presidente-antonio-pompeo-e1549367630584.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"356\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gianluca Trento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gianluca Trento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/09\\\/pompeo-occorre-potenziare-lofferta-di-servizi-sanitari-nel-nostro-territorio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/09\\\/pompeo-occorre-potenziare-lofferta-di-servizi-sanitari-nel-nostro-territorio\\\/\"},\"author\":{\"name\":\"Gianluca Trento\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/61ad8468fc64fa3e36d950057c9c2cbd\"},\"headline\":\"Pompeo: \u201cOccorre potenziare l&#8217;offerta di servizi sanitari nel nostro territorio&#8221;\",\"datePublished\":\"2018-11-09T14:32:20+00:00\",\"dateModified\":\"2018-11-12T16:41:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/09\\\/pompeo-occorre-potenziare-lofferta-di-servizi-sanitari-nel-nostro-territorio\\\/\"},\"wordCount\":304,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/09\\\/pompeo-occorre-potenziare-lofferta-di-servizi-sanitari-nel-nostro-territorio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/presidente-antonio-pompeo-e1549367630584.jpg\",\"keywords\":[\"pompeo\",\"presidi\",\"provincia\",\"Sanit\u00e0\"],\"articleSection\":[\"Evidenza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/09\\\/pompeo-occorre-potenziare-lofferta-di-servizi-sanitari-nel-nostro-territorio\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/09\\\/pompeo-occorre-potenziare-lofferta-di-servizi-sanitari-nel-nostro-territorio\\\/\",\"name\":\"Pompeo: \u201cOccorre potenziare l'offerta di servizi sanitari nel nostro territorio\\\" - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/09\\\/pompeo-occorre-potenziare-lofferta-di-servizi-sanitari-nel-nostro-territorio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/09\\\/pompeo-occorre-potenziare-lofferta-di-servizi-sanitari-nel-nostro-territorio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/presidente-antonio-pompeo-e1549367630584.jpg\",\"datePublished\":\"2018-11-09T14:32:20+00:00\",\"dateModified\":\"2018-11-12T16:41:56+00:00\",\"description\":\"E\u2019 necessario che l\u2019organizzazione dei servizi sanitari preveda la presenza di presidi che permettano a tutti i cittadini di avere le stesse possibilit\u00e0.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/09\\\/pompeo-occorre-potenziare-lofferta-di-servizi-sanitari-nel-nostro-territorio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/09\\\/pompeo-occorre-potenziare-lofferta-di-servizi-sanitari-nel-nostro-territorio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/09\\\/pompeo-occorre-potenziare-lofferta-di-servizi-sanitari-nel-nostro-territorio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/presidente-antonio-pompeo-e1549367630584.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/presidente-antonio-pompeo-e1549367630584.jpg\",\"width\":632,\"height\":356,\"caption\":\"Il sindaco di Ferentino Antonio Pompeo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/09\\\/pompeo-occorre-potenziare-lofferta-di-servizi-sanitari-nel-nostro-territorio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pompeo: \u201cOccorre potenziare l&#8217;offerta di servizi sanitari nel nostro territorio&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/09\\\/pompeo-occorre-potenziare-lofferta-di-servizi-sanitari-nel-nostro-territorio\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/09\\\/pompeo-occorre-potenziare-lofferta-di-servizi-sanitari-nel-nostro-territorio\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/61ad8468fc64fa3e36d950057c9c2cbd\",\"name\":\"Gianluca Trento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g\",\"caption\":\"Gianluca Trento\"},\"description\":\"Giornalista dei quotidiani online \\\"LaProvinciaQuotidiano.it\\\" e \\\"TuNews24.it\\\" e del settimanale cartaceo \\\"Tu News\\\". In passato \u00e8 stato anche Direttore Editoriale de \\\"La Provincia\\\", Direttore Responsabile del quotidiano \\\"Ciociaria Oggi\\\", Condirettore de \\\"Il quotidiano della Ciociaria\\\", giornalista di \\\"Paese Sera\\\", del settimanale \\\"L\u2019Inchiesta\\\" e del quotidiano online \\\"Il Corriere della Provincia\\\".\",\"sameAs\":[\"https:\\\/\\\/www.tunews24.it\",\"http:\\\/\\\/www.facebook.com\\\/TuNews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/gianluca\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/09\\\/pompeo-occorre-potenziare-lofferta-di-servizi-sanitari-nel-nostro-territorio\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pompeo: \u201cOccorre potenziare l'offerta di servizi sanitari nel nostro territorio\" - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"E\u2019 necessario che l\u2019organizzazione dei servizi sanitari preveda la presenza di presidi che permettano a tutti i cittadini di avere le stesse possibilit\u00e0.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/09\/pompeo-occorre-potenziare-lofferta-di-servizi-sanitari-nel-nostro-territorio\/","og_locale":"it_IT","og_type":"article","og_title":"Pompeo: \u201cOccorre potenziare l'offerta di servizi sanitari nel nostro territorio\"","og_description":"E\u2019 necessario che l\u2019organizzazione dei servizi sanitari preveda la presenza di presidi che permettano a tutti i cittadini di avere le stesse possibilit\u00e0.","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/09\/pompeo-occorre-potenziare-lofferta-di-servizi-sanitari-nel-nostro-territorio\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"http:\/\/www.facebook.com\/TuNews24","article_published_time":"2018-11-09T14:32:20+00:00","article_modified_time":"2018-11-12T16:41:56+00:00","og_image":[{"width":632,"height":356,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/presidente-antonio-pompeo-e1549367630584.jpg","type":"image\/jpeg"}],"author":"Gianluca Trento","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Gianluca Trento","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/09\/pompeo-occorre-potenziare-lofferta-di-servizi-sanitari-nel-nostro-territorio\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/09\/pompeo-occorre-potenziare-lofferta-di-servizi-sanitari-nel-nostro-territorio\/"},"author":{"name":"Gianluca Trento","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/61ad8468fc64fa3e36d950057c9c2cbd"},"headline":"Pompeo: \u201cOccorre potenziare l&#8217;offerta di servizi sanitari nel nostro territorio&#8221;","datePublished":"2018-11-09T14:32:20+00:00","dateModified":"2018-11-12T16:41:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/09\/pompeo-occorre-potenziare-lofferta-di-servizi-sanitari-nel-nostro-territorio\/"},"wordCount":304,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/09\/pompeo-occorre-potenziare-lofferta-di-servizi-sanitari-nel-nostro-territorio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/presidente-antonio-pompeo-e1549367630584.jpg","keywords":["pompeo","presidi","provincia","Sanit\u00e0"],"articleSection":["Evidenza"],"inLanguage":"it-IT","copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/09\/pompeo-occorre-potenziare-lofferta-di-servizi-sanitari-nel-nostro-territorio\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/09\/pompeo-occorre-potenziare-lofferta-di-servizi-sanitari-nel-nostro-territorio\/","name":"Pompeo: \u201cOccorre potenziare l'offerta di servizi sanitari nel nostro territorio\" - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/09\/pompeo-occorre-potenziare-lofferta-di-servizi-sanitari-nel-nostro-territorio\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/09\/pompeo-occorre-potenziare-lofferta-di-servizi-sanitari-nel-nostro-territorio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/presidente-antonio-pompeo-e1549367630584.jpg","datePublished":"2018-11-09T14:32:20+00:00","dateModified":"2018-11-12T16:41:56+00:00","description":"E\u2019 necessario che l\u2019organizzazione dei servizi sanitari preveda la presenza di presidi che permettano a tutti i cittadini di avere le stesse possibilit\u00e0.","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/09\/pompeo-occorre-potenziare-lofferta-di-servizi-sanitari-nel-nostro-territorio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/09\/pompeo-occorre-potenziare-lofferta-di-servizi-sanitari-nel-nostro-territorio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/09\/pompeo-occorre-potenziare-lofferta-di-servizi-sanitari-nel-nostro-territorio\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/presidente-antonio-pompeo-e1549367630584.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/presidente-antonio-pompeo-e1549367630584.jpg","width":632,"height":356,"caption":"Il sindaco di Ferentino Antonio Pompeo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/09\/pompeo-occorre-potenziare-lofferta-di-servizi-sanitari-nel-nostro-territorio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Pompeo: \u201cOccorre potenziare l&#8217;offerta di servizi sanitari nel nostro territorio&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/09\/pompeo-occorre-potenziare-lofferta-di-servizi-sanitari-nel-nostro-territorio\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/09\/pompeo-occorre-potenziare-lofferta-di-servizi-sanitari-nel-nostro-territorio\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/61ad8468fc64fa3e36d950057c9c2cbd","name":"Gianluca Trento","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g","caption":"Gianluca Trento"},"description":"Giornalista dei quotidiani online \"LaProvinciaQuotidiano.it\" e \"TuNews24.it\" e del settimanale cartaceo \"Tu News\". In passato \u00e8 stato anche Direttore Editoriale de \"La Provincia\", Direttore Responsabile del quotidiano \"Ciociaria Oggi\", Condirettore de \"Il quotidiano della Ciociaria\", giornalista di \"Paese Sera\", del settimanale \"L\u2019Inchiesta\" e del quotidiano online \"Il Corriere della Provincia\".","sameAs":["https:\/\/www.tunews24.it","http:\/\/www.facebook.com\/TuNews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/gianluca\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/09\/pompeo-occorre-potenziare-lofferta-di-servizi-sanitari-nel-nostro-territorio\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/1337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=1337"}],"version-history":[{"count":4,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/1337\/revisions"}],"predecessor-version":[{"id":1343,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/1337\/revisions\/1343"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/1340"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=1337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=1337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=1337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}