{"id":13353,"date":"2019-06-19T20:22:33","date_gmt":"2019-06-19T18:22:33","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=13353"},"modified":"2019-06-21T19:51:17","modified_gmt":"2019-06-21T17:51:17","slug":"la-rivoluzione-azzurra-parte-dallastor-venerdi-gli-stati-generali-di-fi","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/19\/la-rivoluzione-azzurra-parte-dallastor-venerdi-gli-stati-generali-di-fi\/","title":{"rendered":"Parte la \u2018Rivoluzione azzurra\u2019: all&#8217;Astor gli Stati generali di FI"},"content":{"rendered":"<p>&#8220;Un processo di rinnovamento, voluto con forza e chiesto da militanti, eletti e quadri dirigenti che rappresentano i territori, in modo particolare dal coordinamento provinciale di Frosinone&#8221;.<\/p>\n<p>Cos\u00ec il <strong>coordinatore provinciale azzurro, Tommaso Ciccone<\/strong>, annuncia gli Stati generali in programma per <strong>venerd\u00ec prossimo, alle 18.30, all\u2019Astor Hotel di Frosinone<\/strong>, dove insieme a lui ci saranno il vice coordinatore regionale <strong>Gianluca Quadrini<\/strong>; il vice coordinatore nazionale degli enti locali, <strong>Mario Abbruzzese<\/strong>; i consiglieri regionali <strong>Pasquale Ciacciarelli<\/strong> e <strong>Adriano Palozzi<\/strong> e il capogruppo alla Regione, <strong>Antonello Aurigemma<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_13354\" aria-describedby=\"caption-attachment-13354\" style=\"width: 632px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13354 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/abbruzzese-ciacciarelli-e1560968070952.jpg\" alt=\"abbruzzese ciacciarelli forza italia frosinone astor il corriere della provincia\" width=\"632\" height=\"352\" \/><figcaption id=\"caption-attachment-13354\" class=\"wp-caption-text\">Mario Abbruzzese e Pasquale Ciacciarelli<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>Un appuntamento che segue quello del 18 giugno scorso, che ha visto la nascita del \u2018Laboratorio Lazio per il cambiamento\u2019, un\u2019ipotesi di lavoro per aprire una stagione di profondo e radicale cambiamento del nostro partito.<\/p>\n<h2>L\u2019analisi critica e il futuro del partito<\/h2>\n<p>&#8220;Gi\u00e0 nei mesi scorsi \u2013 sottolinea Ciccone &#8211; \u00e8 stata sollevata pi\u00f9 volte, e non solo nella nostra provincia, la necessit\u00e0 di uno smantellamento del cosiddetto \u2018cerchio magico\u2019, concausa del declino nazionale a cui noi tutti stiamo assistendo. Gi\u00e0 da settimane<strong> il coordinamento provinciale di Forza Italia ha avviato una profonda riflessione sul futuro del nostro partito<\/strong>, su come rinnovare la sua classe dirigente e la sua offerta politica&#8221;.<\/p>\n<p>&#8220;Una critica rivolta alla gestione del partito, sottolineata dai quadri dirigenti e dagli eletti del nostro territorio, affinch\u00e9, con i fatti e non pi\u00f9 solo a parole, si manifesti la volont\u00e0 d\u2019intraprendere un percorso virtuoso fatto di rigenerazione e di proposte concrete, utili a invertire la tendenza che ci vede in disfacimento&#8221;.<\/p>\n<h2>Il rinnovamento deve passare per i territori<\/h2>\n<p>Ciccone si sofferma anche sulla necessit\u00e0 del &#8220;<strong>coinvolgimento fattivo dei rappresentanti territoriali<\/strong>, conoscitori delle istanze e delle necessit\u00e0 delle comunit\u00e0 locali. Dopo la conferenza stampa di Roma, inizia ora la fase del confronto e delle proposte concrete, attraverso l\u2019organizzazione di una serie di incontri articolati su base provinciale, per ogni provincia del Lazio, e coordinati con l\u2019attivit\u00e0 di \u2018Laboratorio Lazio per il cambiamento\u2019. L\u2019organizzazione territoriale di Forza Italia, dalla provincia di Frosinone, si dimostra, di fatto, ancora essenziale nelle dinamiche interne del nostro partito&#8221;.<\/p>\n<p>&#8220;Lo ha fatto gi\u00e0 come prima provincia nella quale si \u00e8 celebrato un congresso provinciale per la nomina del coordinatore e del coordinamento; lo sta continuando a fare, insieme alle altre province del Lazio, come ingranaggio portante di un meccanismo di rigenerazione politica che sola pu\u00f2 garantire la sopravvivenza del nostro partito\u201d.<\/p>\n<h2>Venerd\u00ec gli Stati generali<\/h2>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_13355\" aria-describedby=\"caption-attachment-13355\" style=\"width: 632px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13355 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/antonello-aurigemma-e1560968241921.jpg\" alt=\"antonello aurigemma forza italia regione lazio il corriere della provincia\" width=\"632\" height=\"421\" \/><figcaption id=\"caption-attachment-13355\" class=\"wp-caption-text\">Il capogruppo di Forza Italia alla Regione Lazio Antonello Aurigemma<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&#8220;Nelle scorse settimane, durante i giorni di campagna elettorale, avevo lanciato la proposta di convocare gli \u2018Stati generali di Forza Italia\u2019 a livello provinciale, per raccogliere, in una mozione condivisa, critiche e proposte per un reale rinnovamento politico. Quella proposta, oggi, grazie all\u2019iniziativa degli onorevoli Ciacciarelli, Aurigemma, Palozzi e Abbruzzese, acquista maggior peso perch\u00e9 inserita in un percorso di confronto e dibattito da condurre a livello regionale&#8221;.<\/p>\n<p>&#8220;Da qui l\u2019appuntamento dal titolo &#8216;Stati generali di Forza Italia \u2013 Laboratorio Lazio per il cambiamento&#8217;, in programma per <strong>venerd\u00ec 21 giugno all\u2019Astor hotel di Frosinone<\/strong>, con <strong>inizio alle ore 18.30<\/strong>.\u00a0 Il primo di una serie che toccher\u00e0 tutte le province del Lazio. <strong>Sar\u00e0 l\u2019occasione per un confronto corale<\/strong>, dialettico e costruttivo sul futuro di Forza Italia e dei suoi appartenenti, condotto fra i simpatizzanti, i militanti, gli eletti e i quadri dirigenti locali&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_2611\" aria-describedby=\"caption-attachment-2611\" style=\"width: 680px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2611 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/quadrini-gianluca.jpg\" alt=\"malasanit\u00e0 sora ospedale quadrini endoscopia ciociaria arpino frosinone regione lazio\" width=\"680\" height=\"365\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/quadrini-gianluca.jpg 680w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/quadrini-gianluca-300x161.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/quadrini-gianluca-500x268.jpg 500w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><figcaption id=\"caption-attachment-2611\" class=\"wp-caption-text\">Il vice coordinatore regionale di FI Gianluca Quadrini<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h2>La proposta: Frosinone cantiere azzurro<\/h2>\n<p>&#8220;In quella stessa occasione \u2013 fa sapere infine Ciccone &#8211; proporr\u00f2 la costituzione, per la provincia di Frosinone, di un tavolo per l\u2019elaborazione progettuale e l\u2019approfondimento politico denominato \u2018Frosinone cantiere azzurro\u2019, con lo scopo di rafforzare la \u201cRivoluzione azzurra\u201d attraverso l\u2019impegno congiunto di un gruppo di lavoro composto non solo da chi, a ogni livello di competenza e secondo il proprio ruolo, si riconosce in Forza Italia, ma anche da quanti sono rimasti, per scelta o per necessit\u00e0, ai margini del nostro partito&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Un processo di rinnovamento, voluto con forza e chiesto da militanti, eletti e quadri dirigenti che rappresentano i territori, in<\/p>\n","protected":false},"author":18,"featured_media":10476,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[4780,1115,1109,93,1251,1226,1336,4819,2927],"class_list":["post-13353","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-antonello-aurigemma","tag-astor-hotel","tag-forza-italia","tag-frosinone","tag-gianluca-quadrini","tag-mario-abbruzzese","tag-pasquale-ciacciarelli","tag-stati-generali","tag-tommaso-ciccone"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Parte la \u2018Rivoluzione azzurra\u2019: all&#039;Astor gli Stati generali di FI - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"La rivoluzione azzurra parte da Frosinone dove venerd\u00ec prossimo, 21 giugno, si svolgeranno all&#039;Astor Hotel gli Stati generali di Forza Italia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/19\/la-rivoluzione-azzurra-parte-dallastor-venerdi-gli-stati-generali-di-fi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Parte la \u2018Rivoluzione azzurra\u2019: all&#039;Astor gli Stati generali di FI\" \/>\n<meta property=\"og:description\" content=\"La rivoluzione azzurra parte da Frosinone dove venerd\u00ec prossimo, 21 giugno, si svolgeranno all&#039;Astor Hotel gli Stati generali di Forza Italia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/19\/la-rivoluzione-azzurra-parte-dallastor-venerdi-gli-stati-generali-di-fi\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-19T18:22:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-21T17:51:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/Tommaso-ciccone-provincia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"575\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/19\\\/la-rivoluzione-azzurra-parte-dallastor-venerdi-gli-stati-generali-di-fi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/19\\\/la-rivoluzione-azzurra-parte-dallastor-venerdi-gli-stati-generali-di-fi\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Parte la \u2018Rivoluzione azzurra\u2019: all&#8217;Astor gli Stati generali di FI\",\"datePublished\":\"2019-06-19T18:22:33+00:00\",\"dateModified\":\"2019-06-21T17:51:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/19\\\/la-rivoluzione-azzurra-parte-dallastor-venerdi-gli-stati-generali-di-fi\\\/\"},\"wordCount\":690,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/19\\\/la-rivoluzione-azzurra-parte-dallastor-venerdi-gli-stati-generali-di-fi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/Tommaso-ciccone-provincia.jpg\",\"keywords\":[\"Antonello Aurigemma\",\"astor hotel\",\"forza italia\",\"Frosinone\",\"Gianluca Quadrini\",\"mario abbruzzese\",\"pasquale ciacciarelli\",\"stati generali\",\"Tommaso Ciccone\"],\"articleSection\":[\"News\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/19\\\/la-rivoluzione-azzurra-parte-dallastor-venerdi-gli-stati-generali-di-fi\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/19\\\/la-rivoluzione-azzurra-parte-dallastor-venerdi-gli-stati-generali-di-fi\\\/\",\"name\":\"Parte la \u2018Rivoluzione azzurra\u2019: all'Astor gli Stati generali di FI - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/19\\\/la-rivoluzione-azzurra-parte-dallastor-venerdi-gli-stati-generali-di-fi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/19\\\/la-rivoluzione-azzurra-parte-dallastor-venerdi-gli-stati-generali-di-fi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/Tommaso-ciccone-provincia.jpg\",\"datePublished\":\"2019-06-19T18:22:33+00:00\",\"dateModified\":\"2019-06-21T17:51:17+00:00\",\"description\":\"La rivoluzione azzurra parte da Frosinone dove venerd\u00ec prossimo, 21 giugno, si svolgeranno all'Astor Hotel gli Stati generali di Forza Italia\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/19\\\/la-rivoluzione-azzurra-parte-dallastor-venerdi-gli-stati-generali-di-fi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/19\\\/la-rivoluzione-azzurra-parte-dallastor-venerdi-gli-stati-generali-di-fi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/19\\\/la-rivoluzione-azzurra-parte-dallastor-venerdi-gli-stati-generali-di-fi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/Tommaso-ciccone-provincia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/Tommaso-ciccone-provincia.jpg\",\"width\":575,\"height\":395,\"caption\":\"Il coordinatore provinciale di Forza Italia Tommaso Ciccone\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/19\\\/la-rivoluzione-azzurra-parte-dallastor-venerdi-gli-stati-generali-di-fi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parte la \u2018Rivoluzione azzurra\u2019: all&#8217;Astor gli Stati generali di FI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/19\\\/la-rivoluzione-azzurra-parte-dallastor-venerdi-gli-stati-generali-di-fi\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/19\\\/la-rivoluzione-azzurra-parte-dallastor-venerdi-gli-stati-generali-di-fi\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/19\\\/la-rivoluzione-azzurra-parte-dallastor-venerdi-gli-stati-generali-di-fi\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Parte la \u2018Rivoluzione azzurra\u2019: all'Astor gli Stati generali di FI - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"La rivoluzione azzurra parte da Frosinone dove venerd\u00ec prossimo, 21 giugno, si svolgeranno all'Astor Hotel gli Stati generali di Forza Italia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/19\/la-rivoluzione-azzurra-parte-dallastor-venerdi-gli-stati-generali-di-fi\/","og_locale":"it_IT","og_type":"article","og_title":"Parte la \u2018Rivoluzione azzurra\u2019: all'Astor gli Stati generali di FI","og_description":"La rivoluzione azzurra parte da Frosinone dove venerd\u00ec prossimo, 21 giugno, si svolgeranno all'Astor Hotel gli Stati generali di Forza Italia","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/19\/la-rivoluzione-azzurra-parte-dallastor-venerdi-gli-stati-generali-di-fi\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-06-19T18:22:33+00:00","article_modified_time":"2019-06-21T17:51:17+00:00","og_image":[{"width":575,"height":395,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/Tommaso-ciccone-provincia.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/19\/la-rivoluzione-azzurra-parte-dallastor-venerdi-gli-stati-generali-di-fi\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/19\/la-rivoluzione-azzurra-parte-dallastor-venerdi-gli-stati-generali-di-fi\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Parte la \u2018Rivoluzione azzurra\u2019: all&#8217;Astor gli Stati generali di FI","datePublished":"2019-06-19T18:22:33+00:00","dateModified":"2019-06-21T17:51:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/19\/la-rivoluzione-azzurra-parte-dallastor-venerdi-gli-stati-generali-di-fi\/"},"wordCount":690,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/19\/la-rivoluzione-azzurra-parte-dallastor-venerdi-gli-stati-generali-di-fi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/Tommaso-ciccone-provincia.jpg","keywords":["Antonello Aurigemma","astor hotel","forza italia","Frosinone","Gianluca Quadrini","mario abbruzzese","pasquale ciacciarelli","stati generali","Tommaso Ciccone"],"articleSection":["News"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/19\/la-rivoluzione-azzurra-parte-dallastor-venerdi-gli-stati-generali-di-fi\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/19\/la-rivoluzione-azzurra-parte-dallastor-venerdi-gli-stati-generali-di-fi\/","name":"Parte la \u2018Rivoluzione azzurra\u2019: all'Astor gli Stati generali di FI - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/19\/la-rivoluzione-azzurra-parte-dallastor-venerdi-gli-stati-generali-di-fi\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/19\/la-rivoluzione-azzurra-parte-dallastor-venerdi-gli-stati-generali-di-fi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/Tommaso-ciccone-provincia.jpg","datePublished":"2019-06-19T18:22:33+00:00","dateModified":"2019-06-21T17:51:17+00:00","description":"La rivoluzione azzurra parte da Frosinone dove venerd\u00ec prossimo, 21 giugno, si svolgeranno all'Astor Hotel gli Stati generali di Forza Italia","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/19\/la-rivoluzione-azzurra-parte-dallastor-venerdi-gli-stati-generali-di-fi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/19\/la-rivoluzione-azzurra-parte-dallastor-venerdi-gli-stati-generali-di-fi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/19\/la-rivoluzione-azzurra-parte-dallastor-venerdi-gli-stati-generali-di-fi\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/Tommaso-ciccone-provincia.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/Tommaso-ciccone-provincia.jpg","width":575,"height":395,"caption":"Il coordinatore provinciale di Forza Italia Tommaso Ciccone"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/19\/la-rivoluzione-azzurra-parte-dallastor-venerdi-gli-stati-generali-di-fi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Parte la \u2018Rivoluzione azzurra\u2019: all&#8217;Astor gli Stati generali di FI"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/19\/la-rivoluzione-azzurra-parte-dallastor-venerdi-gli-stati-generali-di-fi\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/19\/la-rivoluzione-azzurra-parte-dallastor-venerdi-gli-stati-generali-di-fi\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/19\/la-rivoluzione-azzurra-parte-dallastor-venerdi-gli-stati-generali-di-fi\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/13353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=13353"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/13353\/revisions"}],"predecessor-version":[{"id":13357,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/13353\/revisions\/13357"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/10476"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=13353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=13353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=13353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}