{"id":13197,"date":"2019-06-17T15:46:54","date_gmt":"2019-06-17T13:46:54","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=13197"},"modified":"2019-06-17T15:46:54","modified_gmt":"2019-06-17T13:46:54","slug":"bcc-roma-il-cda-nomina-roberto-gandolfo-direttore-generale-e-francesco-petitto-vice-direttore-generale-vicario","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/17\/bcc-roma-il-cda-nomina-roberto-gandolfo-direttore-generale-e-francesco-petitto-vice-direttore-generale-vicario\/","title":{"rendered":"BCC Roma: il Cda nomina Roberto Gandolfo direttore generale e Francesco Petitto vice direttore generale vicario"},"content":{"rendered":"<p><strong>Roberto Gandolfo<\/strong> \u00e8 il nuovo direttore generale della Banca di Credito Cooperativo di Roma. Lo ha deciso il Consiglio d&#8217;amministrazione con il parere motivato della Capogruppo Iccrea<b>. <\/b>Prende il posto di Mauro Pastore, nominato Direttore Generale della Capogruppo Iccrea.<b><br \/>\n<\/b><\/p>\n<h2>Il curriculum<\/h2>\n<p class=\"m_-6164408247901857296MsoNormal_mailru_css_attribute_postfix\">Dirigente di lungo corso della Banca, Gandolfo \u00e8 nato a Roma nel 1956 e si \u00e8 laureato in Economia e Commercio nel 1978. Dal 1977 al 1979 \u00e8 stato revisore presso la Arthur Young &amp; Co, dal 1979 al 1984 ha lavorato presso il Credito Romagnolo e dal 1984 al 1988 in Arthur Young Consulting. Dal 1988 al 1993 \u00e8 stato Dirigente in importanti societ\u00e0 di informatica come la Datamat Ingegneria dei Sistemi. Nel 1993 \u00e8 entrato in BCC Roma (allora Cassa Rurale ed Artigiana) come Direttore dell\u2019Area Affari, quindi con la responsabilit\u00e0 dell\u2019Area Crediti. Nel 2002 \u00e8 nominato Vice Direttore Generale e dal 2004 ha ricoperto la carica di Vicario con la responsabilit\u00e0 dell\u2019Area Governo Asset.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-13199\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/Francesco-Petitto-Vice-Direttore-Generale-Vicario-BCC-Roma.jpg\" alt=\"Francesco Petitto, Vice Direttore Generale Vicario BCC Roma\" width=\"632\" height=\"953\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/Francesco-Petitto-Vice-Direttore-Generale-Vicario-BCC-Roma.jpg 392w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/Francesco-Petitto-Vice-Direttore-Generale-Vicario-BCC-Roma-199x300.jpg 199w\" sizes=\"auto, (max-width: 632px) 100vw, 632px\" \/><\/p>\n<p class=\"m_-6164408247901857296MsoNormal_mailru_css_attribute_postfix\">\n<p class=\"m_-6164408247901857296MsoNormal_mailru_css_attribute_postfix\">Nella stessa seduta il Consiglio di Amministrazione ha nominato Vice Direttore Generale Vicario <b>Francesco Petitto<\/b>, gi\u00e0 Vice Direttore Generale. Nato a Roma nel 1956, Petitto \u00e8 laureato in Giurisprudenza e ha lavorato presso la BNL, l\u2019Istituto San Paolo di Torino e la Banca del Fucino. \u00c8 alle dipendenze BCC Roma dal 2003, a seguito dell\u2019incorporazione della BCC di Segni in cui ricopriva il ruolo di Direttore Generale. Nel 2007 \u00e8 stato nominato Direttore delle Risorse Umane; dal 2010 \u00e8 Direttore Rete e Commerciale, e dall\u2019aprile 2015 Vice Direttore Generale.<\/p>\n<h2>L&#8217;intervento del presidente Liberati<\/h2>\n<p class=\"m_-6164408247901857296MsoNormal_mailru_css_attribute_postfix\">\u201cLe nomine di Gandolfo e Petitto sono ispirate alla continuit\u00e0 gestionale aziendale, nel quadro di un progetto di lungo termine che ha portato la Banca a conseguire risultati sempre pi\u00f9 apprezzabili, divenendo un punto di riferimento nelle aree di competenza territoriale e nel panorama del credito cooperativo italiano\u201d, ha dichiarato Francesco Liberati, Presidente di BCC Roma, aggiungendo inoltre che \u201cla nomina di Mauro Pastore come Direttore Generale della Capogruppo Iccrea rappresenta una scelta utile per il futuro del Gruppo, che potr\u00e0 contare sull\u2019esperienza maturata da Pastore stesso in BCC Roma\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Roberto Gandolfo \u00e8 il nuovo direttore generale della Banca di Credito Cooperativo di Roma. Lo ha deciso il Consiglio d&#8217;amministrazione<\/p>\n","protected":false},"author":3,"featured_media":13198,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[3918,3919,4753,4751,4752],"class_list":["post-13197","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","tag-bcc-roma","tag-francesco-liberati","tag-francesco-petitto","tag-mauro-pastore","tag-roberto-gandolfo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>BCC Roma: il Cda nomina Roberto Gandolfo direttore generale e Francesco Petitto vice direttore generale vicario - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Liberati: \u201cNomine ispirate alla continuit\u00e0 aziendale, nel quadro di un progetto di lungo termine che ha portato la banca a diventare punto di riferimento\u201d.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/17\/bcc-roma-il-cda-nomina-roberto-gandolfo-direttore-generale-e-francesco-petitto-vice-direttore-generale-vicario\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BCC Roma: il Cda nomina Roberto Gandolfo direttore generale e Francesco Petitto vice direttore generale vicario\" \/>\n<meta property=\"og:description\" content=\"Liberati: \u201cNomine ispirate alla continuit\u00e0 aziendale, nel quadro di un progetto di lungo termine che ha portato la banca a diventare punto di riferimento\u201d.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/17\/bcc-roma-il-cda-nomina-roberto-gandolfo-direttore-generale-e-francesco-petitto-vice-direttore-generale-vicario\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"http:\/\/www.facebook.com\/TuNews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-17T13:46:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/Roberto-Gandolfo-Direttore-Generale-BCC-Roma.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"610\" \/>\n\t<meta property=\"og:image:height\" content=\"405\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gianluca Trento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gianluca Trento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/17\\\/bcc-roma-il-cda-nomina-roberto-gandolfo-direttore-generale-e-francesco-petitto-vice-direttore-generale-vicario\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/17\\\/bcc-roma-il-cda-nomina-roberto-gandolfo-direttore-generale-e-francesco-petitto-vice-direttore-generale-vicario\\\/\"},\"author\":{\"name\":\"Gianluca Trento\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/61ad8468fc64fa3e36d950057c9c2cbd\"},\"headline\":\"BCC Roma: il Cda nomina Roberto Gandolfo direttore generale e Francesco Petitto vice direttore generale vicario\",\"datePublished\":\"2019-06-17T13:46:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/17\\\/bcc-roma-il-cda-nomina-roberto-gandolfo-direttore-generale-e-francesco-petitto-vice-direttore-generale-vicario\\\/\"},\"wordCount\":337,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/17\\\/bcc-roma-il-cda-nomina-roberto-gandolfo-direttore-generale-e-francesco-petitto-vice-direttore-generale-vicario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/Roberto-Gandolfo-Direttore-Generale-BCC-Roma.jpg\",\"keywords\":[\"Bcc Roma\",\"Francesco Liberati\",\"Francesco Petitto\",\"Mauro Pastore\",\"Roberto Gandolfo\"],\"articleSection\":[\"Economia e Finanza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/17\\\/bcc-roma-il-cda-nomina-roberto-gandolfo-direttore-generale-e-francesco-petitto-vice-direttore-generale-vicario\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/17\\\/bcc-roma-il-cda-nomina-roberto-gandolfo-direttore-generale-e-francesco-petitto-vice-direttore-generale-vicario\\\/\",\"name\":\"BCC Roma: il Cda nomina Roberto Gandolfo direttore generale e Francesco Petitto vice direttore generale vicario - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/17\\\/bcc-roma-il-cda-nomina-roberto-gandolfo-direttore-generale-e-francesco-petitto-vice-direttore-generale-vicario\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/17\\\/bcc-roma-il-cda-nomina-roberto-gandolfo-direttore-generale-e-francesco-petitto-vice-direttore-generale-vicario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/Roberto-Gandolfo-Direttore-Generale-BCC-Roma.jpg\",\"datePublished\":\"2019-06-17T13:46:54+00:00\",\"description\":\"Liberati: \u201cNomine ispirate alla continuit\u00e0 aziendale, nel quadro di un progetto di lungo termine che ha portato la banca a diventare punto di riferimento\u201d.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/17\\\/bcc-roma-il-cda-nomina-roberto-gandolfo-direttore-generale-e-francesco-petitto-vice-direttore-generale-vicario\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/17\\\/bcc-roma-il-cda-nomina-roberto-gandolfo-direttore-generale-e-francesco-petitto-vice-direttore-generale-vicario\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/17\\\/bcc-roma-il-cda-nomina-roberto-gandolfo-direttore-generale-e-francesco-petitto-vice-direttore-generale-vicario\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/Roberto-Gandolfo-Direttore-Generale-BCC-Roma.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/Roberto-Gandolfo-Direttore-Generale-BCC-Roma.jpg\",\"width\":610,\"height\":405,\"caption\":\"Roberto Gandolfo, Direttore Generale BCC Roma\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/17\\\/bcc-roma-il-cda-nomina-roberto-gandolfo-direttore-generale-e-francesco-petitto-vice-direttore-generale-vicario\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BCC Roma: il Cda nomina Roberto Gandolfo direttore generale e Francesco Petitto vice direttore generale vicario\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/17\\\/bcc-roma-il-cda-nomina-roberto-gandolfo-direttore-generale-e-francesco-petitto-vice-direttore-generale-vicario\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/17\\\/bcc-roma-il-cda-nomina-roberto-gandolfo-direttore-generale-e-francesco-petitto-vice-direttore-generale-vicario\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/61ad8468fc64fa3e36d950057c9c2cbd\",\"name\":\"Gianluca Trento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g\",\"caption\":\"Gianluca Trento\"},\"description\":\"Giornalista dei quotidiani online \\\"LaProvinciaQuotidiano.it\\\" e \\\"TuNews24.it\\\" e del settimanale cartaceo \\\"Tu News\\\". In passato \u00e8 stato anche Direttore Editoriale de \\\"La Provincia\\\", Direttore Responsabile del quotidiano \\\"Ciociaria Oggi\\\", Condirettore de \\\"Il quotidiano della Ciociaria\\\", giornalista di \\\"Paese Sera\\\", del settimanale \\\"L\u2019Inchiesta\\\" e del quotidiano online \\\"Il Corriere della Provincia\\\".\",\"sameAs\":[\"https:\\\/\\\/www.tunews24.it\",\"http:\\\/\\\/www.facebook.com\\\/TuNews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/gianluca\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/17\\\/bcc-roma-il-cda-nomina-roberto-gandolfo-direttore-generale-e-francesco-petitto-vice-direttore-generale-vicario\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"BCC Roma: il Cda nomina Roberto Gandolfo direttore generale e Francesco Petitto vice direttore generale vicario - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Liberati: \u201cNomine ispirate alla continuit\u00e0 aziendale, nel quadro di un progetto di lungo termine che ha portato la banca a diventare punto di riferimento\u201d.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/17\/bcc-roma-il-cda-nomina-roberto-gandolfo-direttore-generale-e-francesco-petitto-vice-direttore-generale-vicario\/","og_locale":"it_IT","og_type":"article","og_title":"BCC Roma: il Cda nomina Roberto Gandolfo direttore generale e Francesco Petitto vice direttore generale vicario","og_description":"Liberati: \u201cNomine ispirate alla continuit\u00e0 aziendale, nel quadro di un progetto di lungo termine che ha portato la banca a diventare punto di riferimento\u201d.","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/17\/bcc-roma-il-cda-nomina-roberto-gandolfo-direttore-generale-e-francesco-petitto-vice-direttore-generale-vicario\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"http:\/\/www.facebook.com\/TuNews24","article_published_time":"2019-06-17T13:46:54+00:00","og_image":[{"width":610,"height":405,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/Roberto-Gandolfo-Direttore-Generale-BCC-Roma.jpg","type":"image\/jpeg"}],"author":"Gianluca Trento","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Gianluca Trento","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/17\/bcc-roma-il-cda-nomina-roberto-gandolfo-direttore-generale-e-francesco-petitto-vice-direttore-generale-vicario\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/17\/bcc-roma-il-cda-nomina-roberto-gandolfo-direttore-generale-e-francesco-petitto-vice-direttore-generale-vicario\/"},"author":{"name":"Gianluca Trento","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/61ad8468fc64fa3e36d950057c9c2cbd"},"headline":"BCC Roma: il Cda nomina Roberto Gandolfo direttore generale e Francesco Petitto vice direttore generale vicario","datePublished":"2019-06-17T13:46:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/17\/bcc-roma-il-cda-nomina-roberto-gandolfo-direttore-generale-e-francesco-petitto-vice-direttore-generale-vicario\/"},"wordCount":337,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/17\/bcc-roma-il-cda-nomina-roberto-gandolfo-direttore-generale-e-francesco-petitto-vice-direttore-generale-vicario\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/Roberto-Gandolfo-Direttore-Generale-BCC-Roma.jpg","keywords":["Bcc Roma","Francesco Liberati","Francesco Petitto","Mauro Pastore","Roberto Gandolfo"],"articleSection":["Economia e Finanza"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/17\/bcc-roma-il-cda-nomina-roberto-gandolfo-direttore-generale-e-francesco-petitto-vice-direttore-generale-vicario\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/17\/bcc-roma-il-cda-nomina-roberto-gandolfo-direttore-generale-e-francesco-petitto-vice-direttore-generale-vicario\/","name":"BCC Roma: il Cda nomina Roberto Gandolfo direttore generale e Francesco Petitto vice direttore generale vicario - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/17\/bcc-roma-il-cda-nomina-roberto-gandolfo-direttore-generale-e-francesco-petitto-vice-direttore-generale-vicario\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/17\/bcc-roma-il-cda-nomina-roberto-gandolfo-direttore-generale-e-francesco-petitto-vice-direttore-generale-vicario\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/Roberto-Gandolfo-Direttore-Generale-BCC-Roma.jpg","datePublished":"2019-06-17T13:46:54+00:00","description":"Liberati: \u201cNomine ispirate alla continuit\u00e0 aziendale, nel quadro di un progetto di lungo termine che ha portato la banca a diventare punto di riferimento\u201d.","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/17\/bcc-roma-il-cda-nomina-roberto-gandolfo-direttore-generale-e-francesco-petitto-vice-direttore-generale-vicario\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/17\/bcc-roma-il-cda-nomina-roberto-gandolfo-direttore-generale-e-francesco-petitto-vice-direttore-generale-vicario\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/17\/bcc-roma-il-cda-nomina-roberto-gandolfo-direttore-generale-e-francesco-petitto-vice-direttore-generale-vicario\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/Roberto-Gandolfo-Direttore-Generale-BCC-Roma.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/Roberto-Gandolfo-Direttore-Generale-BCC-Roma.jpg","width":610,"height":405,"caption":"Roberto Gandolfo, Direttore Generale BCC Roma"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/17\/bcc-roma-il-cda-nomina-roberto-gandolfo-direttore-generale-e-francesco-petitto-vice-direttore-generale-vicario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"BCC Roma: il Cda nomina Roberto Gandolfo direttore generale e Francesco Petitto vice direttore generale vicario"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/17\/bcc-roma-il-cda-nomina-roberto-gandolfo-direttore-generale-e-francesco-petitto-vice-direttore-generale-vicario\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/17\/bcc-roma-il-cda-nomina-roberto-gandolfo-direttore-generale-e-francesco-petitto-vice-direttore-generale-vicario\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/61ad8468fc64fa3e36d950057c9c2cbd","name":"Gianluca Trento","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g","caption":"Gianluca Trento"},"description":"Giornalista dei quotidiani online \"LaProvinciaQuotidiano.it\" e \"TuNews24.it\" e del settimanale cartaceo \"Tu News\". In passato \u00e8 stato anche Direttore Editoriale de \"La Provincia\", Direttore Responsabile del quotidiano \"Ciociaria Oggi\", Condirettore de \"Il quotidiano della Ciociaria\", giornalista di \"Paese Sera\", del settimanale \"L\u2019Inchiesta\" e del quotidiano online \"Il Corriere della Provincia\".","sameAs":["https:\/\/www.tunews24.it","http:\/\/www.facebook.com\/TuNews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/gianluca\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/17\/bcc-roma-il-cda-nomina-roberto-gandolfo-direttore-generale-e-francesco-petitto-vice-direttore-generale-vicario\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/13197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=13197"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/13197\/revisions"}],"predecessor-version":[{"id":13201,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/13197\/revisions\/13201"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/13198"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=13197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=13197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=13197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}