{"id":13162,"date":"2019-06-16T10:11:36","date_gmt":"2019-06-16T08:11:36","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=13162"},"modified":"2019-06-18T14:05:51","modified_gmt":"2019-06-18T12:05:51","slug":"diciottenne-rientra-dalle-vacanze-in-spagna-e-viene-arrestato-allaeroporto","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/16\/diciottenne-rientra-dalle-vacanze-in-spagna-e-viene-arrestato-allaeroporto\/","title":{"rendered":"Diciottenne rientra dalle vacanze in Spagna e viene arrestato all&#8217;aeroporto"},"content":{"rendered":"<p>Non poteva finire peggio la vacanza nella penisola iberica per un <strong>diciottenne di Fiuggi<\/strong> che nella tarda serata di ieri, sceso<strong> all&#8217;aeroporto di Fiumicino<\/strong>, invece dei parenti e degli amici contenti di riabbracciarlo ha trovato ad attenderlo i carabinieri della citt\u00e0 termale, che hanno fatto scattare le manette.<\/p>\n<h2>Un&#8217;altra pedina dello spaccio in piazza Spada a Fiuggi<\/h2>\n<p>I militari hanno dato esecuzione all&#8217;ordinanza di custodia cautelare, emessa in data 10 giugno 2019 dal Tribunale dei Minorenni di Roma: <strong>il diciottenne \u00e8 ritenuto responsabile di detenzione ai fini di spaccio di sostanza stupefacente<\/strong> in concorso, quando era ancora minorenne.<\/p>\n<p>Il giovane, al termine delle operazioni di rito, <strong>\u00e8 stato associato presso una comunit\u00e0 educativa<\/strong> in provincia di Viterbo. L&#8217;esecuzione della misura cautelare rientra nella pi\u00f9 vasta e articolata attivit\u00e0 investigativa condotta brillantemente dai carabinieri e finanzieri della citt\u00e0 termale nell&#8217;ambito dell&#8217;operazione convenzionalmente denominata &#8216;Synergie&#8217; che ha sgominato una banda dedita allo spaccio di sostanze stupefacenti nell&#8217;aria nord della provincia di Frosinone.<\/p>\n<h2>I risultati della brillante operazione &#8216;Synergie&#8217;<\/h2>\n<p>L&#8217;attivit\u00e0 \u00e8 iniziata nel mese di febbraio 2018 e conclusasi nel mese di marzo 2019. Un&#8217;indagine durata oltre un anno, coordinata dalla Procura di Frosinone e da quella per i Minorenni di Roma, che ha portato a<strong> 10 arresti<\/strong> (due dei quali minori) tra misure cautelari emesse a seguito dell&#8217;inchiesta e persone finite in manette perch\u00e9 colte in flagranza di reato, un deferimento e 7 segnalati alla prefettura di Frosinone per uso di sostanze stupefacenti, nonch\u00e9 il <strong>sequestro di oltre 15 chili di droga<\/strong> (tra hashish e marijuana) e <strong>la somma contante di oltre 40.000 euro<\/strong>, ritenuta provento dell&#8217;attivit\u00e0 illecita.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Non poteva finire peggio la vacanza nella penisola iberica per un diciottenne di Fiuggi che nella tarda serata di ieri,<\/p>\n","protected":false},"author":18,"featured_media":13163,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,2],"tags":[356,192,90,4738,189,217,4736,4737,4566,741],"class_list":["post-13162","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-cronaca","tag-aeroporto","tag-arresto","tag-carabinieri","tag-diciottenne","tag-droga","tag-fiuggi","tag-fiumicino","tag-operazione-synergie","tag-piazza-spada","tag-spagna"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Diciottenne rientra dalle vacanze in Spagna e viene arrestato all&#039;aeroporto - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Un diciottenne \u00e8 stato arrestato ieri sera a Fiumicino mentre rientrava dalle vacanze in Spagna. Accusato di spaccio di droga a piazza Spada, a Fiuggi\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/16\/diciottenne-rientra-dalle-vacanze-in-spagna-e-viene-arrestato-allaeroporto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diciottenne rientra dalle vacanze in Spagna e viene arrestato all&#039;aeroporto\" \/>\n<meta property=\"og:description\" content=\"Un diciottenne \u00e8 stato arrestato ieri sera a Fiumicino mentre rientrava dalle vacanze in Spagna. Accusato di spaccio di droga a piazza Spada, a Fiuggi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/16\/diciottenne-rientra-dalle-vacanze-in-spagna-e-viene-arrestato-allaeroporto\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-16T08:11:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-18T12:05:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/carabinieri-fiumicino-e1560672638626.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"422\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/16\\\/diciottenne-rientra-dalle-vacanze-in-spagna-e-viene-arrestato-allaeroporto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/16\\\/diciottenne-rientra-dalle-vacanze-in-spagna-e-viene-arrestato-allaeroporto\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Diciottenne rientra dalle vacanze in Spagna e viene arrestato all&#8217;aeroporto\",\"datePublished\":\"2019-06-16T08:11:36+00:00\",\"dateModified\":\"2019-06-18T12:05:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/16\\\/diciottenne-rientra-dalle-vacanze-in-spagna-e-viene-arrestato-allaeroporto\\\/\"},\"wordCount\":277,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/16\\\/diciottenne-rientra-dalle-vacanze-in-spagna-e-viene-arrestato-allaeroporto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/carabinieri-fiumicino-e1560672638626.jpg\",\"keywords\":[\"aeroporto\",\"arresto\",\"carabinieri\",\"diciottenne\",\"droga\",\"Fiuggi\",\"fiumicino\",\"operazione synergie\",\"piazza spada\",\"Spagna\"],\"articleSection\":[\"*SLIDE*\",\"Cronaca\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/16\\\/diciottenne-rientra-dalle-vacanze-in-spagna-e-viene-arrestato-allaeroporto\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/16\\\/diciottenne-rientra-dalle-vacanze-in-spagna-e-viene-arrestato-allaeroporto\\\/\",\"name\":\"Diciottenne rientra dalle vacanze in Spagna e viene arrestato all'aeroporto - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/16\\\/diciottenne-rientra-dalle-vacanze-in-spagna-e-viene-arrestato-allaeroporto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/16\\\/diciottenne-rientra-dalle-vacanze-in-spagna-e-viene-arrestato-allaeroporto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/carabinieri-fiumicino-e1560672638626.jpg\",\"datePublished\":\"2019-06-16T08:11:36+00:00\",\"dateModified\":\"2019-06-18T12:05:51+00:00\",\"description\":\"Un diciottenne \u00e8 stato arrestato ieri sera a Fiumicino mentre rientrava dalle vacanze in Spagna. Accusato di spaccio di droga a piazza Spada, a Fiuggi\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/16\\\/diciottenne-rientra-dalle-vacanze-in-spagna-e-viene-arrestato-allaeroporto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/16\\\/diciottenne-rientra-dalle-vacanze-in-spagna-e-viene-arrestato-allaeroporto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/16\\\/diciottenne-rientra-dalle-vacanze-in-spagna-e-viene-arrestato-allaeroporto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/carabinieri-fiumicino-e1560672638626.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/carabinieri-fiumicino-e1560672638626.jpg\",\"width\":632,\"height\":422,\"caption\":\"Carabinieri all'aeroporto\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/16\\\/diciottenne-rientra-dalle-vacanze-in-spagna-e-viene-arrestato-allaeroporto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Diciottenne rientra dalle vacanze in Spagna e viene arrestato all&#8217;aeroporto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/16\\\/diciottenne-rientra-dalle-vacanze-in-spagna-e-viene-arrestato-allaeroporto\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/16\\\/diciottenne-rientra-dalle-vacanze-in-spagna-e-viene-arrestato-allaeroporto\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/16\\\/diciottenne-rientra-dalle-vacanze-in-spagna-e-viene-arrestato-allaeroporto\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Diciottenne rientra dalle vacanze in Spagna e viene arrestato all'aeroporto - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Un diciottenne \u00e8 stato arrestato ieri sera a Fiumicino mentre rientrava dalle vacanze in Spagna. Accusato di spaccio di droga a piazza Spada, a Fiuggi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/16\/diciottenne-rientra-dalle-vacanze-in-spagna-e-viene-arrestato-allaeroporto\/","og_locale":"it_IT","og_type":"article","og_title":"Diciottenne rientra dalle vacanze in Spagna e viene arrestato all'aeroporto","og_description":"Un diciottenne \u00e8 stato arrestato ieri sera a Fiumicino mentre rientrava dalle vacanze in Spagna. Accusato di spaccio di droga a piazza Spada, a Fiuggi","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/16\/diciottenne-rientra-dalle-vacanze-in-spagna-e-viene-arrestato-allaeroporto\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-06-16T08:11:36+00:00","article_modified_time":"2019-06-18T12:05:51+00:00","og_image":[{"width":632,"height":422,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/carabinieri-fiumicino-e1560672638626.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/16\/diciottenne-rientra-dalle-vacanze-in-spagna-e-viene-arrestato-allaeroporto\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/16\/diciottenne-rientra-dalle-vacanze-in-spagna-e-viene-arrestato-allaeroporto\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Diciottenne rientra dalle vacanze in Spagna e viene arrestato all&#8217;aeroporto","datePublished":"2019-06-16T08:11:36+00:00","dateModified":"2019-06-18T12:05:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/16\/diciottenne-rientra-dalle-vacanze-in-spagna-e-viene-arrestato-allaeroporto\/"},"wordCount":277,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/16\/diciottenne-rientra-dalle-vacanze-in-spagna-e-viene-arrestato-allaeroporto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/carabinieri-fiumicino-e1560672638626.jpg","keywords":["aeroporto","arresto","carabinieri","diciottenne","droga","Fiuggi","fiumicino","operazione synergie","piazza spada","Spagna"],"articleSection":["*SLIDE*","Cronaca"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/16\/diciottenne-rientra-dalle-vacanze-in-spagna-e-viene-arrestato-allaeroporto\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/16\/diciottenne-rientra-dalle-vacanze-in-spagna-e-viene-arrestato-allaeroporto\/","name":"Diciottenne rientra dalle vacanze in Spagna e viene arrestato all'aeroporto - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/16\/diciottenne-rientra-dalle-vacanze-in-spagna-e-viene-arrestato-allaeroporto\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/16\/diciottenne-rientra-dalle-vacanze-in-spagna-e-viene-arrestato-allaeroporto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/carabinieri-fiumicino-e1560672638626.jpg","datePublished":"2019-06-16T08:11:36+00:00","dateModified":"2019-06-18T12:05:51+00:00","description":"Un diciottenne \u00e8 stato arrestato ieri sera a Fiumicino mentre rientrava dalle vacanze in Spagna. Accusato di spaccio di droga a piazza Spada, a Fiuggi","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/16\/diciottenne-rientra-dalle-vacanze-in-spagna-e-viene-arrestato-allaeroporto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/16\/diciottenne-rientra-dalle-vacanze-in-spagna-e-viene-arrestato-allaeroporto\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/16\/diciottenne-rientra-dalle-vacanze-in-spagna-e-viene-arrestato-allaeroporto\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/carabinieri-fiumicino-e1560672638626.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/carabinieri-fiumicino-e1560672638626.jpg","width":632,"height":422,"caption":"Carabinieri all'aeroporto"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/16\/diciottenne-rientra-dalle-vacanze-in-spagna-e-viene-arrestato-allaeroporto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Diciottenne rientra dalle vacanze in Spagna e viene arrestato all&#8217;aeroporto"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/16\/diciottenne-rientra-dalle-vacanze-in-spagna-e-viene-arrestato-allaeroporto\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/16\/diciottenne-rientra-dalle-vacanze-in-spagna-e-viene-arrestato-allaeroporto\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/16\/diciottenne-rientra-dalle-vacanze-in-spagna-e-viene-arrestato-allaeroporto\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/13162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=13162"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/13162\/revisions"}],"predecessor-version":[{"id":13164,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/13162\/revisions\/13164"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/13163"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=13162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=13162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=13162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}