{"id":1284,"date":"2018-11-08T16:07:38","date_gmt":"2018-11-08T15:07:38","guid":{"rendered":"http:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=1284"},"modified":"2018-11-08T16:44:12","modified_gmt":"2018-11-08T15:44:12","slug":"traffico-di-droga-ad-anagni-i-dettagli-delloperazione-brothers","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/08\/traffico-di-droga-ad-anagni-i-dettagli-delloperazione-brothers\/","title":{"rendered":"Traffico di droga ad Anagni: i dettagli dell&#8217;operazione &#8216;Brothers&#8217;"},"content":{"rendered":"<p>Nelle prime ore di oggi, ad Anagni, nell\u2019ambito di una articolata<strong> indagine<\/strong> denominata <strong>\u201cBrothers\u201d<\/strong>,\u00a0 coordinata dalla\u00a0 dottoressa\u00a0<strong> Barbara Trotta<\/strong>, pubblico ministero della <strong>Procura di Frosinone<\/strong>,\u00a0 i carabinieri della <strong>Compagnia di Anagni<\/strong> hanno eseguito un\u2019ordinanza di custodia cautelare in carcere, emessa dal gip del tribunale di Frosinone, la dottoressa <strong>Ida Loguluso<\/strong>, nei confronti di <strong>sei indagati<\/strong>, gravemente indiziati di <strong>detenzione ai fini di spaccio di sostanze stupefacenti<\/strong> in concorso.<\/p>\n<p>Le indagini svolte dal <strong>Nucleo Operativo e Radiomobile<\/strong> della Compagnia di Anagni, corroborate da attivit\u00e0 tecniche, intercettazioni, pedinamenti e sequestri hanno confermato come gli indagati abbiano tratto profitti esclusivamente dall\u2019attivit\u00e0 di spaccio di cocaina.<\/p>\n<figure id=\"attachment_1296\" aria-describedby=\"caption-attachment-1296\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1296 size-medium\" src=\"http:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/carabinieri-anagni-300x168.jpg\" alt=\"carabinieri anagni arresto cocaina spaccio \" width=\"300\" height=\"168\" \/><figcaption id=\"caption-attachment-1296\" class=\"wp-caption-text\">Un momento dell&#8217;operazione dei carabinieri<\/figcaption><\/figure>\n<h2>Un anno fa l\u2019inizio dell\u2019indagine<\/h2>\n<p>L\u2019attivit\u00e0 info investigativa \u00e8 iniziata nei<strong> primi mesi del 2017<\/strong> e port\u00f2 all\u2019arresto di <strong>Marina Todaro<\/strong>, quarantatreenne sorpresa in piazza Cavour con <strong>27 dosi<\/strong> di cocaina.<\/p>\n<p>La Compagnia di Anagni aveva accertato che nella zona di via San Paolo, nel centro storico anagnino, la Todaro, con il suo convivente <strong>Leonard Kasaj (36 anni)<\/strong>, aveva messo su un\u2019attivit\u00e0 di spaccio. Dalle attivit\u00e0 degli inquirenti, infatti, era stato notato un costante andirivieni di giovani durante tutto l\u2019arco della giornata, i quali, per eludere il controllo dei carabinieri, <strong>nascondevano lo stupefacente presso la cantina di propriet\u00e0 di un&#8217;anziana<\/strong> persona riuscendo facilmente a prelevarlo in corrispondenza di un piccolo foro che si apriva su una rete metallica sovrastante la porta d\u2019ingresso.<\/p>\n<p>I carabinieri accertarono che il canale di approvvigionamento proveniva da cittadini di nazionalit\u00e0 albanese (Cinaj, Tafa e Cepele), tutti residenti nella citt\u00e0 dei papi che, oltre ad usare i pi\u00f9 disparati modi per eludere il controllo dei carabinieri, <strong>nascondevano la cocaina negli anfratti dei muri delle abitazioni<\/strong> del centro storico, stesso modus operandi usato dalla Todaro e da Kasaj.<\/p>\n<h2>La banda usava anche auto &#8216;speciali&#8217;<\/h2>\n<p>Anche le <strong>auto utilizzate<\/strong> dagli indagati risultavano essere state acquistate poich\u00e9 dotate di specifici comparti segreti per occultare lo stupefacente, a ulteriore riprova come le loro attivit\u00e0 illecite erano compiute in modo professionale e con impegno giornaliero di tutte le loro energie. Inoltre, sono stati anche effettuati, al fine<strong> accertamenti patrimoniali<\/strong> che hanno consentito di apprezzare le disponibilit\u00e0 economiche e il flusso di denaro transitato sui rapporti finanziari della coppia Todaro\/Kasaj in pi\u00f9 di 5 mesi (<strong>flussi di denaro mediamente di 2.600 euro al mese<\/strong>) , fornendo uno spaccato della floridit\u00e0 dei loro traffici.<\/p>\n<figure id=\"attachment_1298\" aria-describedby=\"caption-attachment-1298\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1298 size-medium\" src=\"http:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/carabinieri-anagni-arresto-300x169.jpg\" alt=\"arresti cocaina droga anagni frosinone ciociaria\" width=\"300\" height=\"169\" \/><figcaption id=\"caption-attachment-1298\" class=\"wp-caption-text\">Uno dei sei arrestati nell&#8217;operazione &#8216;Brothers&#8217;<\/figcaption><\/figure>\n<h2>Gli esiti dell\u2019indagine: gli arresti e le accuse<\/h2>\n<p>Gli elementi probatori raccolti hanno permesso di\u00a0 arrestare\u00a0 3 persone, tra cui \u00a0Anton Feza, sorpreso a cedere <strong>1,7 grammi<\/strong> a un giovane di Anagni dietro il compenso di euro 100,00 (e la successiva perquisizione effettuata nella cantina risultata nella sua disponibilit\u00e0\u00a0 permise il rinvenimento di ulteriori 9 grammi di cocaina). In manette sono finiti anche Leonard Kasaj (trovato in possesso di<strong> 6 grammi di cocaina<\/strong>)\u00a0 e di Marina Todaro, per la detenzione di <strong>10 grammi di cocaina<\/strong> appena acquistata dai propri fornitori. Inoltre, sono stati accertati almeno <strong>80 episodi di cessioni<\/strong> di cocaina, per un totale di <strong>150 grammi<\/strong> e un controvalore di<strong> 23.000 euro<\/strong> per lo spaccio al dettaglio.<\/p>\n<p>Agli arrestati viene contestato il reato continuato e in concorso nella detenzione ai fini di spaccio di sostanze stupefacenti e, in particolare, con il provvedimento odierno per Marina Todaro, Leonard Kasaj, Mezin Cinaj (albanese di 36 anni) e <strong>Anton Feza<\/strong> (43 anni) \u00e8 stata disposta la misura cautelare della custodia in carcere. Per <strong>Perparim Tafa<\/strong> (42 anni) e <strong>Agim Cepel<\/strong> di 43 e sono, invece, scattati i domiciliari.<\/p>\n<p>Inoltre,\u00a0 sono stati indagati a piede libero un 35enne albanese, espulso a marzo dall\u2019Italia per motivi di sicurezza, e un 34enne albanese. Sono state anche <strong>segnalati alla Prefettura di Frosinone sei assuntori di sostanza stupefacente<\/strong> per uso personale non terapeutico e sequestrati 45 grammi di cocaina.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nelle prime ore di oggi, ad Anagni, nell\u2019ambito di una articolata indagine denominata \u201cBrothers\u201d,\u00a0 coordinata dalla\u00a0 dottoressa\u00a0 Barbara Trotta, pubblico<\/p>\n","protected":false},"author":7,"featured_media":1291,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,2],"tags":[441,440,463,90,94,189,93,462,442,461],"class_list":["post-1284","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-cronaca","tag-anagni","tag-arresti","tag-brothers","tag-carabinieri","tag-ciociaria","tag-droga","tag-frosinone","tag-operazione","tag-spaccio","tag-traffico"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Traffico di droga ad Anagni: i dettagli dell&#039;operazione &#039;Brothers&#039; - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/08\/traffico-di-droga-ad-anagni-i-dettagli-delloperazione-brothers\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Traffico di droga ad Anagni: i dettagli dell&#039;operazione &#039;Brothers&#039;\" \/>\n<meta property=\"og:description\" content=\"Nelle prime ore di oggi, ad Anagni, nell\u2019ambito di una articolata indagine denominata \u201cBrothers\u201d,\u00a0 coordinata dalla\u00a0 dottoressa\u00a0 Barbara Trotta, pubblico\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/08\/traffico-di-droga-ad-anagni-i-dettagli-delloperazione-brothers\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"http:\/\/www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-08T15:07:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-08T15:44:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/carabinieri-arresti-anagni1-e1541689592909.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"366\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Giulia Abbruzzese\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giulia Abbruzzese\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/08\\\/traffico-di-droga-ad-anagni-i-dettagli-delloperazione-brothers\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/08\\\/traffico-di-droga-ad-anagni-i-dettagli-delloperazione-brothers\\\/\"},\"author\":{\"name\":\"Giulia Abbruzzese\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/58bf90a6d70d54d2f0db83bc3d580351\"},\"headline\":\"Traffico di droga ad Anagni: i dettagli dell&#8217;operazione &#8216;Brothers&#8217;\",\"datePublished\":\"2018-11-08T15:07:38+00:00\",\"dateModified\":\"2018-11-08T15:44:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/08\\\/traffico-di-droga-ad-anagni-i-dettagli-delloperazione-brothers\\\/\"},\"wordCount\":645,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/08\\\/traffico-di-droga-ad-anagni-i-dettagli-delloperazione-brothers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/carabinieri-arresti-anagni1-e1541689592909.jpg\",\"keywords\":[\"anagni\",\"arresti\",\"brothers\",\"carabinieri\",\"Ciociaria\",\"droga\",\"Frosinone\",\"operazione\",\"spaccio\",\"traffico\"],\"articleSection\":[\"*SLIDE*\",\"Cronaca\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/08\\\/traffico-di-droga-ad-anagni-i-dettagli-delloperazione-brothers\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/08\\\/traffico-di-droga-ad-anagni-i-dettagli-delloperazione-brothers\\\/\",\"name\":\"Traffico di droga ad Anagni: i dettagli dell'operazione 'Brothers' - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/08\\\/traffico-di-droga-ad-anagni-i-dettagli-delloperazione-brothers\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/08\\\/traffico-di-droga-ad-anagni-i-dettagli-delloperazione-brothers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/carabinieri-arresti-anagni1-e1541689592909.jpg\",\"datePublished\":\"2018-11-08T15:07:38+00:00\",\"dateModified\":\"2018-11-08T15:44:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/08\\\/traffico-di-droga-ad-anagni-i-dettagli-delloperazione-brothers\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/08\\\/traffico-di-droga-ad-anagni-i-dettagli-delloperazione-brothers\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/08\\\/traffico-di-droga-ad-anagni-i-dettagli-delloperazione-brothers\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/carabinieri-arresti-anagni1-e1541689592909.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/carabinieri-arresti-anagni1-e1541689592909.jpg\",\"width\":632,\"height\":366,\"caption\":\"Gli arrestati nell'operazione \\\"Brothers\\\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/08\\\/traffico-di-droga-ad-anagni-i-dettagli-delloperazione-brothers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Traffico di droga ad Anagni: i dettagli dell&#8217;operazione &#8216;Brothers&#8217;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/08\\\/traffico-di-droga-ad-anagni-i-dettagli-delloperazione-brothers\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/08\\\/traffico-di-droga-ad-anagni-i-dettagli-delloperazione-brothers\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/58bf90a6d70d54d2f0db83bc3d580351\",\"name\":\"Giulia Abbruzzese\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff9b2f7c2c6d1751e3de0056e95b7af4a6c366bf539cdd639aac86cd1908507f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff9b2f7c2c6d1751e3de0056e95b7af4a6c366bf539cdd639aac86cd1908507f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff9b2f7c2c6d1751e3de0056e95b7af4a6c366bf539cdd639aac86cd1908507f?s=96&d=mm&r=g\",\"caption\":\"Giulia Abbruzzese\"},\"description\":\"Giornalista dei quotidiani online \\\"Il Corriere della Provincia\\\" e \\\"TuNews24.it\\\" e del settimanale \\\"Tu News\\\", ha collaborato anche con il mensile \\\"Qui Magazine\\\" oltre che con il settimanale \\\"Qui Sette\\\"; \u00e8 stata inoltre Caposervizio del quotidiano \\\"\u2018Ciociaria Oggi\\\" e Caporedattore de \\\"Il quotidiano della Ciociaria\\\". Collabora con la rivista \\\"Chic Style\\\".\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"http:\\\/\\\/www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/giulia-abbruzzese\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/08\\\/traffico-di-droga-ad-anagni-i-dettagli-delloperazione-brothers\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Traffico di droga ad Anagni: i dettagli dell'operazione 'Brothers' - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/08\/traffico-di-droga-ad-anagni-i-dettagli-delloperazione-brothers\/","og_locale":"it_IT","og_type":"article","og_title":"Traffico di droga ad Anagni: i dettagli dell'operazione 'Brothers'","og_description":"Nelle prime ore di oggi, ad Anagni, nell\u2019ambito di una articolata indagine denominata \u201cBrothers\u201d,\u00a0 coordinata dalla\u00a0 dottoressa\u00a0 Barbara Trotta, pubblico","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/08\/traffico-di-droga-ad-anagni-i-dettagli-delloperazione-brothers\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"http:\/\/www.facebook.com\/tunews24","article_published_time":"2018-11-08T15:07:38+00:00","article_modified_time":"2018-11-08T15:44:12+00:00","og_image":[{"width":632,"height":366,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/carabinieri-arresti-anagni1-e1541689592909.jpg","type":"image\/jpeg"}],"author":"Giulia Abbruzzese","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Giulia Abbruzzese","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/08\/traffico-di-droga-ad-anagni-i-dettagli-delloperazione-brothers\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/08\/traffico-di-droga-ad-anagni-i-dettagli-delloperazione-brothers\/"},"author":{"name":"Giulia Abbruzzese","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/58bf90a6d70d54d2f0db83bc3d580351"},"headline":"Traffico di droga ad Anagni: i dettagli dell&#8217;operazione &#8216;Brothers&#8217;","datePublished":"2018-11-08T15:07:38+00:00","dateModified":"2018-11-08T15:44:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/08\/traffico-di-droga-ad-anagni-i-dettagli-delloperazione-brothers\/"},"wordCount":645,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/08\/traffico-di-droga-ad-anagni-i-dettagli-delloperazione-brothers\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/carabinieri-arresti-anagni1-e1541689592909.jpg","keywords":["anagni","arresti","brothers","carabinieri","Ciociaria","droga","Frosinone","operazione","spaccio","traffico"],"articleSection":["*SLIDE*","Cronaca"],"inLanguage":"it-IT","copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/08\/traffico-di-droga-ad-anagni-i-dettagli-delloperazione-brothers\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/08\/traffico-di-droga-ad-anagni-i-dettagli-delloperazione-brothers\/","name":"Traffico di droga ad Anagni: i dettagli dell'operazione 'Brothers' - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/08\/traffico-di-droga-ad-anagni-i-dettagli-delloperazione-brothers\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/08\/traffico-di-droga-ad-anagni-i-dettagli-delloperazione-brothers\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/carabinieri-arresti-anagni1-e1541689592909.jpg","datePublished":"2018-11-08T15:07:38+00:00","dateModified":"2018-11-08T15:44:12+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/08\/traffico-di-droga-ad-anagni-i-dettagli-delloperazione-brothers\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/08\/traffico-di-droga-ad-anagni-i-dettagli-delloperazione-brothers\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/08\/traffico-di-droga-ad-anagni-i-dettagli-delloperazione-brothers\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/carabinieri-arresti-anagni1-e1541689592909.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/carabinieri-arresti-anagni1-e1541689592909.jpg","width":632,"height":366,"caption":"Gli arrestati nell'operazione \"Brothers\""},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/08\/traffico-di-droga-ad-anagni-i-dettagli-delloperazione-brothers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Traffico di droga ad Anagni: i dettagli dell&#8217;operazione &#8216;Brothers&#8217;"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/08\/traffico-di-droga-ad-anagni-i-dettagli-delloperazione-brothers\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/08\/traffico-di-droga-ad-anagni-i-dettagli-delloperazione-brothers\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/58bf90a6d70d54d2f0db83bc3d580351","name":"Giulia Abbruzzese","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ff9b2f7c2c6d1751e3de0056e95b7af4a6c366bf539cdd639aac86cd1908507f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ff9b2f7c2c6d1751e3de0056e95b7af4a6c366bf539cdd639aac86cd1908507f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ff9b2f7c2c6d1751e3de0056e95b7af4a6c366bf539cdd639aac86cd1908507f?s=96&d=mm&r=g","caption":"Giulia Abbruzzese"},"description":"Giornalista dei quotidiani online \"Il Corriere della Provincia\" e \"TuNews24.it\" e del settimanale \"Tu News\", ha collaborato anche con il mensile \"Qui Magazine\" oltre che con il settimanale \"Qui Sette\"; \u00e8 stata inoltre Caposervizio del quotidiano \"\u2018Ciociaria Oggi\" e Caporedattore de \"Il quotidiano della Ciociaria\". Collabora con la rivista \"Chic Style\".","sameAs":["http:\/\/www.tunews24.it","http:\/\/www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/giulia-abbruzzese\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/08\/traffico-di-droga-ad-anagni-i-dettagli-delloperazione-brothers\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/1284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=1284"}],"version-history":[{"count":4,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/1284\/revisions"}],"predecessor-version":[{"id":1299,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/1284\/revisions\/1299"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/1291"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=1284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=1284"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=1284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}