{"id":12538,"date":"2019-06-05T18:47:38","date_gmt":"2019-06-05T16:47:38","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=12538"},"modified":"2019-06-06T16:42:40","modified_gmt":"2019-06-06T14:42:40","slug":"scoperta-a-frosinone-la-truffa-del-noleggio-di-auto-di-lusso","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/05\/scoperta-a-frosinone-la-truffa-del-noleggio-di-auto-di-lusso\/","title":{"rendered":"Scoperta a Frosinone la truffa del noleggio di auto di lusso"},"content":{"rendered":"<p>Un <strong>napoletano di 43 anni<\/strong> e uno <strong>studente di Alatri, classe 1998<\/strong>. Sono loro, secondo l\u2019indagine condotta dai carabinieri del Nucleo operativo e radiomobile di Frosinone, <strong>i responsabili di una truffa<\/strong> nella quale sono cadute decine di persone.<\/p>\n<p>Nella giornata odierna, infatti, i militari del Norm, a conclusione di un\u2019articolata attivit\u00e0 d&#8217;indagine, intrapresa a seguito della denuncia\/querela presentata negli uffici del Comando,<strong> hanno denunciato in stato di libert\u00e0 alla Procura della Repubblica<\/strong> presso il tribunale di Frosinone <strong>A.E. nato a Napoli nel 1976<\/strong>, nullafacente e con precedenti di polizia per reati contro il patrimonio e <strong>C.R., studente ventunenne di Alatri<\/strong>.<\/p>\n<h2>Le accuse<\/h2>\n<p>Secondo quanto accertato dai carabinieri, i due, lo scorso 13 aprile, hanno noleggiato da una societ\u00e0 del capoluogo una Jaguar f pace omettendo di restituirla al termine del periodo previsto.<\/p>\n<p>A seguito di un servizio appositamente predisposto, <strong>i militari hanno rintracciato i due mentre, in un\u2019altra societ\u00e0 di autonoleggio, stavano per affittare una BMW S3<\/strong>, la consegna della quale \u00e8 stata impedita grazie all\u2019intervento dei carabinieri.<\/p>\n<h2>La perquisizione<\/h2>\n<p>La successiva perquisizione domiciliare, effettuata nell\u2019abitazione utilizzata dai due e per la quale la proprietaria aveva formalizzato una denuncia-querela per il mancato pagamento del canone di locazione, <strong>ha consentito ai militari di trovare le chiavi e la carta di circolazione della Jaguar f pace<\/strong>, oltre a numerose carte di pagamento e contratti di noleggio di automobili, per i quali sono in corso ulteriori approfondimenti per accertarne autenticit\u00e0 e provenienza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un napoletano di 43 anni e uno studente di Alatri, classe 1998. Sono loro, secondo l\u2019indagine condotta dai carabinieri del<\/p>\n","protected":false},"author":18,"featured_media":12539,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,2],"tags":[368,4491,90,93,4489,4492,4413,4490,243],"class_list":["post-12538","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-cronaca","tag-alatri","tag-canone","tag-carabinieri","tag-frosinone","tag-jaguar-f-pace","tag-macchine","tag-noleggio","tag-studente","tag-truffa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Scoperta a Frosinone la truffa del noleggio di auto di lusso - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"I carabinieri del Norm di Frosinone hanno scoperto una truffa nel settore del noleggio di auto di lusso: denunciati un napoletano e uno studente di Alatri\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/05\/scoperta-a-frosinone-la-truffa-del-noleggio-di-auto-di-lusso\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Scoperta a Frosinone la truffa del noleggio di auto di lusso\" \/>\n<meta property=\"og:description\" content=\"I carabinieri del Norm di Frosinone hanno scoperto una truffa nel settore del noleggio di auto di lusso: denunciati un napoletano e uno studente di Alatri\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/05\/scoperta-a-frosinone-la-truffa-del-noleggio-di-auto-di-lusso\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-05T16:47:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-06T14:42:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/jaguar-noleggio-truffa-e1559753180627.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"421\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/05\\\/scoperta-a-frosinone-la-truffa-del-noleggio-di-auto-di-lusso\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/05\\\/scoperta-a-frosinone-la-truffa-del-noleggio-di-auto-di-lusso\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Scoperta a Frosinone la truffa del noleggio di auto di lusso\",\"datePublished\":\"2019-06-05T16:47:38+00:00\",\"dateModified\":\"2019-06-06T14:42:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/05\\\/scoperta-a-frosinone-la-truffa-del-noleggio-di-auto-di-lusso\\\/\"},\"wordCount\":254,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/05\\\/scoperta-a-frosinone-la-truffa-del-noleggio-di-auto-di-lusso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/jaguar-noleggio-truffa-e1559753180627.jpg\",\"keywords\":[\"alatri\",\"canone\",\"carabinieri\",\"Frosinone\",\"jaguar f pace\",\"macchine\",\"noleggio\",\"studente\",\"truffa\"],\"articleSection\":[\"*SLIDE*\",\"Cronaca\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/05\\\/scoperta-a-frosinone-la-truffa-del-noleggio-di-auto-di-lusso\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/05\\\/scoperta-a-frosinone-la-truffa-del-noleggio-di-auto-di-lusso\\\/\",\"name\":\"Scoperta a Frosinone la truffa del noleggio di auto di lusso - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/05\\\/scoperta-a-frosinone-la-truffa-del-noleggio-di-auto-di-lusso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/05\\\/scoperta-a-frosinone-la-truffa-del-noleggio-di-auto-di-lusso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/jaguar-noleggio-truffa-e1559753180627.jpg\",\"datePublished\":\"2019-06-05T16:47:38+00:00\",\"dateModified\":\"2019-06-06T14:42:40+00:00\",\"description\":\"I carabinieri del Norm di Frosinone hanno scoperto una truffa nel settore del noleggio di auto di lusso: denunciati un napoletano e uno studente di Alatri\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/05\\\/scoperta-a-frosinone-la-truffa-del-noleggio-di-auto-di-lusso\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/05\\\/scoperta-a-frosinone-la-truffa-del-noleggio-di-auto-di-lusso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/05\\\/scoperta-a-frosinone-la-truffa-del-noleggio-di-auto-di-lusso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/jaguar-noleggio-truffa-e1559753180627.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/jaguar-noleggio-truffa-e1559753180627.jpg\",\"width\":632,\"height\":421,\"caption\":\"Jaguar f pace\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/05\\\/scoperta-a-frosinone-la-truffa-del-noleggio-di-auto-di-lusso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Scoperta a Frosinone la truffa del noleggio di auto di lusso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/05\\\/scoperta-a-frosinone-la-truffa-del-noleggio-di-auto-di-lusso\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/05\\\/scoperta-a-frosinone-la-truffa-del-noleggio-di-auto-di-lusso\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/05\\\/scoperta-a-frosinone-la-truffa-del-noleggio-di-auto-di-lusso\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Scoperta a Frosinone la truffa del noleggio di auto di lusso - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"I carabinieri del Norm di Frosinone hanno scoperto una truffa nel settore del noleggio di auto di lusso: denunciati un napoletano e uno studente di Alatri","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/05\/scoperta-a-frosinone-la-truffa-del-noleggio-di-auto-di-lusso\/","og_locale":"it_IT","og_type":"article","og_title":"Scoperta a Frosinone la truffa del noleggio di auto di lusso","og_description":"I carabinieri del Norm di Frosinone hanno scoperto una truffa nel settore del noleggio di auto di lusso: denunciati un napoletano e uno studente di Alatri","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/05\/scoperta-a-frosinone-la-truffa-del-noleggio-di-auto-di-lusso\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-06-05T16:47:38+00:00","article_modified_time":"2019-06-06T14:42:40+00:00","og_image":[{"width":632,"height":421,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/jaguar-noleggio-truffa-e1559753180627.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/05\/scoperta-a-frosinone-la-truffa-del-noleggio-di-auto-di-lusso\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/05\/scoperta-a-frosinone-la-truffa-del-noleggio-di-auto-di-lusso\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Scoperta a Frosinone la truffa del noleggio di auto di lusso","datePublished":"2019-06-05T16:47:38+00:00","dateModified":"2019-06-06T14:42:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/05\/scoperta-a-frosinone-la-truffa-del-noleggio-di-auto-di-lusso\/"},"wordCount":254,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/05\/scoperta-a-frosinone-la-truffa-del-noleggio-di-auto-di-lusso\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/jaguar-noleggio-truffa-e1559753180627.jpg","keywords":["alatri","canone","carabinieri","Frosinone","jaguar f pace","macchine","noleggio","studente","truffa"],"articleSection":["*SLIDE*","Cronaca"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/05\/scoperta-a-frosinone-la-truffa-del-noleggio-di-auto-di-lusso\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/05\/scoperta-a-frosinone-la-truffa-del-noleggio-di-auto-di-lusso\/","name":"Scoperta a Frosinone la truffa del noleggio di auto di lusso - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/05\/scoperta-a-frosinone-la-truffa-del-noleggio-di-auto-di-lusso\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/05\/scoperta-a-frosinone-la-truffa-del-noleggio-di-auto-di-lusso\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/jaguar-noleggio-truffa-e1559753180627.jpg","datePublished":"2019-06-05T16:47:38+00:00","dateModified":"2019-06-06T14:42:40+00:00","description":"I carabinieri del Norm di Frosinone hanno scoperto una truffa nel settore del noleggio di auto di lusso: denunciati un napoletano e uno studente di Alatri","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/05\/scoperta-a-frosinone-la-truffa-del-noleggio-di-auto-di-lusso\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/05\/scoperta-a-frosinone-la-truffa-del-noleggio-di-auto-di-lusso\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/05\/scoperta-a-frosinone-la-truffa-del-noleggio-di-auto-di-lusso\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/jaguar-noleggio-truffa-e1559753180627.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/jaguar-noleggio-truffa-e1559753180627.jpg","width":632,"height":421,"caption":"Jaguar f pace"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/05\/scoperta-a-frosinone-la-truffa-del-noleggio-di-auto-di-lusso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Scoperta a Frosinone la truffa del noleggio di auto di lusso"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/05\/scoperta-a-frosinone-la-truffa-del-noleggio-di-auto-di-lusso\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/05\/scoperta-a-frosinone-la-truffa-del-noleggio-di-auto-di-lusso\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/05\/scoperta-a-frosinone-la-truffa-del-noleggio-di-auto-di-lusso\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/12538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=12538"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/12538\/revisions"}],"predecessor-version":[{"id":12540,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/12538\/revisions\/12540"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/12539"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=12538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=12538"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=12538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}