{"id":12506,"date":"2019-06-08T08:55:35","date_gmt":"2019-06-08T06:55:35","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=12506"},"modified":"2019-06-09T06:46:32","modified_gmt":"2019-06-09T04:46:32","slug":"villa-gasbarra-apre-ai-cittadini-sabato-linaugurazione","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/08\/villa-gasbarra-apre-ai-cittadini-sabato-linaugurazione\/","title":{"rendered":"Ferentino, Villa Gasbarra apre ai cittadini"},"content":{"rendered":"<p><strong>La bellissima Villa Gasbarra<\/strong>, uno dei gioielli del patrimonio architettonico di Ferentino torna a disposizione dei cittadini, insieme al suo straordinario giardino. Oggi, 8 giugno, alle ore 17,30, con una cerimonia pubblica verr\u00e0 inaugurata dopo i lavori che l\u2019hanno restituita al suo splendore.<\/p>\n<h2>Il programma<\/h2>\n<p>Gi\u00e0 il programma della cerimonia fa intravedere le enormi potenzialit\u00e0 della struttura che servir\u00e0 a valorizzare l\u2019offerta socio culturale della citt\u00e0. E\u2019, infatti, prevista la mostra personale dell\u2019artista Domenico Cialone e un aperitivo musicale, con Fabio Caputo, Valeria Minicilli, Malvina Picariello, Luigi Bartolini, Manuel Caruso, Fabrizio Bartolini.<\/p>\n<h2>Valorizzazione del patrimonio<\/h2>\n<p>I lavori realizzati dal Comune, attraverso un finanziamento regionale, hanno permesso il completamento, il restauro e il risanamento conservativo della Villa, nel rispetto dell\u2019originalit\u00e0 e delle peculiarit\u00e0 architettoniche. Insomma, un ulteriore lavoro che si inserisce negli obiettivi da sempre perseguiti dall\u2019amministrazione Pompeo: valorizzazione del patrimonio cittadino, attenzione all\u2019estetica e al decoro, servizi. Tutti aspetti che gli interventi su Villa Gasbarra hanno conseguito.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_11881\" aria-describedby=\"caption-attachment-11881\" style=\"width: 632px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-11881\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/antonio-pompeo-sindaco-ferentino.jpg\" alt=\"antonio pompeo sindaco ferentino\" width=\"632\" height=\"484\" \/><figcaption id=\"caption-attachment-11881\" class=\"wp-caption-text\">Antonio Pompeo<\/figcaption><\/figure>\n<h2>L&#8217;intervento del sindaco Pompeo<\/h2>\n<p>\u201cVilla Gasbarra \u00e8 un luogo caro a tutti i cittadini di Ferentino \u2013 ha dichiarato il sindaco Antonio Pompeo \u2013 Per questo abbiamo voluto con determinazione riconsegnarla alla nostra comunit\u00e0. <strong>Pi\u00f9 bella e sicura, una struttura in pi\u00f9 per attivit\u00e0 culturali e di natura sociale<\/strong>, che offre una risposta reale alla volont\u00e0 di aumentare i luoghi di condivisione, di incontro, di iniziative e anche di servizi alla persona. Senza contare il belllissimo giardino. L\u2019amministrazione comunale, come dimostrano il parcheggio della Casa della salute, Villa Gasbarra, gli incentivi per le attivit\u00e0 commerciali e artigiane, l\u2019avvio del ricco cartellone di iniziative estive, \u00e8 come sempre in piena attivit\u00e0, al servizio della citt\u00e0 e della sua crescita\u201d.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-12507\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/MANIFESTO-VILLA-GASBARRA-1.jpg\" alt=\"\" width=\"632\" height=\"901\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/MANIFESTO-VILLA-GASBARRA-1.jpg 493w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/MANIFESTO-VILLA-GASBARRA-1-210x300.jpg 210w\" sizes=\"auto, (max-width: 632px) 100vw, 632px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La bellissima Villa Gasbarra, uno dei gioielli del patrimonio architettonico di Ferentino torna a disposizione dei cittadini, insieme al suo<\/p>\n","protected":false},"author":18,"featured_media":12508,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[43],"tags":[842,4481,92,4482,2360],"class_list":["post-12506","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-turismo","tag-antonio-pompeo","tag-domenmico-cialone","tag-ferentino","tag-inagurazione","tag-villa-gasbarra"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ferentino, Villa Gasbarra apre ai cittadini - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Sabato prossimo, 8 giugno, alle ore 17,30, con una cerimonia pubblica verr\u00e0 inaugurata dopo i lavori che l\u2019hanno restituita al suo splendore.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/08\/villa-gasbarra-apre-ai-cittadini-sabato-linaugurazione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ferentino, Villa Gasbarra apre ai cittadini\" \/>\n<meta property=\"og:description\" content=\"Sabato prossimo, 8 giugno, alle ore 17,30, con una cerimonia pubblica verr\u00e0 inaugurata dopo i lavori che l\u2019hanno restituita al suo splendore.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/08\/villa-gasbarra-apre-ai-cittadini-sabato-linaugurazione\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-08T06:55:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-09T04:46:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/villa-gasbarra-ferentino-il-corriere-della-provincia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"683\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/08\\\/villa-gasbarra-apre-ai-cittadini-sabato-linaugurazione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/08\\\/villa-gasbarra-apre-ai-cittadini-sabato-linaugurazione\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Ferentino, Villa Gasbarra apre ai cittadini\",\"datePublished\":\"2019-06-08T06:55:35+00:00\",\"dateModified\":\"2019-06-09T04:46:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/08\\\/villa-gasbarra-apre-ai-cittadini-sabato-linaugurazione\\\/\"},\"wordCount\":294,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/08\\\/villa-gasbarra-apre-ai-cittadini-sabato-linaugurazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/villa-gasbarra-ferentino-il-corriere-della-provincia.jpg\",\"keywords\":[\"antonio pompeo\",\"Domenmico Cialone\",\"ferentino\",\"Inagurazione\",\"villa gasbarra\"],\"articleSection\":[\"Turismo\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/08\\\/villa-gasbarra-apre-ai-cittadini-sabato-linaugurazione\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/08\\\/villa-gasbarra-apre-ai-cittadini-sabato-linaugurazione\\\/\",\"name\":\"Ferentino, Villa Gasbarra apre ai cittadini - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/08\\\/villa-gasbarra-apre-ai-cittadini-sabato-linaugurazione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/08\\\/villa-gasbarra-apre-ai-cittadini-sabato-linaugurazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/villa-gasbarra-ferentino-il-corriere-della-provincia.jpg\",\"datePublished\":\"2019-06-08T06:55:35+00:00\",\"dateModified\":\"2019-06-09T04:46:32+00:00\",\"description\":\"Sabato prossimo, 8 giugno, alle ore 17,30, con una cerimonia pubblica verr\u00e0 inaugurata dopo i lavori che l\u2019hanno restituita al suo splendore.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/08\\\/villa-gasbarra-apre-ai-cittadini-sabato-linaugurazione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/08\\\/villa-gasbarra-apre-ai-cittadini-sabato-linaugurazione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/08\\\/villa-gasbarra-apre-ai-cittadini-sabato-linaugurazione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/villa-gasbarra-ferentino-il-corriere-della-provincia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/villa-gasbarra-ferentino-il-corriere-della-provincia.jpg\",\"width\":683,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/08\\\/villa-gasbarra-apre-ai-cittadini-sabato-linaugurazione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ferentino, Villa Gasbarra apre ai cittadini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/08\\\/villa-gasbarra-apre-ai-cittadini-sabato-linaugurazione\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/08\\\/villa-gasbarra-apre-ai-cittadini-sabato-linaugurazione\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/08\\\/villa-gasbarra-apre-ai-cittadini-sabato-linaugurazione\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ferentino, Villa Gasbarra apre ai cittadini - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Sabato prossimo, 8 giugno, alle ore 17,30, con una cerimonia pubblica verr\u00e0 inaugurata dopo i lavori che l\u2019hanno restituita al suo splendore.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/08\/villa-gasbarra-apre-ai-cittadini-sabato-linaugurazione\/","og_locale":"it_IT","og_type":"article","og_title":"Ferentino, Villa Gasbarra apre ai cittadini","og_description":"Sabato prossimo, 8 giugno, alle ore 17,30, con una cerimonia pubblica verr\u00e0 inaugurata dopo i lavori che l\u2019hanno restituita al suo splendore.","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/08\/villa-gasbarra-apre-ai-cittadini-sabato-linaugurazione\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-06-08T06:55:35+00:00","article_modified_time":"2019-06-09T04:46:32+00:00","og_image":[{"width":683,"height":525,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/villa-gasbarra-ferentino-il-corriere-della-provincia.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/08\/villa-gasbarra-apre-ai-cittadini-sabato-linaugurazione\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/08\/villa-gasbarra-apre-ai-cittadini-sabato-linaugurazione\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Ferentino, Villa Gasbarra apre ai cittadini","datePublished":"2019-06-08T06:55:35+00:00","dateModified":"2019-06-09T04:46:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/08\/villa-gasbarra-apre-ai-cittadini-sabato-linaugurazione\/"},"wordCount":294,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/08\/villa-gasbarra-apre-ai-cittadini-sabato-linaugurazione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/villa-gasbarra-ferentino-il-corriere-della-provincia.jpg","keywords":["antonio pompeo","Domenmico Cialone","ferentino","Inagurazione","villa gasbarra"],"articleSection":["Turismo"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/08\/villa-gasbarra-apre-ai-cittadini-sabato-linaugurazione\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/08\/villa-gasbarra-apre-ai-cittadini-sabato-linaugurazione\/","name":"Ferentino, Villa Gasbarra apre ai cittadini - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/08\/villa-gasbarra-apre-ai-cittadini-sabato-linaugurazione\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/08\/villa-gasbarra-apre-ai-cittadini-sabato-linaugurazione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/villa-gasbarra-ferentino-il-corriere-della-provincia.jpg","datePublished":"2019-06-08T06:55:35+00:00","dateModified":"2019-06-09T04:46:32+00:00","description":"Sabato prossimo, 8 giugno, alle ore 17,30, con una cerimonia pubblica verr\u00e0 inaugurata dopo i lavori che l\u2019hanno restituita al suo splendore.","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/08\/villa-gasbarra-apre-ai-cittadini-sabato-linaugurazione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/08\/villa-gasbarra-apre-ai-cittadini-sabato-linaugurazione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/08\/villa-gasbarra-apre-ai-cittadini-sabato-linaugurazione\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/villa-gasbarra-ferentino-il-corriere-della-provincia.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/villa-gasbarra-ferentino-il-corriere-della-provincia.jpg","width":683,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/08\/villa-gasbarra-apre-ai-cittadini-sabato-linaugurazione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Ferentino, Villa Gasbarra apre ai cittadini"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/08\/villa-gasbarra-apre-ai-cittadini-sabato-linaugurazione\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/08\/villa-gasbarra-apre-ai-cittadini-sabato-linaugurazione\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/08\/villa-gasbarra-apre-ai-cittadini-sabato-linaugurazione\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/12506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=12506"}],"version-history":[{"count":5,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/12506\/revisions"}],"predecessor-version":[{"id":12695,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/12506\/revisions\/12695"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/12508"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=12506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=12506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=12506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}