{"id":12358,"date":"2019-06-01T14:58:26","date_gmt":"2019-06-01T12:58:26","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=12358"},"modified":"2019-06-01T15:06:07","modified_gmt":"2019-06-01T13:06:07","slug":"isola-del-liri-scomparsa-ex-sindaco-bartolomucci-il-cordoglio-di-quadrini-e-dellamministrazione","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/01\/isola-del-liri-scomparsa-ex-sindaco-bartolomucci-il-cordoglio-di-quadrini-e-dellamministrazione\/","title":{"rendered":"Scomparsa ex sindaco Bartolomucci, l&#8217;amministrazione Quadrini lo ricorda"},"content":{"rendered":"<p>&#8220;<strong>Enzio Bartolomucci<\/strong> \u00e8 stato primo cittadino dal 1978 al 1985, un periodo molto lungo, considerando anche che il sindaco era espressione del Consiglio Comunale, e non eletto direttamente dai cittadini&#8221;. Cos\u00ec lo ricordano il sindaco Massimiliano Quadrini, l&#8217;Amministrazione del Comune di Isola del Liri e il gi\u00e0 sindaco Vincenzo Quadrini.<\/p>\n<h2>Tante le opere realizzate<\/h2>\n<p>&#8220;Un grande sindaco, che <strong>realizz\u00f2 il nuovo ponte sul Liri a Pirandello<\/strong>, che inaugur\u00f2 l\u2019impianto di metanizzazione, che complet\u00f2 l\u2019insediamento a San Carlo, che diede vita a un fantastico evento di danza sotto la Cascata, con un palco fatto realizzare direttamente nel letto del fiume&#8221;.<\/p>\n<h2>Radicato nel territorio<\/h2>\n<p>&#8220;Un primo o cittadino \u00a0molto popolare, profondamente radicato nel territorio, impegnato nel sociale e nello sport, anima dell\u2019Asaci e poi della Soms, con la quale realizzav<strong>a il &#8216;Maggio Isolano&#8217;<\/strong>.\u00a0Ha onorato sino alla fine la sua citt\u00e0, che dovr\u00e0 adesso trovare il modo di coltivarne il ricordo e continuarne l\u2019opera.\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Enzio Bartolomucci \u00e8 stato primo cittadino dal 1978 al 1985, un periodo molto lungo, considerando anche che il sindaco era<\/p>\n","protected":false},"author":18,"featured_media":12359,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,1],"tags":[4435,260,1775,1921],"class_list":["post-12358","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-news","tag-enzoo-martolomucci","tag-isola-del-liri","tag-massimiliano-quadrini","tag-vincenzo-quadrini"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Scomparsa ex sindaco Bartolomucci, l&#039;amministrazione Quadrini lo ricorda - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Un primo o cittadino \u00a0molto popolare, profondamente radicato nel territorio, impegnato nel sociale e nello sport, anima dell\u2019Asaci\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/01\/isola-del-liri-scomparsa-ex-sindaco-bartolomucci-il-cordoglio-di-quadrini-e-dellamministrazione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Scomparsa ex sindaco Bartolomucci, l&#039;amministrazione Quadrini lo ricorda\" \/>\n<meta property=\"og:description\" content=\"Un primo o cittadino \u00a0molto popolare, profondamente radicato nel territorio, impegnato nel sociale e nello sport, anima dell\u2019Asaci\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/01\/isola-del-liri-scomparsa-ex-sindaco-bartolomucci-il-cordoglio-di-quadrini-e-dellamministrazione\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-01T12:58:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-01T13:06:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/bartolomucci.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"636\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/01\\\/isola-del-liri-scomparsa-ex-sindaco-bartolomucci-il-cordoglio-di-quadrini-e-dellamministrazione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/01\\\/isola-del-liri-scomparsa-ex-sindaco-bartolomucci-il-cordoglio-di-quadrini-e-dellamministrazione\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Scomparsa ex sindaco Bartolomucci, l&#8217;amministrazione Quadrini lo ricorda\",\"datePublished\":\"2019-06-01T12:58:26+00:00\",\"dateModified\":\"2019-06-01T13:06:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/01\\\/isola-del-liri-scomparsa-ex-sindaco-bartolomucci-il-cordoglio-di-quadrini-e-dellamministrazione\\\/\"},\"wordCount\":163,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/01\\\/isola-del-liri-scomparsa-ex-sindaco-bartolomucci-il-cordoglio-di-quadrini-e-dellamministrazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/bartolomucci.jpg\",\"keywords\":[\"Enzoo Martolomucci\",\"isola del liri\",\"massimiliano quadrini\",\"vincenzo quadrini\"],\"articleSection\":[\"*PRIMO PIANO*\",\"News\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/01\\\/isola-del-liri-scomparsa-ex-sindaco-bartolomucci-il-cordoglio-di-quadrini-e-dellamministrazione\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/01\\\/isola-del-liri-scomparsa-ex-sindaco-bartolomucci-il-cordoglio-di-quadrini-e-dellamministrazione\\\/\",\"name\":\"Scomparsa ex sindaco Bartolomucci, l'amministrazione Quadrini lo ricorda - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/01\\\/isola-del-liri-scomparsa-ex-sindaco-bartolomucci-il-cordoglio-di-quadrini-e-dellamministrazione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/01\\\/isola-del-liri-scomparsa-ex-sindaco-bartolomucci-il-cordoglio-di-quadrini-e-dellamministrazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/bartolomucci.jpg\",\"datePublished\":\"2019-06-01T12:58:26+00:00\",\"dateModified\":\"2019-06-01T13:06:07+00:00\",\"description\":\"Un primo o cittadino \u00a0molto popolare, profondamente radicato nel territorio, impegnato nel sociale e nello sport, anima dell\u2019Asaci\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/01\\\/isola-del-liri-scomparsa-ex-sindaco-bartolomucci-il-cordoglio-di-quadrini-e-dellamministrazione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/01\\\/isola-del-liri-scomparsa-ex-sindaco-bartolomucci-il-cordoglio-di-quadrini-e-dellamministrazione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/01\\\/isola-del-liri-scomparsa-ex-sindaco-bartolomucci-il-cordoglio-di-quadrini-e-dellamministrazione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/bartolomucci.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/bartolomucci.jpg\",\"width\":960,\"height\":636},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/01\\\/isola-del-liri-scomparsa-ex-sindaco-bartolomucci-il-cordoglio-di-quadrini-e-dellamministrazione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Scomparsa ex sindaco Bartolomucci, l&#8217;amministrazione Quadrini lo ricorda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/01\\\/isola-del-liri-scomparsa-ex-sindaco-bartolomucci-il-cordoglio-di-quadrini-e-dellamministrazione\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/01\\\/isola-del-liri-scomparsa-ex-sindaco-bartolomucci-il-cordoglio-di-quadrini-e-dellamministrazione\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/06\\\/01\\\/isola-del-liri-scomparsa-ex-sindaco-bartolomucci-il-cordoglio-di-quadrini-e-dellamministrazione\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Scomparsa ex sindaco Bartolomucci, l'amministrazione Quadrini lo ricorda - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Un primo o cittadino \u00a0molto popolare, profondamente radicato nel territorio, impegnato nel sociale e nello sport, anima dell\u2019Asaci","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/01\/isola-del-liri-scomparsa-ex-sindaco-bartolomucci-il-cordoglio-di-quadrini-e-dellamministrazione\/","og_locale":"it_IT","og_type":"article","og_title":"Scomparsa ex sindaco Bartolomucci, l'amministrazione Quadrini lo ricorda","og_description":"Un primo o cittadino \u00a0molto popolare, profondamente radicato nel territorio, impegnato nel sociale e nello sport, anima dell\u2019Asaci","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/01\/isola-del-liri-scomparsa-ex-sindaco-bartolomucci-il-cordoglio-di-quadrini-e-dellamministrazione\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-06-01T12:58:26+00:00","article_modified_time":"2019-06-01T13:06:07+00:00","og_image":[{"width":960,"height":636,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/bartolomucci.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/01\/isola-del-liri-scomparsa-ex-sindaco-bartolomucci-il-cordoglio-di-quadrini-e-dellamministrazione\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/01\/isola-del-liri-scomparsa-ex-sindaco-bartolomucci-il-cordoglio-di-quadrini-e-dellamministrazione\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Scomparsa ex sindaco Bartolomucci, l&#8217;amministrazione Quadrini lo ricorda","datePublished":"2019-06-01T12:58:26+00:00","dateModified":"2019-06-01T13:06:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/01\/isola-del-liri-scomparsa-ex-sindaco-bartolomucci-il-cordoglio-di-quadrini-e-dellamministrazione\/"},"wordCount":163,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/01\/isola-del-liri-scomparsa-ex-sindaco-bartolomucci-il-cordoglio-di-quadrini-e-dellamministrazione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/bartolomucci.jpg","keywords":["Enzoo Martolomucci","isola del liri","massimiliano quadrini","vincenzo quadrini"],"articleSection":["*PRIMO PIANO*","News"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/01\/isola-del-liri-scomparsa-ex-sindaco-bartolomucci-il-cordoglio-di-quadrini-e-dellamministrazione\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/01\/isola-del-liri-scomparsa-ex-sindaco-bartolomucci-il-cordoglio-di-quadrini-e-dellamministrazione\/","name":"Scomparsa ex sindaco Bartolomucci, l'amministrazione Quadrini lo ricorda - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/01\/isola-del-liri-scomparsa-ex-sindaco-bartolomucci-il-cordoglio-di-quadrini-e-dellamministrazione\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/01\/isola-del-liri-scomparsa-ex-sindaco-bartolomucci-il-cordoglio-di-quadrini-e-dellamministrazione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/bartolomucci.jpg","datePublished":"2019-06-01T12:58:26+00:00","dateModified":"2019-06-01T13:06:07+00:00","description":"Un primo o cittadino \u00a0molto popolare, profondamente radicato nel territorio, impegnato nel sociale e nello sport, anima dell\u2019Asaci","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/01\/isola-del-liri-scomparsa-ex-sindaco-bartolomucci-il-cordoglio-di-quadrini-e-dellamministrazione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/01\/isola-del-liri-scomparsa-ex-sindaco-bartolomucci-il-cordoglio-di-quadrini-e-dellamministrazione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/01\/isola-del-liri-scomparsa-ex-sindaco-bartolomucci-il-cordoglio-di-quadrini-e-dellamministrazione\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/bartolomucci.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/bartolomucci.jpg","width":960,"height":636},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/01\/isola-del-liri-scomparsa-ex-sindaco-bartolomucci-il-cordoglio-di-quadrini-e-dellamministrazione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Scomparsa ex sindaco Bartolomucci, l&#8217;amministrazione Quadrini lo ricorda"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/01\/isola-del-liri-scomparsa-ex-sindaco-bartolomucci-il-cordoglio-di-quadrini-e-dellamministrazione\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/01\/isola-del-liri-scomparsa-ex-sindaco-bartolomucci-il-cordoglio-di-quadrini-e-dellamministrazione\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/06\/01\/isola-del-liri-scomparsa-ex-sindaco-bartolomucci-il-cordoglio-di-quadrini-e-dellamministrazione\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/12358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=12358"}],"version-history":[{"count":6,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/12358\/revisions"}],"predecessor-version":[{"id":12365,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/12358\/revisions\/12365"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/12359"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=12358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=12358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=12358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}