{"id":1212,"date":"2018-11-07T16:44:12","date_gmt":"2018-11-07T15:44:12","guid":{"rendered":"http:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=1212"},"modified":"2018-11-07T16:44:12","modified_gmt":"2018-11-07T15:44:12","slug":"isola-del-liri-internet-ultraveloce-sotto-lalbero-di-natale","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/07\/isola-del-liri-internet-ultraveloce-sotto-lalbero-di-natale\/","title":{"rendered":"Isola del Liri: internet ultraveloce sotto l\u2019albero di Natale"},"content":{"rendered":"<p><strong>Isola del Liri<\/strong> sar\u00e0 uno dei primi centri della provincia di Frosinone ad essere raggiunto completamente dalla nuova rete in <strong>fibra ottica<\/strong> grazie al lavoro di <strong>Open Fiber<\/strong>. E gi\u00e0 a Natale non sar\u00e0 pi\u00f9\u2026 un\u2019isola.<\/p>\n<p>A darne notizia \u00e8 l\u2019assessore alla cultura con delega alla smart city, <strong>Lucio Marziale<\/strong>, che parla di una \u201criconversione spontanea\u201d al turismo e alla ristorazione di un centro con una lunga storia industriale alle spalle e un futuro tutto da inventare. \u00a0La citt\u00e0 delle cartiere e della centrale idroelettrica collegata alla cascata, che coincise con la seconda esplosione industriale del paese, oggi \u00e8 pronta per un\u2019altra svolta.<\/p>\n<figure id=\"attachment_1215\" aria-describedby=\"caption-attachment-1215\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1215\" src=\"http:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/lucio-marziale-isola-del-liri-300x200.jpg\" alt=\"assessore cultura isola del liri fibra ottica frosinone ciociaria\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/lucio-marziale-isola-del-liri-300x200.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/lucio-marziale-isola-del-liri-500x333.jpg 500w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/lucio-marziale-isola-del-liri-272x182.jpg 272w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/lucio-marziale-isola-del-liri.jpg 525w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-1215\" class=\"wp-caption-text\">L&#8217;assessore alla cultura Lucio Marziale<\/figcaption><\/figure>\n<h2><strong>L\u2019assessore Marziale: cos\u00ec ci proiettiamo nel futuro<\/strong><\/h2>\n<p>\u201cGi\u00e0 a dicembre \u2013 fa sapere Marziale &#8211; sar\u00e0 completata la rete in fibra ottica di Open Fiber, che porter\u00e0 <strong>Internet ultraveloce<\/strong> in tutto il Comune\u201d. La nuova rete sar\u00e0 aperta a tutti gli operatori, anche locali, che saranno chiamati ad attivare i servizi. \u201cOggi l\u2019<strong>autostrada elettronica<\/strong> \u00e8 pi\u00f9 importante di quella fisica, la fibra consentir\u00e0 di proiettare Isola del Liri nel futuro\u201d \u00e8 l\u2019opinione di Marziale.<\/p>\n<p>\u201cSar\u00e0 uno dei primi Comuni della provincia ad essere collegato\u201d spiega <strong>Graziano Gabriele<\/strong>, field manager di Open Fiber nella provincia di Frosinone. \u201cIl Comune si \u00e8 dimostrato molto aperto, efficiente e ricettivo\u201d aggiunge, spiegando che la <strong>rete sar\u00e0 lunga 6,1 chilometri<\/strong> di cui quasi la met\u00e0 (2,9) stesa sfruttando le infrastrutture dell\u2019illuminazione pubblica gi\u00e0 esistenti. La banda ultra larga di Open Fiber consentir\u00e0 anche di sviluppare i <strong>servizi comunali<\/strong> (come labiblioteca all\u2019interno del parco fluviale), rendere pi\u00f9 attrattive le rassegne musicali e far riscoprire l\u2019archeologia industriale della zona.<\/p>\n<figure id=\"attachment_1217\" aria-describedby=\"caption-attachment-1217\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1217\" src=\"http:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/itis-nicolucci-reggio-isola-del-liri-300x170.jpg\" alt=\"itis nicolucci reggio isola del liri frosinone ciociaria fibra ottica\" width=\"300\" height=\"170\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/itis-nicolucci-reggio-isola-del-liri-300x170.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/itis-nicolucci-reggio-isola-del-liri-500x284.jpg 500w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/itis-nicolucci-reggio-isola-del-liri.jpg 660w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-1217\" class=\"wp-caption-text\">L&#8217;ingresso dell&#8217;Itis Nicolucci Reggio<\/figcaption><\/figure>\n<h2><strong>La ricaduta della fibra ottica sulle scuole e la \u2018mission\u2019 del Nicolucci-Reggio<\/strong><\/h2>\n<p><strong>Mario Luciani<\/strong>, dirigente scolastico dell\u2019Istituto di Istruzione superiore statale \u201cNicolucci-Reggio\u201d, l\u2019unica scuola superiore del territorio comunale, \u00e8 entusiasta anche per un altro motivo.<\/p>\n<p>\u201cArrivare a una velocit\u00e0 di <strong>almeno 100 mega<\/strong> \u2013 dice &#8211; \u00e8 uno degli obiettivi strategici della nostra scuola: la nostra mission \u00e8 diventare il <strong>polo tecnologico<\/strong> della media Valle del Liri\u201d spiega snocciolando i numeri: ai <strong>500 studenti<\/strong> che frequentano l\u2019istituto vanno aggiunti altri <strong>350 nella sede di Sora<\/strong>.\u00a0\u201cAncora oggi garantiamo il <strong>100% di occupazione<\/strong> a due anni dal diploma, soprattutto in informatica e meccanica\u201d. Ora l\u2019arrivo della fibra consentir\u00e0 di collegare classi e laboratori fino a 1 giga di velocit\u00e0.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Isola del Liri sar\u00e0 uno dei primi centri della provincia di Frosinone ad essere raggiunto completamente dalla nuova rete in<\/p>\n","protected":false},"author":7,"featured_media":1219,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[94,420,93,59,260,421,423,422,424],"class_list":["post-1212","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","tag-ciociaria","tag-fibra-ottica","tag-frosinone","tag-internet","tag-isola-del-liri","tag-marziale","tag-open-fiber","tag-rete","tag-servizi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Isola del Liri: internet ultraveloce sotto l\u2019albero di Natale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"A dicembre tutto il comune di Isola del Liri sar\u00e0 raggiunto dalla nuova rete di fibra ottica che porter\u00e0 l&#039;internet ultraveloce ovunque\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/07\/isola-del-liri-internet-ultraveloce-sotto-lalbero-di-natale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Isola del Liri: internet ultraveloce sotto l\u2019albero di Natale\" \/>\n<meta property=\"og:description\" content=\"A dicembre tutto il comune di Isola del Liri sar\u00e0 raggiunto dalla nuova rete di fibra ottica che porter\u00e0 l&#039;internet ultraveloce ovunque\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/07\/isola-del-liri-internet-ultraveloce-sotto-lalbero-di-natale\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"http:\/\/www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-07T15:44:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/cascata-isola-del-liri-panorama-e1541605324196.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"356\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Giulia Abbruzzese\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giulia Abbruzzese\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/07\\\/isola-del-liri-internet-ultraveloce-sotto-lalbero-di-natale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/07\\\/isola-del-liri-internet-ultraveloce-sotto-lalbero-di-natale\\\/\"},\"author\":{\"name\":\"Giulia Abbruzzese\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/58bf90a6d70d54d2f0db83bc3d580351\"},\"headline\":\"Isola del Liri: internet ultraveloce sotto l\u2019albero di Natale\",\"datePublished\":\"2018-11-07T15:44:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/07\\\/isola-del-liri-internet-ultraveloce-sotto-lalbero-di-natale\\\/\"},\"wordCount\":416,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/07\\\/isola-del-liri-internet-ultraveloce-sotto-lalbero-di-natale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/cascata-isola-del-liri-panorama-e1541605324196.jpg\",\"keywords\":[\"Ciociaria\",\"fibra ottica\",\"Frosinone\",\"internet\",\"isola del liri\",\"marziale\",\"open fiber\",\"rete\",\"servizi\"],\"articleSection\":[\"*SLIDE*\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/07\\\/isola-del-liri-internet-ultraveloce-sotto-lalbero-di-natale\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/07\\\/isola-del-liri-internet-ultraveloce-sotto-lalbero-di-natale\\\/\",\"name\":\"Isola del Liri: internet ultraveloce sotto l\u2019albero di Natale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/07\\\/isola-del-liri-internet-ultraveloce-sotto-lalbero-di-natale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/07\\\/isola-del-liri-internet-ultraveloce-sotto-lalbero-di-natale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/cascata-isola-del-liri-panorama-e1541605324196.jpg\",\"datePublished\":\"2018-11-07T15:44:12+00:00\",\"description\":\"A dicembre tutto il comune di Isola del Liri sar\u00e0 raggiunto dalla nuova rete di fibra ottica che porter\u00e0 l'internet ultraveloce ovunque\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/07\\\/isola-del-liri-internet-ultraveloce-sotto-lalbero-di-natale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/07\\\/isola-del-liri-internet-ultraveloce-sotto-lalbero-di-natale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/07\\\/isola-del-liri-internet-ultraveloce-sotto-lalbero-di-natale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/cascata-isola-del-liri-panorama-e1541605324196.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/cascata-isola-del-liri-panorama-e1541605324196.jpg\",\"width\":632,\"height\":356,\"caption\":\"Un'immagine della Cascata grande di Isola del Liri\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/07\\\/isola-del-liri-internet-ultraveloce-sotto-lalbero-di-natale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Isola del Liri: internet ultraveloce sotto l\u2019albero di Natale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/07\\\/isola-del-liri-internet-ultraveloce-sotto-lalbero-di-natale\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/07\\\/isola-del-liri-internet-ultraveloce-sotto-lalbero-di-natale\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/58bf90a6d70d54d2f0db83bc3d580351\",\"name\":\"Giulia Abbruzzese\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff9b2f7c2c6d1751e3de0056e95b7af4a6c366bf539cdd639aac86cd1908507f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff9b2f7c2c6d1751e3de0056e95b7af4a6c366bf539cdd639aac86cd1908507f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff9b2f7c2c6d1751e3de0056e95b7af4a6c366bf539cdd639aac86cd1908507f?s=96&d=mm&r=g\",\"caption\":\"Giulia Abbruzzese\"},\"description\":\"Giornalista dei quotidiani online \\\"Il Corriere della Provincia\\\" e \\\"TuNews24.it\\\" e del settimanale \\\"Tu News\\\", ha collaborato anche con il mensile \\\"Qui Magazine\\\" oltre che con il settimanale \\\"Qui Sette\\\"; \u00e8 stata inoltre Caposervizio del quotidiano \\\"\u2018Ciociaria Oggi\\\" e Caporedattore de \\\"Il quotidiano della Ciociaria\\\". Collabora con la rivista \\\"Chic Style\\\".\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"http:\\\/\\\/www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/giulia-abbruzzese\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/07\\\/isola-del-liri-internet-ultraveloce-sotto-lalbero-di-natale\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Isola del Liri: internet ultraveloce sotto l\u2019albero di Natale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"A dicembre tutto il comune di Isola del Liri sar\u00e0 raggiunto dalla nuova rete di fibra ottica che porter\u00e0 l'internet ultraveloce ovunque","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/07\/isola-del-liri-internet-ultraveloce-sotto-lalbero-di-natale\/","og_locale":"it_IT","og_type":"article","og_title":"Isola del Liri: internet ultraveloce sotto l\u2019albero di Natale","og_description":"A dicembre tutto il comune di Isola del Liri sar\u00e0 raggiunto dalla nuova rete di fibra ottica che porter\u00e0 l'internet ultraveloce ovunque","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/07\/isola-del-liri-internet-ultraveloce-sotto-lalbero-di-natale\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"http:\/\/www.facebook.com\/tunews24","article_published_time":"2018-11-07T15:44:12+00:00","og_image":[{"width":632,"height":356,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/cascata-isola-del-liri-panorama-e1541605324196.jpg","type":"image\/jpeg"}],"author":"Giulia Abbruzzese","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Giulia Abbruzzese","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/07\/isola-del-liri-internet-ultraveloce-sotto-lalbero-di-natale\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/07\/isola-del-liri-internet-ultraveloce-sotto-lalbero-di-natale\/"},"author":{"name":"Giulia Abbruzzese","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/58bf90a6d70d54d2f0db83bc3d580351"},"headline":"Isola del Liri: internet ultraveloce sotto l\u2019albero di Natale","datePublished":"2018-11-07T15:44:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/07\/isola-del-liri-internet-ultraveloce-sotto-lalbero-di-natale\/"},"wordCount":416,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/07\/isola-del-liri-internet-ultraveloce-sotto-lalbero-di-natale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/cascata-isola-del-liri-panorama-e1541605324196.jpg","keywords":["Ciociaria","fibra ottica","Frosinone","internet","isola del liri","marziale","open fiber","rete","servizi"],"articleSection":["*SLIDE*"],"inLanguage":"it-IT","copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/07\/isola-del-liri-internet-ultraveloce-sotto-lalbero-di-natale\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/07\/isola-del-liri-internet-ultraveloce-sotto-lalbero-di-natale\/","name":"Isola del Liri: internet ultraveloce sotto l\u2019albero di Natale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/07\/isola-del-liri-internet-ultraveloce-sotto-lalbero-di-natale\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/07\/isola-del-liri-internet-ultraveloce-sotto-lalbero-di-natale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/cascata-isola-del-liri-panorama-e1541605324196.jpg","datePublished":"2018-11-07T15:44:12+00:00","description":"A dicembre tutto il comune di Isola del Liri sar\u00e0 raggiunto dalla nuova rete di fibra ottica che porter\u00e0 l'internet ultraveloce ovunque","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/07\/isola-del-liri-internet-ultraveloce-sotto-lalbero-di-natale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/07\/isola-del-liri-internet-ultraveloce-sotto-lalbero-di-natale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/07\/isola-del-liri-internet-ultraveloce-sotto-lalbero-di-natale\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/cascata-isola-del-liri-panorama-e1541605324196.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/cascata-isola-del-liri-panorama-e1541605324196.jpg","width":632,"height":356,"caption":"Un'immagine della Cascata grande di Isola del Liri"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/07\/isola-del-liri-internet-ultraveloce-sotto-lalbero-di-natale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Isola del Liri: internet ultraveloce sotto l\u2019albero di Natale"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/07\/isola-del-liri-internet-ultraveloce-sotto-lalbero-di-natale\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/07\/isola-del-liri-internet-ultraveloce-sotto-lalbero-di-natale\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/58bf90a6d70d54d2f0db83bc3d580351","name":"Giulia Abbruzzese","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ff9b2f7c2c6d1751e3de0056e95b7af4a6c366bf539cdd639aac86cd1908507f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ff9b2f7c2c6d1751e3de0056e95b7af4a6c366bf539cdd639aac86cd1908507f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ff9b2f7c2c6d1751e3de0056e95b7af4a6c366bf539cdd639aac86cd1908507f?s=96&d=mm&r=g","caption":"Giulia Abbruzzese"},"description":"Giornalista dei quotidiani online \"Il Corriere della Provincia\" e \"TuNews24.it\" e del settimanale \"Tu News\", ha collaborato anche con il mensile \"Qui Magazine\" oltre che con il settimanale \"Qui Sette\"; \u00e8 stata inoltre Caposervizio del quotidiano \"\u2018Ciociaria Oggi\" e Caporedattore de \"Il quotidiano della Ciociaria\". Collabora con la rivista \"Chic Style\".","sameAs":["http:\/\/www.tunews24.it","http:\/\/www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/giulia-abbruzzese\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/07\/isola-del-liri-internet-ultraveloce-sotto-lalbero-di-natale\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/1212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=1212"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/1212\/revisions"}],"predecessor-version":[{"id":1220,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/1212\/revisions\/1220"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/1219"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=1212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=1212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=1212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}