{"id":11593,"date":"2019-05-19T11:54:04","date_gmt":"2019-05-19T09:54:04","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=11593"},"modified":"2019-05-19T11:54:04","modified_gmt":"2019-05-19T09:54:04","slug":"san-giovanni-incarico-15-000-euro-per-la-rete-wi-fi","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/19\/san-giovanni-incarico-15-000-euro-per-la-rete-wi-fi\/","title":{"rendered":"San Giovanni Incarico: 15.000 euro per la rete wi fi"},"content":{"rendered":"<p>Il Comune di San Giovanni Incarico \u00e8 stato finanziato dalla <strong>Commissione Europea<\/strong> con <strong>15.000 euro<\/strong> per la <strong>realizzazione della rete Wi-Fi cittadina<\/strong>. Il progetto WiFi4EU \u00e8 stato seguito dall\u2019assessore alle comunicazioni Gaetano Battaglini che ha ricevuto il plauso del sindaco Paolo Fallone e dell\u2019intera Amministrazione.<\/p>\n<h2>Cosa prevede il finanziamento<\/h2>\n<p>Il finanziamento favorisce lo sviluppo e l\u2019accesso alla rete internet per tutti i cittadini attraverso l\u2019installazione capillare di Access Point. Un modo questo per rendere il servizio efficiente, efficace e fruibile a tutti i cittadini in modo gratuito.<\/p>\n<p>Il Comune di San Giovanni Incarico, fortemente orientato verso lo sviluppo e l\u2019innovazione tecnologica, in ambito delle comunicazioni e dei servizi al cittadino, ha raggiunto anche questo significativo obiettivo grazie all\u2019impegno dell\u2019assessore alle comunicazioni Gaetano Battaglini che ha seguito, personalmente, il bando europeo WiFi4EU che consentir\u00e0 la realizzazione di una rete estesa a tutto il territorio comunale.<\/p>\n<h2>Le dichiarazioni dell&#8217;assessore<\/h2>\n<p>&#8220;Sono davvero entusiasta &#8211; ha detto<strong> l\u2019assessore alle comunicazioni, Gaetano Battaglini<\/strong> &#8211; per questo risultato che permetter\u00e0, grazie al contributo di 15.000 euro, assegnato dalla Commissione Europea, la realizzazione di una rete estesa Wi-Fi che servir\u00e0 le diverse aree del territorio comunale. Questo consentir\u00e0 l\u2019accesso libero e gratuito alla rete internet con la possibilit\u00e0 di un progressivo sviluppo della tecnologia per erogare i vari servizi ai cittadini&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_11594\" aria-describedby=\"caption-attachment-11594\" style=\"width: 632px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-11594 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/gaetano-battaglini-e1558258793854.jpg\" alt=\"Gaetano Battaglini San Giovanni Incarico il corriere della provincia\" width=\"632\" height=\"843\" \/><figcaption id=\"caption-attachment-11594\" class=\"wp-caption-text\">L&#8217;assessore Gaetano Battaglini<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&#8220;Un grande progetto che realizzeremo, a costo zero per le casse comunali, essendo risultati vincitori del bando WiFi4EU. Con il sindaco Fallone &#8211; ha concluso Battaglini &#8211; e l\u2019intera Amministrazione stiamo lavorando anche per lo sviluppo di altri servizi che saranno accessibili dalla rete attraverso il nuovo sito internet comunale che sar\u00e0 lanciato nei prossimi giorni&#8221;.<\/p>\n<h2>Il sindaco: tra i cinque comuni finanziati<\/h2>\n<p>Anche il sindaco Paolo Fallone ha espresso la sua soddisfazione per il raggiungimento di questo obiettivo.<\/p>\n<p>&#8220;Sono soddisfatto &#8211; ha dichiarato il Sindaco Paolo Fallone &#8211; per l\u2019impegno dell\u2019assessore Gaetano Battaglini che, con costanza e particolare dedizione, \u00e8 riuscito ad ottenere il contributo della Commissione Europea di 15mila euro per realizzare la rete Wi-Fi cittadina che offrir\u00e0 un servizio di qualit\u00e0 a tutti&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_5654\" aria-describedby=\"caption-attachment-5654\" style=\"width: 680px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5654 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/Paolo-Fallone-680x365_c.jpg\" alt=\"Paolo Fallone sindaco San Giovanni Incarico il corriere della provincia\" width=\"680\" height=\"365\" \/><figcaption id=\"caption-attachment-5654\" class=\"wp-caption-text\">Il sindaco Paolo Fallone<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&#8220;Sottolineo, inoltre, che nella nostra provincia solo cinque comuni sono stati finanziati e noi con orgoglio siamo uno di quelli. Al pi\u00f9 presto &#8211; ha concluso il sindaco Fallone &#8211; saranno attivati altri e importanti strumenti di comunicazione interconnessi alla rete, grazie ad un progressivo sviluppo dei moderni processi di digitalizzazione per offrire servizi di qualit\u00e0 ai tutti cittadini&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Comune di San Giovanni Incarico \u00e8 stato finanziato dalla Commissione Europea con 15.000 euro per la realizzazione della rete<\/p>\n","protected":false},"author":18,"featured_media":9508,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[3342,4212,837,4211,2890,362,3339],"class_list":["post-11593","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","tag-commissione-europea","tag-comunicazione","tag-finanziamento","tag-gaetano-battaglini","tag-paolo-fallone","tag-progetto","tag-wi-fi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>San Giovanni Incarico: 15.000 euro per la rete wi fi - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Il Comune di San Giovanni Incarico ha ottenuto un finanziamento di 15.000 euro dalla Commissione Europea per il progetto della rete wi fi cittadina\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/19\/san-giovanni-incarico-15-000-euro-per-la-rete-wi-fi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"San Giovanni Incarico: 15.000 euro per la rete wi fi\" \/>\n<meta property=\"og:description\" content=\"Il Comune di San Giovanni Incarico ha ottenuto un finanziamento di 15.000 euro dalla Commissione Europea per il progetto della rete wi fi cittadina\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/19\/san-giovanni-incarico-15-000-euro-per-la-rete-wi-fi\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-19T09:54:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/comune-san-giovanni-incarico-e1554636435982.png\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"393\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/19\\\/san-giovanni-incarico-15-000-euro-per-la-rete-wi-fi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/19\\\/san-giovanni-incarico-15-000-euro-per-la-rete-wi-fi\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"San Giovanni Incarico: 15.000 euro per la rete wi fi\",\"datePublished\":\"2019-05-19T09:54:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/19\\\/san-giovanni-incarico-15-000-euro-per-la-rete-wi-fi\\\/\"},\"wordCount\":445,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/19\\\/san-giovanni-incarico-15-000-euro-per-la-rete-wi-fi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/comune-san-giovanni-incarico-e1554636435982.png\",\"keywords\":[\"commissione europea\",\"comunicazione\",\"finanziamento\",\"gaetano battaglini\",\"Paolo Fallone\",\"progetto\",\"wi-fi\"],\"articleSection\":[\"*PRIMO PIANO*\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/19\\\/san-giovanni-incarico-15-000-euro-per-la-rete-wi-fi\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/19\\\/san-giovanni-incarico-15-000-euro-per-la-rete-wi-fi\\\/\",\"name\":\"San Giovanni Incarico: 15.000 euro per la rete wi fi - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/19\\\/san-giovanni-incarico-15-000-euro-per-la-rete-wi-fi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/19\\\/san-giovanni-incarico-15-000-euro-per-la-rete-wi-fi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/comune-san-giovanni-incarico-e1554636435982.png\",\"datePublished\":\"2019-05-19T09:54:04+00:00\",\"description\":\"Il Comune di San Giovanni Incarico ha ottenuto un finanziamento di 15.000 euro dalla Commissione Europea per il progetto della rete wi fi cittadina\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/19\\\/san-giovanni-incarico-15-000-euro-per-la-rete-wi-fi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/19\\\/san-giovanni-incarico-15-000-euro-per-la-rete-wi-fi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/19\\\/san-giovanni-incarico-15-000-euro-per-la-rete-wi-fi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/comune-san-giovanni-incarico-e1554636435982.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/comune-san-giovanni-incarico-e1554636435982.png\",\"width\":632,\"height\":393,\"caption\":\"Il Comune di San Giovanni Incarico\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/19\\\/san-giovanni-incarico-15-000-euro-per-la-rete-wi-fi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"San Giovanni Incarico: 15.000 euro per la rete wi fi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/19\\\/san-giovanni-incarico-15-000-euro-per-la-rete-wi-fi\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/19\\\/san-giovanni-incarico-15-000-euro-per-la-rete-wi-fi\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/19\\\/san-giovanni-incarico-15-000-euro-per-la-rete-wi-fi\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"San Giovanni Incarico: 15.000 euro per la rete wi fi - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Il Comune di San Giovanni Incarico ha ottenuto un finanziamento di 15.000 euro dalla Commissione Europea per il progetto della rete wi fi cittadina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/19\/san-giovanni-incarico-15-000-euro-per-la-rete-wi-fi\/","og_locale":"it_IT","og_type":"article","og_title":"San Giovanni Incarico: 15.000 euro per la rete wi fi","og_description":"Il Comune di San Giovanni Incarico ha ottenuto un finanziamento di 15.000 euro dalla Commissione Europea per il progetto della rete wi fi cittadina","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/19\/san-giovanni-incarico-15-000-euro-per-la-rete-wi-fi\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-05-19T09:54:04+00:00","og_image":[{"width":632,"height":393,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/comune-san-giovanni-incarico-e1554636435982.png","type":"image\/png"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/19\/san-giovanni-incarico-15-000-euro-per-la-rete-wi-fi\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/19\/san-giovanni-incarico-15-000-euro-per-la-rete-wi-fi\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"San Giovanni Incarico: 15.000 euro per la rete wi fi","datePublished":"2019-05-19T09:54:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/19\/san-giovanni-incarico-15-000-euro-per-la-rete-wi-fi\/"},"wordCount":445,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/19\/san-giovanni-incarico-15-000-euro-per-la-rete-wi-fi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/comune-san-giovanni-incarico-e1554636435982.png","keywords":["commissione europea","comunicazione","finanziamento","gaetano battaglini","Paolo Fallone","progetto","wi-fi"],"articleSection":["*PRIMO PIANO*"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/19\/san-giovanni-incarico-15-000-euro-per-la-rete-wi-fi\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/19\/san-giovanni-incarico-15-000-euro-per-la-rete-wi-fi\/","name":"San Giovanni Incarico: 15.000 euro per la rete wi fi - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/19\/san-giovanni-incarico-15-000-euro-per-la-rete-wi-fi\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/19\/san-giovanni-incarico-15-000-euro-per-la-rete-wi-fi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/comune-san-giovanni-incarico-e1554636435982.png","datePublished":"2019-05-19T09:54:04+00:00","description":"Il Comune di San Giovanni Incarico ha ottenuto un finanziamento di 15.000 euro dalla Commissione Europea per il progetto della rete wi fi cittadina","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/19\/san-giovanni-incarico-15-000-euro-per-la-rete-wi-fi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/19\/san-giovanni-incarico-15-000-euro-per-la-rete-wi-fi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/19\/san-giovanni-incarico-15-000-euro-per-la-rete-wi-fi\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/comune-san-giovanni-incarico-e1554636435982.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/comune-san-giovanni-incarico-e1554636435982.png","width":632,"height":393,"caption":"Il Comune di San Giovanni Incarico"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/19\/san-giovanni-incarico-15-000-euro-per-la-rete-wi-fi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"San Giovanni Incarico: 15.000 euro per la rete wi fi"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/19\/san-giovanni-incarico-15-000-euro-per-la-rete-wi-fi\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/19\/san-giovanni-incarico-15-000-euro-per-la-rete-wi-fi\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/19\/san-giovanni-incarico-15-000-euro-per-la-rete-wi-fi\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/11593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=11593"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/11593\/revisions"}],"predecessor-version":[{"id":11595,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/11593\/revisions\/11595"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/9508"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=11593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=11593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=11593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}