{"id":11507,"date":"2019-05-17T16:22:23","date_gmt":"2019-05-17T14:22:23","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=11507"},"modified":"2019-05-18T16:55:32","modified_gmt":"2019-05-18T14:55:32","slug":"isola-del-liri-quadrini-incontra-i-residenti-ater-di-san-carlo","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/17\/isola-del-liri-quadrini-incontra-i-residenti-ater-di-san-carlo\/","title":{"rendered":"Isola del Liri: Quadrini incontra i residenti Ater di San Carlo"},"content":{"rendered":"<p>Continuano gli appuntamenti elettorali del candidato sindaco<strong> Massimiliano Quadrini<\/strong>.<\/p>\n<p>Domenica prossima, 19 maggio, il capolista di &#8216;Per Isola del Liri&#8217; <strong>incontrer\u00e0 i residenti del quartiere San Carlo<\/strong>, insieme al commissario straordinario dell&#8217;Ater di Frosinone, <strong>Sergio Cippitelli<\/strong> e al candidato <strong>Massimo D&#8217;Orazio<\/strong>.<\/p>\n<h2>Il messaggio di D&#8217;Orazio<\/h2>\n<p>L&#8217;incontro \u00e8 fissato per le 17 presso il porticato della scala 37 G degli alloggi di edilizia residenziale pubblica. &#8220;Da ragazzo sono nato e cresciuto in questo quartiere &#8211; ha scritto D&#8217;Orazio in un post pubblicato sul suo profilo Facebook &#8211; e sento il dovere di invitare tutti voi per ascoltarvi e confrontarci sui reali problemi che quotidianamente viviamo&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_11508\" aria-describedby=\"caption-attachment-11508\" style=\"width: 322px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-11508 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/massimo-dorazio.jpg\" alt=\"Massimo D'Orazio candidato Isola del Liri il corriere della provincia\" width=\"322\" height=\"443\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/massimo-dorazio.jpg 322w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/massimo-dorazio-218x300.jpg 218w\" sizes=\"auto, (max-width: 322px) 100vw, 322px\" \/><figcaption id=\"caption-attachment-11508\" class=\"wp-caption-text\">Massimo D&#8217;Orazio<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Continuano gli appuntamenti elettorali del candidato sindaco Massimiliano Quadrini. Domenica prossima, 19 maggio, il capolista di &#8216;Per Isola del Liri&#8217;<\/p>\n","protected":false},"author":18,"featured_media":9996,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,28],"tags":[141,80,405,260,1775,4184,760,1266,4183,117],"class_list":["post-11507","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-politica","tag-ater","tag-elezioni","tag-incontro","tag-isola-del-liri","tag-massimiliano-quadrini","tag-massimo-dorazio","tag-quartiere","tag-residenti","tag-san-carlo","tag-sindaco"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Isola del Liri: Quadrini incontra i residenti Ater di San Carlo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Domenica prossima, 19 maggio, il candidato sindaco Massimiliano Quadrini incontrer\u00e0 i residenti del quartiere San Carlo con Cippitelli e D&#039;Orazio\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/17\/isola-del-liri-quadrini-incontra-i-residenti-ater-di-san-carlo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Isola del Liri: Quadrini incontra i residenti Ater di San Carlo\" \/>\n<meta property=\"og:description\" content=\"Domenica prossima, 19 maggio, il candidato sindaco Massimiliano Quadrini incontrer\u00e0 i residenti del quartiere San Carlo con Cippitelli e D&#039;Orazio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/17\/isola-del-liri-quadrini-incontra-i-residenti-ater-di-san-carlo\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-17T14:22:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-18T14:55:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/quadrini-saluto-e1555337486387.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"422\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/17\\\/isola-del-liri-quadrini-incontra-i-residenti-ater-di-san-carlo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/17\\\/isola-del-liri-quadrini-incontra-i-residenti-ater-di-san-carlo\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Isola del Liri: Quadrini incontra i residenti Ater di San Carlo\",\"datePublished\":\"2019-05-17T14:22:23+00:00\",\"dateModified\":\"2019-05-18T14:55:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/17\\\/isola-del-liri-quadrini-incontra-i-residenti-ater-di-san-carlo\\\/\"},\"wordCount\":127,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/17\\\/isola-del-liri-quadrini-incontra-i-residenti-ater-di-san-carlo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/quadrini-saluto-e1555337486387.jpg\",\"keywords\":[\"ater\",\"Elezioni\",\"incontro\",\"isola del liri\",\"massimiliano quadrini\",\"massimo d'orazio\",\"quartiere\",\"residenti\",\"san carlo\",\"Sindaco\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Evidenza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/17\\\/isola-del-liri-quadrini-incontra-i-residenti-ater-di-san-carlo\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/17\\\/isola-del-liri-quadrini-incontra-i-residenti-ater-di-san-carlo\\\/\",\"name\":\"Isola del Liri: Quadrini incontra i residenti Ater di San Carlo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/17\\\/isola-del-liri-quadrini-incontra-i-residenti-ater-di-san-carlo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/17\\\/isola-del-liri-quadrini-incontra-i-residenti-ater-di-san-carlo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/quadrini-saluto-e1555337486387.jpg\",\"datePublished\":\"2019-05-17T14:22:23+00:00\",\"dateModified\":\"2019-05-18T14:55:32+00:00\",\"description\":\"Domenica prossima, 19 maggio, il candidato sindaco Massimiliano Quadrini incontrer\u00e0 i residenti del quartiere San Carlo con Cippitelli e D'Orazio\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/17\\\/isola-del-liri-quadrini-incontra-i-residenti-ater-di-san-carlo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/17\\\/isola-del-liri-quadrini-incontra-i-residenti-ater-di-san-carlo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/17\\\/isola-del-liri-quadrini-incontra-i-residenti-ater-di-san-carlo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/quadrini-saluto-e1555337486387.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/quadrini-saluto-e1555337486387.jpg\",\"width\":632,\"height\":422,\"caption\":\"Massimiliano Quadrini si \u00e8 intrattenuto con tanti cittadini intervenuti ieri\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/17\\\/isola-del-liri-quadrini-incontra-i-residenti-ater-di-san-carlo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Isola del Liri: Quadrini incontra i residenti Ater di San Carlo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/17\\\/isola-del-liri-quadrini-incontra-i-residenti-ater-di-san-carlo\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/17\\\/isola-del-liri-quadrini-incontra-i-residenti-ater-di-san-carlo\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/17\\\/isola-del-liri-quadrini-incontra-i-residenti-ater-di-san-carlo\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Isola del Liri: Quadrini incontra i residenti Ater di San Carlo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Domenica prossima, 19 maggio, il candidato sindaco Massimiliano Quadrini incontrer\u00e0 i residenti del quartiere San Carlo con Cippitelli e D'Orazio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/17\/isola-del-liri-quadrini-incontra-i-residenti-ater-di-san-carlo\/","og_locale":"it_IT","og_type":"article","og_title":"Isola del Liri: Quadrini incontra i residenti Ater di San Carlo","og_description":"Domenica prossima, 19 maggio, il candidato sindaco Massimiliano Quadrini incontrer\u00e0 i residenti del quartiere San Carlo con Cippitelli e D'Orazio","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/17\/isola-del-liri-quadrini-incontra-i-residenti-ater-di-san-carlo\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-05-17T14:22:23+00:00","article_modified_time":"2019-05-18T14:55:32+00:00","og_image":[{"width":632,"height":422,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/quadrini-saluto-e1555337486387.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/17\/isola-del-liri-quadrini-incontra-i-residenti-ater-di-san-carlo\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/17\/isola-del-liri-quadrini-incontra-i-residenti-ater-di-san-carlo\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Isola del Liri: Quadrini incontra i residenti Ater di San Carlo","datePublished":"2019-05-17T14:22:23+00:00","dateModified":"2019-05-18T14:55:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/17\/isola-del-liri-quadrini-incontra-i-residenti-ater-di-san-carlo\/"},"wordCount":127,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/17\/isola-del-liri-quadrini-incontra-i-residenti-ater-di-san-carlo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/quadrini-saluto-e1555337486387.jpg","keywords":["ater","Elezioni","incontro","isola del liri","massimiliano quadrini","massimo d'orazio","quartiere","residenti","san carlo","Sindaco"],"articleSection":["*PRIMO PIANO*","Evidenza"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/17\/isola-del-liri-quadrini-incontra-i-residenti-ater-di-san-carlo\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/17\/isola-del-liri-quadrini-incontra-i-residenti-ater-di-san-carlo\/","name":"Isola del Liri: Quadrini incontra i residenti Ater di San Carlo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/17\/isola-del-liri-quadrini-incontra-i-residenti-ater-di-san-carlo\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/17\/isola-del-liri-quadrini-incontra-i-residenti-ater-di-san-carlo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/quadrini-saluto-e1555337486387.jpg","datePublished":"2019-05-17T14:22:23+00:00","dateModified":"2019-05-18T14:55:32+00:00","description":"Domenica prossima, 19 maggio, il candidato sindaco Massimiliano Quadrini incontrer\u00e0 i residenti del quartiere San Carlo con Cippitelli e D'Orazio","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/17\/isola-del-liri-quadrini-incontra-i-residenti-ater-di-san-carlo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/17\/isola-del-liri-quadrini-incontra-i-residenti-ater-di-san-carlo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/17\/isola-del-liri-quadrini-incontra-i-residenti-ater-di-san-carlo\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/quadrini-saluto-e1555337486387.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/quadrini-saluto-e1555337486387.jpg","width":632,"height":422,"caption":"Massimiliano Quadrini si \u00e8 intrattenuto con tanti cittadini intervenuti ieri"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/17\/isola-del-liri-quadrini-incontra-i-residenti-ater-di-san-carlo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Isola del Liri: Quadrini incontra i residenti Ater di San Carlo"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/17\/isola-del-liri-quadrini-incontra-i-residenti-ater-di-san-carlo\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/17\/isola-del-liri-quadrini-incontra-i-residenti-ater-di-san-carlo\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/17\/isola-del-liri-quadrini-incontra-i-residenti-ater-di-san-carlo\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/11507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=11507"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/11507\/revisions"}],"predecessor-version":[{"id":11509,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/11507\/revisions\/11509"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/9996"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=11507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=11507"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=11507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}