{"id":11469,"date":"2019-05-16T19:19:07","date_gmt":"2019-05-16T17:19:07","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=11469"},"modified":"2019-05-16T21:52:00","modified_gmt":"2019-05-16T19:52:00","slug":"later-presenta-il-piano-triennale-delle-opere-2","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/16\/later-presenta-il-piano-triennale-delle-opere-2\/","title":{"rendered":"L&#8217;Ater presenta il piano triennale delle opere"},"content":{"rendered":"<p>Un <strong>investimento complessivo di circa 27 milioni di euro<\/strong> che prevede <strong>44 nuovi alloggi<\/strong> nella provincia di Frosinone e <strong>interventi di manutenzione straordinaria per 400 appartamenti<\/strong>. Una risposta concreta al fabbisogno abitativo della provincia di Frosinone con un limitato consumo di suolo e costruzioni ad alta sostenibilit\u00e0 ambientale.<\/p>\n<p style=\"text-align: left;\">\u00c8 stato presentato questo pomeriggio, nel corso di una <strong>conferenza stampa<\/strong> che si \u00e8 svolta nella sala convegni \u2018Benito Stirpe\u2019 dell\u2019Ater di via Alcide De Gasperi, a Frosinone, il <strong>programma delle opere per il triennio 2019-2021<\/strong>.<\/p>\n<p style=\"text-align: left;\">A fare gli onori di casa il commissario straordinario dell\u2019Azienda territoriale di edilizia residenziale, <strong>Sergio Cippitelli<\/strong>, che ha accolto l\u2019assessore regionale alle Politiche Abitative, <strong>Massimiliano Valeriani<\/strong> e il presidente del Consiglio regionale del Lazio, <strong>Mauro Buschini<\/strong>.<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/WUKP6VZzqgw\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p style=\"text-align: left;\">Prima di illustrare, nel dettaglio, le linee guida del piano, il commissario dell\u2019Ater Cippitelli, insieme all\u2019assessore Valeriani, al presidente Buschini e al sindaco di Ceprano, <strong>Marco Galli<\/strong>, ha consegnato 24 alloggi popolari in localit\u00e0 Chiusa Grande a Ceprano, con un finanziamento di oltre 2,5 milioni di euro.<\/p>\n<h2 style=\"text-align: left;\">L&#8217;intervento del commissario Ater Cippitelli<\/h2>\n<p>&#8220;<em>Un momento di grande emozione<\/em> \u2013 ha sottolineato Cippitelli \u2013 <em>nel vedere la gioia delle famiglie quando hanno ricevuto le chiavi delle loro case. Una delle tante testimonianze del lavoro continuo e importante che l\u2019Ater di Frosinone ha messo in campo per affrontare il grave problema dell\u2019emergenza abitativa&#8221;<\/em>.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_11472\" aria-describedby=\"caption-attachment-11472\" style=\"width: 632px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-11472 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/Alloggi-Ater-Ceprano-3-e1558025331328.jpg\" alt=\"sergio cippitelli ceprano ater il corriere della provincia\" width=\"632\" height=\"364\" \/><figcaption id=\"caption-attachment-11472\" class=\"wp-caption-text\">Un momento dell&#8217;intervento del commissario Ater Sergio Cippitelli a Ceprano<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>Nell\u2019intervento durante la conferenza stampa, poi, il commissario Ater ha elencato i contenuti del programma triennale: oltre ai <strong>24 alloggi di Ceprano<\/strong>, sono previsti l\u2019acquisizione e il recupero di <strong>15 alloggi<\/strong> nel centro storico di <strong>Sora<\/strong>, di cui 7 gi\u00e0 terminati (Fondi Contratti di Quartiere II per 5.456.506,13) e <strong>5 alloggi <\/strong>\u00a0nel comune di <strong>Monte San Giovanni Campano<\/strong> (Fondi ex C.E.R. per 1.120.343 euro). Inoltre sono previsti interventi di manutenzione straordinaria nei comuni di <strong>Ferentino<\/strong> (84 alloggi in via Borsellino); <strong>Cassino<\/strong> (54 alloggi in via Bonomi); <strong>Frosinone<\/strong> (63 alloggi complessivi in Corso Francia, 51 in viale Parigi e un fabbricato in via Claudio Monteverdi); <strong>Pico<\/strong> (19 alloggi in via Civita Farnese); <strong>Ceccano<\/strong> (20 alloggi nel Villaggio UNRRA); <strong>Pontecorvo<\/strong> (37 alloggi in viale Dante); <strong>Sora<\/strong> (34 alloggi in via Roccatani) e <strong>Ripi<\/strong> (30 alloggi in via Muraglione).<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_11475\" aria-describedby=\"caption-attachment-11475\" style=\"width: 632px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-11475 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/Alloggi-Ater-Ceprano2-e1558026189480.jpg\" alt=\"commissario ater cippitelli ceprano alloggi il corriere della provincia\" width=\"632\" height=\"308\" \/><figcaption id=\"caption-attachment-11475\" class=\"wp-caption-text\">Il commissario Ater Cippitelli consegna le chiavi a un&#8217;inquilina degli alloggi di Chiusa Grande<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&#8220;<em>I lavori appena elencati \u2013 <\/em>ha tenuto a precisare il commissario Ater,<strong> Sergio Cippitelli<\/strong><em> \u2013 che riguardano la ristrutturazione e l\u2019efficientamento energetico saranno realizzati grazie ai fondi ottenuti con la legge 80\/2014 e fondi ex C.E.R.. Sappiamo che in questi ultimi anni \u2013 <\/em>ha detto<em> \u2013 l\u2019edilizia residenziale pubblica ha subito notevoli cambiamenti che hanno ridotto in modo sostanziale i fondi destinati ai nostri enti. Un cambiamento che va in controtendenza con il momento storico che stiamo attraversando, in cui la povert\u00e0 \u00e8 sempre in aumento e le richieste di alloggi popolari sempre in crescita&#8221;. <\/em><\/p>\n<p><em>&#8220;Quella di oggi \u00e8 un\u2019ulteriore e importante testimonianza del nostro lavoro, per il quale voglio ringraziare tutti i dipendenti dell\u2019Ater di Frosinone, in modo particolare il direttore, la dottoressa <strong>Nicoletta Paniccia<\/strong>, e i dirigenti che si sono adoperati per ottenere i fondi necessari che ci permetteranno di realizzare le opere nei prossimi anni&#8221;.<\/em><\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_11474\" aria-describedby=\"caption-attachment-11474\" style=\"width: 632px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-11474 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/Alloggi-Ater-Ceprano-e1558025530893.jpg\" alt=\"alloggi ater ceprano il corriere della provincia\" width=\"632\" height=\"308\" \/><figcaption id=\"caption-attachment-11474\" class=\"wp-caption-text\">Gli alloggi Ater di Ceprano consegnati questo pomeriggio<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>Il commissario Sergio Cippitelli ha anche reso noto che l\u2019ultimo bilancio Ater \u00e8 stato chiuso in pareggio, cosa che non accadeva da diversi anni.<\/p>\n<h2>Le parole di Buschini<\/h2>\n<p>Anche il presidente del Consiglio regionale del Lazio, <strong>Mauro Buschini<\/strong>, ha ringraziato l\u2019Ater per il lavoro svolto &#8220;<em>perch\u00e9 \u2013 <\/em>ha detto<em> \u2013 il diritto alla casa \u00e8 uno dei pi\u00f9 importanti. \u00c8 stato davvero emozionante guardare negli occhi le persone che oggi hanno ricevuto le chiavi dei loro appartamenti a Ceprano, a testimonianza non solo dell\u2019ottimo lavoro svolto dall\u2019Ater di Frosinone ma anche dell\u2019affidabilit\u00e0 che la Regione Lazio oggi pu\u00f2 vantare come partner in un\u2019azione ordinata di programmazione degli interventi&#8221;<\/em>.<\/p>\n<h2>L&#8217;assessore Valeriani: un nuovo modello per affrontare il problema casa<\/h2>\n<p>In chiusura l\u2019assessore regionale alle Politiche Abitative, <strong>Massimiliano Valeriani<\/strong>, ha affermato: \u201c<em>Penso che questa conferenza stampa<\/em> <em>possa rappresentare un modello, un nuovo modo di affrontare il problema della casa attraverso gli impegni formali, pubblici per il triennio che andiamo ad illustrare ad amministratori e cittadini&#8221;. <\/em><\/p>\n<p><em>&#8220;Quello di oggi \u00e8 il secondo appuntamento ma lo ripeteremo per tutte le province della nostra Regione perch\u00e9 quello della casa \u00e8 un problema per tante persone: le poche risorse, gli sfratti e la carenza di alloggi per chi non pu\u00f2 permettersi abitazioni a prezzo di mercato hanno creato rilevanti criticit\u00e0. Una difficolt\u00e0 che vogliamo affrontare con un investimento importante e un piano di interventi concreti e in tempi certi. In questa provincia, in particolare, abbiamo previsto investimenti per circa 27 milioni di euro, di cui 10 milioni di euro per le nuove realizzazioni e quasi 17 milioni di euro per interventi di manutenzione straordinaria su alloggi esistenti. Inoltre siamo riusciti a recuperare pi\u00f9 di un milione di euro per lavori di abbattimento di barriere architettoniche sempre in Ciociaria&#8221;. <\/em><\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_11476\" aria-describedby=\"caption-attachment-11476\" style=\"width: 632px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-11476 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/Ater1-e1558025716225.jpg\" alt=\"conferenza stampa ater valeriani cippitelli buschini il corriere della provincia\" width=\"632\" height=\"438\" \/><figcaption id=\"caption-attachment-11476\" class=\"wp-caption-text\">Il tavolo dei relatori alla conferenza stampa dell&#8217;Ater<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>Non solo: l\u2019assessore Valeriani ha annunciato di aver chiesto alle Ater di tutte le province del Lazio di studiare progetti di rigenerazione urbana, \u201c<em>un grande strumento di possibile recupero delle aree abbandonate che hanno bisogno di ricostruzione, ampliamenti e servizi per portare bellezza e armonia nelle periferie. Una grande sfida di recupero \u2013 <\/em>ha concluso \u2013 <em>dei nuclei urbani esistenti perch\u00e9 oggi \u00e8 finita la stagione del consumo del suolo\u201d.<\/em><\/p>\n<p>A portare un saluto sono intervenuti anche la consigliera regionale <strong>Sara Battisti<\/strong> e il presidente della Provincia, <strong>Antonio Pompeo<\/strong>, che hanno elogiato il lavoro svolto e ribadito la necessit\u00e0 di recuperare i centri storici evitando, cos\u00ec, la desertificazione degli stessi e un ulteriore consumo di suolo.<\/p>\n<p>In particolare il presidente Pompeo ha sottolineato come sia &#8220;<em>fondamentale investire in edilizia pubblica per dare risposta alla domanda di alloggi e per recuperare il patrimonio dei nostri centri abitati, coniugando sviluppo e bisogni dei cittadini<\/em>&#8220;.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-11477 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/Ater2-e1558025792178.jpg\" alt=\"conferenza stampa ater il corriere della provincia\" width=\"632\" height=\"356\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un investimento complessivo di circa 27 milioni di euro che prevede 44 nuovi alloggi nella provincia di Frosinone e interventi<\/p>\n","protected":false},"author":7,"featured_media":11478,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,2236],"tags":[4173,842,141,247,4174,93,4177,616,464,4150,1388,847,4148,1721,2809],"class_list":["post-11469","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-attualita","tag-alloggi","tag-antonio-pompeo","tag-ater","tag-ceprano","tag-consegna","tag-frosinone","tag-iacp-frosinone","tag-interventi","tag-manutenzione","tag-massimiliano-valeriani","tag-mauro-buschini","tag-opere","tag-piano-triennale","tag-sara-battisti","tag-sergio-cippitelli"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>L&#039;Ater presenta il piano triennale delle opere - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"L&#039;Ater di Frosinone ha illustrato il piano triennale delle opere 2019-2021 nel corso di una conferenza stampa con l&#039;assessore regionale Valeriani.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/16\/later-presenta-il-piano-triennale-delle-opere-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;Ater presenta il piano triennale delle opere\" \/>\n<meta property=\"og:description\" content=\"L&#039;Ater di Frosinone ha illustrato il piano triennale delle opere 2019-2021 nel corso di una conferenza stampa con l&#039;assessore regionale Valeriani.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/16\/later-presenta-il-piano-triennale-delle-opere-2\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"http:\/\/www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-16T17:19:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-16T19:52:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/Ater3-e1558025156587.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"462\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Giulia Abbruzzese\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giulia Abbruzzese\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/16\\\/later-presenta-il-piano-triennale-delle-opere-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/16\\\/later-presenta-il-piano-triennale-delle-opere-2\\\/\"},\"author\":{\"name\":\"Giulia Abbruzzese\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/58bf90a6d70d54d2f0db83bc3d580351\"},\"headline\":\"L&#8217;Ater presenta il piano triennale delle opere\",\"datePublished\":\"2019-05-16T17:19:07+00:00\",\"dateModified\":\"2019-05-16T19:52:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/16\\\/later-presenta-il-piano-triennale-delle-opere-2\\\/\"},\"wordCount\":1019,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/16\\\/later-presenta-il-piano-triennale-delle-opere-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/05\\\/Ater3-e1558025156587.jpg\",\"keywords\":[\"alloggi\",\"antonio pompeo\",\"ater\",\"ceprano\",\"consegna\",\"Frosinone\",\"Iacp frosinone\",\"interventi\",\"manutenzione\",\"massimiliano valeriani\",\"mauro buschini\",\"opere\",\"piano triennale\",\"Sara Battisti\",\"sergio cippitelli\"],\"articleSection\":[\"*SLIDE*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/16\\\/later-presenta-il-piano-triennale-delle-opere-2\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/16\\\/later-presenta-il-piano-triennale-delle-opere-2\\\/\",\"name\":\"L'Ater presenta il piano triennale delle opere - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/16\\\/later-presenta-il-piano-triennale-delle-opere-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/16\\\/later-presenta-il-piano-triennale-delle-opere-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/05\\\/Ater3-e1558025156587.jpg\",\"datePublished\":\"2019-05-16T17:19:07+00:00\",\"dateModified\":\"2019-05-16T19:52:00+00:00\",\"description\":\"L'Ater di Frosinone ha illustrato il piano triennale delle opere 2019-2021 nel corso di una conferenza stampa con l'assessore regionale Valeriani.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/16\\\/later-presenta-il-piano-triennale-delle-opere-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/16\\\/later-presenta-il-piano-triennale-delle-opere-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/16\\\/later-presenta-il-piano-triennale-delle-opere-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/05\\\/Ater3-e1558025156587.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/05\\\/Ater3-e1558025156587.jpg\",\"width\":632,\"height\":462,\"caption\":\"Il tavolo dei relatori durante la conferenza stampa di oggi all'Ater\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/16\\\/later-presenta-il-piano-triennale-delle-opere-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;Ater presenta il piano triennale delle opere\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/16\\\/later-presenta-il-piano-triennale-delle-opere-2\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/16\\\/later-presenta-il-piano-triennale-delle-opere-2\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/58bf90a6d70d54d2f0db83bc3d580351\",\"name\":\"Giulia Abbruzzese\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff9b2f7c2c6d1751e3de0056e95b7af4a6c366bf539cdd639aac86cd1908507f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff9b2f7c2c6d1751e3de0056e95b7af4a6c366bf539cdd639aac86cd1908507f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff9b2f7c2c6d1751e3de0056e95b7af4a6c366bf539cdd639aac86cd1908507f?s=96&d=mm&r=g\",\"caption\":\"Giulia Abbruzzese\"},\"description\":\"Giornalista dei quotidiani online \\\"Il Corriere della Provincia\\\" e \\\"TuNews24.it\\\" e del settimanale \\\"Tu News\\\", ha collaborato anche con il mensile \\\"Qui Magazine\\\" oltre che con il settimanale \\\"Qui Sette\\\"; \u00e8 stata inoltre Caposervizio del quotidiano \\\"\u2018Ciociaria Oggi\\\" e Caporedattore de \\\"Il quotidiano della Ciociaria\\\". Collabora con la rivista \\\"Chic Style\\\".\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"http:\\\/\\\/www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/giulia-abbruzzese\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/16\\\/later-presenta-il-piano-triennale-delle-opere-2\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"L'Ater presenta il piano triennale delle opere - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"L'Ater di Frosinone ha illustrato il piano triennale delle opere 2019-2021 nel corso di una conferenza stampa con l'assessore regionale Valeriani.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/16\/later-presenta-il-piano-triennale-delle-opere-2\/","og_locale":"it_IT","og_type":"article","og_title":"L'Ater presenta il piano triennale delle opere","og_description":"L'Ater di Frosinone ha illustrato il piano triennale delle opere 2019-2021 nel corso di una conferenza stampa con l'assessore regionale Valeriani.","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/16\/later-presenta-il-piano-triennale-delle-opere-2\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"http:\/\/www.facebook.com\/tunews24","article_published_time":"2019-05-16T17:19:07+00:00","article_modified_time":"2019-05-16T19:52:00+00:00","og_image":[{"width":632,"height":462,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/Ater3-e1558025156587.jpg","type":"image\/jpeg"}],"author":"Giulia Abbruzzese","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Giulia Abbruzzese","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/16\/later-presenta-il-piano-triennale-delle-opere-2\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/16\/later-presenta-il-piano-triennale-delle-opere-2\/"},"author":{"name":"Giulia Abbruzzese","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/58bf90a6d70d54d2f0db83bc3d580351"},"headline":"L&#8217;Ater presenta il piano triennale delle opere","datePublished":"2019-05-16T17:19:07+00:00","dateModified":"2019-05-16T19:52:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/16\/later-presenta-il-piano-triennale-delle-opere-2\/"},"wordCount":1019,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/16\/later-presenta-il-piano-triennale-delle-opere-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/Ater3-e1558025156587.jpg","keywords":["alloggi","antonio pompeo","ater","ceprano","consegna","Frosinone","Iacp frosinone","interventi","manutenzione","massimiliano valeriani","mauro buschini","opere","piano triennale","Sara Battisti","sergio cippitelli"],"articleSection":["*SLIDE*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/16\/later-presenta-il-piano-triennale-delle-opere-2\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/16\/later-presenta-il-piano-triennale-delle-opere-2\/","name":"L'Ater presenta il piano triennale delle opere - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/16\/later-presenta-il-piano-triennale-delle-opere-2\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/16\/later-presenta-il-piano-triennale-delle-opere-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/Ater3-e1558025156587.jpg","datePublished":"2019-05-16T17:19:07+00:00","dateModified":"2019-05-16T19:52:00+00:00","description":"L'Ater di Frosinone ha illustrato il piano triennale delle opere 2019-2021 nel corso di una conferenza stampa con l'assessore regionale Valeriani.","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/16\/later-presenta-il-piano-triennale-delle-opere-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/16\/later-presenta-il-piano-triennale-delle-opere-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/16\/later-presenta-il-piano-triennale-delle-opere-2\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/Ater3-e1558025156587.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/Ater3-e1558025156587.jpg","width":632,"height":462,"caption":"Il tavolo dei relatori durante la conferenza stampa di oggi all'Ater"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/16\/later-presenta-il-piano-triennale-delle-opere-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"L&#8217;Ater presenta il piano triennale delle opere"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/16\/later-presenta-il-piano-triennale-delle-opere-2\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/16\/later-presenta-il-piano-triennale-delle-opere-2\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/58bf90a6d70d54d2f0db83bc3d580351","name":"Giulia Abbruzzese","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ff9b2f7c2c6d1751e3de0056e95b7af4a6c366bf539cdd639aac86cd1908507f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ff9b2f7c2c6d1751e3de0056e95b7af4a6c366bf539cdd639aac86cd1908507f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ff9b2f7c2c6d1751e3de0056e95b7af4a6c366bf539cdd639aac86cd1908507f?s=96&d=mm&r=g","caption":"Giulia Abbruzzese"},"description":"Giornalista dei quotidiani online \"Il Corriere della Provincia\" e \"TuNews24.it\" e del settimanale \"Tu News\", ha collaborato anche con il mensile \"Qui Magazine\" oltre che con il settimanale \"Qui Sette\"; \u00e8 stata inoltre Caposervizio del quotidiano \"\u2018Ciociaria Oggi\" e Caporedattore de \"Il quotidiano della Ciociaria\". Collabora con la rivista \"Chic Style\".","sameAs":["http:\/\/www.tunews24.it","http:\/\/www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/giulia-abbruzzese\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/16\/later-presenta-il-piano-triennale-delle-opere-2\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/11469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=11469"}],"version-history":[{"count":8,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/11469\/revisions"}],"predecessor-version":[{"id":11495,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/11469\/revisions\/11495"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/11478"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=11469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=11469"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=11469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}