{"id":10781,"date":"2019-05-01T09:15:50","date_gmt":"2019-05-01T07:15:50","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=10781"},"modified":"2019-05-01T08:38:07","modified_gmt":"2019-05-01T06:38:07","slug":"sara-battisti-oggi-la-politica-metta-al-primo-posto-il-lavoro","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/01\/sara-battisti-oggi-la-politica-metta-al-primo-posto-il-lavoro\/","title":{"rendered":"Sara Battisti: oggi la politica metta al primo posto il lavoro"},"content":{"rendered":"<p><strong>&#8220;La politica metta al primo posto il lavoro&#8221;<\/strong>. Queste le prime parole del <strong>consigliere regionale Sara Battisti<\/strong> nel commentare la<strong> ricorrenza del 1 Maggio<\/strong>. La vicepresidente della I Commissione alla Pisana sar\u00e0 presente, oggi, al <strong>tradizionale corteo dei sindacati Cgil, Cisl e Uil a Isola del Liri<\/strong>.<\/p>\n<h2>La responsabilit\u00e0 della politica<\/h2>\n<p>&#8220;Il primo maggio si celebra la Festa dei lavoratori, un evento che ricorda le battaglie operaie combattute a met\u00e0 del 1800 per la conquista di diritti e sicurezza sul luogo di lavoro. <strong>Anche quest\u2019anno, per\u00f2, il 1\u00b0 Maggio non pu\u00f2 essere una festa per tante italiane ed italiani<\/strong>, tante donne e tanti giovani&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_8359\" aria-describedby=\"caption-attachment-8359\" style=\"width: 632px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-8359 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/sara-battisti-pd-e1553106260685.jpg\" alt=\"\" width=\"632\" height=\"397\" \/><figcaption id=\"caption-attachment-8359\" class=\"wp-caption-text\">La consigliera regionale del Pd Sara Battisti<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&#8220;La politica ha il dovere di intervenire e cambiare la rotta, rimettendo al primo posto il lavoro. Lo slogan dei sindacati nella manifestazione di Bologna centra le priorit\u00e0: &#8216;La nostra Europa: lavoro, diritti, stato sociale&#8217;. <strong>Solo con un&#8217;Europa unita e forte anche se sicuramente diversa da quella attuale si potranno affermare i diritti del lavoro<\/strong> e avere attenzione allo stato sociale, con politiche rivolte alla crescita ed allo sviluppo. Tutti uniti per il lavoro&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;La politica metta al primo posto il lavoro&#8221;. Queste le prime parole del consigliere regionale Sara Battisti nel commentare la<\/p>\n","protected":false},"author":18,"featured_media":10786,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,17],"tags":[869,870,3129,260,279,253,3822,1721,687,871],"class_list":["post-10781","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-lavoro","tag-cgil","tag-cisl","tag-corteo","tag-isola-del-liri","tag-lavoro","tag-politica","tag-primo-maggio","tag-sara-battisti","tag-sindacati","tag-uil"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Sara Battisti: oggi la politica metta al primo posto il lavoro - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"La consigliera regionale Sara Battisti interviene sulla ricorrenza del primo maggio e chiede alla politica di mettere al primo posto il lavoro\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/01\/sara-battisti-oggi-la-politica-metta-al-primo-posto-il-lavoro\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sara Battisti: oggi la politica metta al primo posto il lavoro\" \/>\n<meta property=\"og:description\" content=\"La consigliera regionale Sara Battisti interviene sulla ricorrenza del primo maggio e chiede alla politica di mettere al primo posto il lavoro\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/01\/sara-battisti-oggi-la-politica-metta-al-primo-posto-il-lavoro\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-01T07:15:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/primo-maggio-isola-e1556690939122.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/01\\\/sara-battisti-oggi-la-politica-metta-al-primo-posto-il-lavoro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/01\\\/sara-battisti-oggi-la-politica-metta-al-primo-posto-il-lavoro\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Sara Battisti: oggi la politica metta al primo posto il lavoro\",\"datePublished\":\"2019-05-01T07:15:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/01\\\/sara-battisti-oggi-la-politica-metta-al-primo-posto-il-lavoro\\\/\"},\"wordCount\":204,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/01\\\/sara-battisti-oggi-la-politica-metta-al-primo-posto-il-lavoro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/05\\\/primo-maggio-isola-e1556690939122.jpg\",\"keywords\":[\"Cgil\",\"Cisl\",\"corteo\",\"isola del liri\",\"lavoro\",\"politica\",\"Primo Maggio\",\"Sara Battisti\",\"sindacati\",\"Uil\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Lavoro\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/01\\\/sara-battisti-oggi-la-politica-metta-al-primo-posto-il-lavoro\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/01\\\/sara-battisti-oggi-la-politica-metta-al-primo-posto-il-lavoro\\\/\",\"name\":\"Sara Battisti: oggi la politica metta al primo posto il lavoro - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/01\\\/sara-battisti-oggi-la-politica-metta-al-primo-posto-il-lavoro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/01\\\/sara-battisti-oggi-la-politica-metta-al-primo-posto-il-lavoro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/05\\\/primo-maggio-isola-e1556690939122.jpg\",\"datePublished\":\"2019-05-01T07:15:50+00:00\",\"description\":\"La consigliera regionale Sara Battisti interviene sulla ricorrenza del primo maggio e chiede alla politica di mettere al primo posto il lavoro\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/01\\\/sara-battisti-oggi-la-politica-metta-al-primo-posto-il-lavoro\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/01\\\/sara-battisti-oggi-la-politica-metta-al-primo-posto-il-lavoro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/01\\\/sara-battisti-oggi-la-politica-metta-al-primo-posto-il-lavoro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/05\\\/primo-maggio-isola-e1556690939122.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/05\\\/primo-maggio-isola-e1556690939122.jpg\",\"width\":632,\"height\":300,\"caption\":\"Il corteo del primo maggio a Isola del Liri\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/01\\\/sara-battisti-oggi-la-politica-metta-al-primo-posto-il-lavoro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sara Battisti: oggi la politica metta al primo posto il lavoro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/01\\\/sara-battisti-oggi-la-politica-metta-al-primo-posto-il-lavoro\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/01\\\/sara-battisti-oggi-la-politica-metta-al-primo-posto-il-lavoro\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/05\\\/01\\\/sara-battisti-oggi-la-politica-metta-al-primo-posto-il-lavoro\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Sara Battisti: oggi la politica metta al primo posto il lavoro - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"La consigliera regionale Sara Battisti interviene sulla ricorrenza del primo maggio e chiede alla politica di mettere al primo posto il lavoro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/01\/sara-battisti-oggi-la-politica-metta-al-primo-posto-il-lavoro\/","og_locale":"it_IT","og_type":"article","og_title":"Sara Battisti: oggi la politica metta al primo posto il lavoro","og_description":"La consigliera regionale Sara Battisti interviene sulla ricorrenza del primo maggio e chiede alla politica di mettere al primo posto il lavoro","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/01\/sara-battisti-oggi-la-politica-metta-al-primo-posto-il-lavoro\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-05-01T07:15:50+00:00","og_image":[{"width":632,"height":300,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/primo-maggio-isola-e1556690939122.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/01\/sara-battisti-oggi-la-politica-metta-al-primo-posto-il-lavoro\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/01\/sara-battisti-oggi-la-politica-metta-al-primo-posto-il-lavoro\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Sara Battisti: oggi la politica metta al primo posto il lavoro","datePublished":"2019-05-01T07:15:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/01\/sara-battisti-oggi-la-politica-metta-al-primo-posto-il-lavoro\/"},"wordCount":204,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/01\/sara-battisti-oggi-la-politica-metta-al-primo-posto-il-lavoro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/primo-maggio-isola-e1556690939122.jpg","keywords":["Cgil","Cisl","corteo","isola del liri","lavoro","politica","Primo Maggio","Sara Battisti","sindacati","Uil"],"articleSection":["*PRIMO PIANO*","Lavoro"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/01\/sara-battisti-oggi-la-politica-metta-al-primo-posto-il-lavoro\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/01\/sara-battisti-oggi-la-politica-metta-al-primo-posto-il-lavoro\/","name":"Sara Battisti: oggi la politica metta al primo posto il lavoro - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/01\/sara-battisti-oggi-la-politica-metta-al-primo-posto-il-lavoro\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/01\/sara-battisti-oggi-la-politica-metta-al-primo-posto-il-lavoro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/primo-maggio-isola-e1556690939122.jpg","datePublished":"2019-05-01T07:15:50+00:00","description":"La consigliera regionale Sara Battisti interviene sulla ricorrenza del primo maggio e chiede alla politica di mettere al primo posto il lavoro","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/01\/sara-battisti-oggi-la-politica-metta-al-primo-posto-il-lavoro\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/01\/sara-battisti-oggi-la-politica-metta-al-primo-posto-il-lavoro\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/01\/sara-battisti-oggi-la-politica-metta-al-primo-posto-il-lavoro\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/primo-maggio-isola-e1556690939122.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/primo-maggio-isola-e1556690939122.jpg","width":632,"height":300,"caption":"Il corteo del primo maggio a Isola del Liri"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/01\/sara-battisti-oggi-la-politica-metta-al-primo-posto-il-lavoro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Sara Battisti: oggi la politica metta al primo posto il lavoro"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/01\/sara-battisti-oggi-la-politica-metta-al-primo-posto-il-lavoro\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/01\/sara-battisti-oggi-la-politica-metta-al-primo-posto-il-lavoro\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/05\/01\/sara-battisti-oggi-la-politica-metta-al-primo-posto-il-lavoro\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/10781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=10781"}],"version-history":[{"count":3,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/10781\/revisions"}],"predecessor-version":[{"id":10787,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/10781\/revisions\/10787"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/10786"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=10781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=10781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=10781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}