{"id":10703,"date":"2019-04-29T14:25:20","date_gmt":"2019-04-29T12:25:20","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=10703"},"modified":"2019-04-29T14:27:33","modified_gmt":"2019-04-29T12:27:33","slug":"ferentino-sant-ambrogio-tutto-pronto-per-la-festa","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/29\/ferentino-sant-ambrogio-tutto-pronto-per-la-festa\/","title":{"rendered":"Ferentino, Sant&#8217; Ambrogio: tutto pronto per la festa"},"content":{"rendered":"<div dir=\"auto\">Tutto pronto a Ferentino per quello che \u00e8 l\u2019appuntamento pi\u00f9 sentito dalla citt\u00e0: la festa di Sant&#8217; Ambrogio. La macchina organizzativa messa a punto dal Comune, come ogni anno, ha definito tutto il programma nei minimi dettagli.<\/div>\n<h2><\/h2>\n<h2>Macchina organizzativa al lavoro<\/h2>\n<div dir=\"auto\">Sul piano della sicurezza, sarann<strong>o previsti appositi servizi per l\u2019ordine pubblico<\/strong>, cos\u00ec come richiesto dalle ultime normative. Ma quello che spicca &#8211; un tratto essenziale dell\u2019amministrazione cittadina e non solo in occasione di questa ricorrenza &#8211; \u00e8 l\u2019attenzione al decoro e alla manutenzione del territorio.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">In questi giorni, gli operai comunali, insieme agli operatori del servizio civico, hanno lavorato incessantemente per offrire ai tanti fedeli e ai turisti che si riverseranno a Ferentino, l\u2019immagine pi\u00f9 bella della citt\u00e0 che rende omaggio al suo santo patrono.<\/div>\n<h2><\/h2>\n<h2>Navette gratuite<\/h2>\n<div dir=\"auto\"><strong>Attenzione particolare alla cura del verde<\/strong>, all\u2019abbellimento degli spazi con i fiori, alla sistemazione delle strade e degli angoli caratteristici, alla pulizia e al decoro urbano. Insomma, nello stile consueto della citt\u00e0 e dell\u2019amministrazione cittadina, la cura del territorio \u00e8 una priorit\u00e0 che \u00e8 garantita tutto l\u2019anno, soprattutto in occasioni importanti come la festa di Sant&#8217; Ambrogio. Al fine di facilitare l\u2019accesso in citt\u00e0, inoltre, il Comune ha garantito anche stavolta la<strong> presenza del servizio navetta gratuito<\/strong>, cos\u00ec da non intasare il traffico cittadino.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">\n<figure id=\"attachment_1340\" aria-describedby=\"caption-attachment-1340\" style=\"width: 632px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1340\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/presidente-antonio-pompeo-e1549367630584.jpg\" alt=\"antonio pompeo ferentino il corriere della provincia\" width=\"632\" height=\"356\" \/><figcaption id=\"caption-attachment-1340\" class=\"wp-caption-text\">Il sindaco di Ferentino Antonio Pompeo<\/figcaption><\/figure>\n<\/div>\n<div dir=\"auto\"><\/div>\n<h2><\/h2>\n<h2>L&#8217;intervento di Pompeo<\/h2>\n<div dir=\"auto\">\u201c<strong>Voglio ringraziare,<\/strong> a nome della citt\u00e0 e dell\u2019amministrazione \u2013 ha spiegato il sindaco Antonio Pompeo \u2013 tutti coloro che in questi giorni stanno lavorando per far s\u00ec che la festa di Sant&#8217;Ambrogio si svolga nel migliore dei modi: <strong>la macchina comunale, gli operai, gli addetti del servizio civico, le associazioni, la Protezione Civile e la Croce Rossa.<\/strong> Un gioco di squadra efficace e collaudato per vivere al meglio i riti e le secolari tradizioni che legano Ferentino al martire Ambrogio\u201d.<\/div>\n<div dir=\"auto\"><\/div>\n<h2><\/h2>\n<h2>Il programma<\/h2>\n<div dir=\"auto\"><b>Marted\u00ec 30 aprile,<\/b>\u00a0alle ore 11.00, esposizione della Statua di s. <span class=\"il\">Ambrogio<\/span><b>,\u00a0<\/b>opera in argento del 1641. Alle ore 19.45 la processione con\u00a0<b>la sacra Reliquia<\/b>, con l\u2019usanza dei\u00a0<i>lampadini\u00a0<\/i>e delle\u00a0<b>\u201cpant\u00e0sume<\/b>\u201d ad illuminare il percorso nel centro storico.<\/div>\n<div dir=\"auto\"><b>Mercoled\u00ec 1\u00b0 Maggio,\u00a0<\/b>la\u00a0<b>Fiera Mercato<\/b>\u00a0e alle ore 10.00, la santa messa presieduta dal Vascovo Spreafico e\u00a0<b>la tradizionale processione\u00a0<\/b>con la<b>\u00a0Statua del Patrono con la grande Macchina<\/b>, opera dello scultore romano Filippo Cianfarani (1729-1754) portata a spalla da oltre 150 incollatori, suddivisi nelle antiche Confraternite. Alle ore 21.30, in Piazza Matteotti,<b>\u00a0Concerto del 1\u00b0 maggio<\/b>, protagonista\u00a0<b>Riccardo Fogli.\u00a0\u00a0<\/b><\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">A chiudere i festeggiamenti, il tradizionale\u00a0<b>spettacolo pirotecnico,\u00a0<\/b>la sera del<b>\u00a02 maggio<\/b>\u00a0in Piazza Duomo, dopo la reposizione della statua. <b>Venerd\u00ec 3 maggio<\/b>, nella Biblioteca comunale, presentazione del libro di Fernando Popoli, \u201cVado a Roma a fare il Cinema\u201d.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Tutto pronto a Ferentino per quello che \u00e8 l\u2019appuntamento pi\u00f9 sentito dalla citt\u00e0: la festa di Sant&#8217; Ambrogio. La macchina<\/p>\n","protected":false},"author":18,"featured_media":10704,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[842,92,3822,3907],"class_list":["post-10703","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","tag-antonio-pompeo","tag-ferentino","tag-primo-maggio","tag-santambrogio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ferentino, Sant&#039; Ambrogio: tutto pronto per la festa - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Il sindaco Antonio Pompeo ringrazia tutta la macchina organizzativa per l&#039;ecceellente lavoro svolto in questi giorni. Attivate navette gratuite\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/29\/ferentino-sant-ambrogio-tutto-pronto-per-la-festa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ferentino, Sant&#039; Ambrogio: tutto pronto per la festa\" \/>\n<meta property=\"og:description\" content=\"Il sindaco Antonio Pompeo ringrazia tutta la macchina organizzativa per l&#039;ecceellente lavoro svolto in questi giorni. Attivate navette gratuite\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/29\/ferentino-sant-ambrogio-tutto-pronto-per-la-festa\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-29T12:25:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-29T12:27:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/santambrogio-ferentino.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"745\" \/>\n\t<meta property=\"og:image:height\" content=\"497\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/29\\\/ferentino-sant-ambrogio-tutto-pronto-per-la-festa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/29\\\/ferentino-sant-ambrogio-tutto-pronto-per-la-festa\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Ferentino, Sant&#8217; Ambrogio: tutto pronto per la festa\",\"datePublished\":\"2019-04-29T12:25:20+00:00\",\"dateModified\":\"2019-04-29T12:27:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/29\\\/ferentino-sant-ambrogio-tutto-pronto-per-la-festa\\\/\"},\"wordCount\":456,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/29\\\/ferentino-sant-ambrogio-tutto-pronto-per-la-festa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/santambrogio-ferentino.jpg\",\"keywords\":[\"antonio pompeo\",\"ferentino\",\"Primo Maggio\",\"Sant'Ambrogio\"],\"articleSection\":[\"*PRIMO PIANO*\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/29\\\/ferentino-sant-ambrogio-tutto-pronto-per-la-festa\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/29\\\/ferentino-sant-ambrogio-tutto-pronto-per-la-festa\\\/\",\"name\":\"Ferentino, Sant' Ambrogio: tutto pronto per la festa - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/29\\\/ferentino-sant-ambrogio-tutto-pronto-per-la-festa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/29\\\/ferentino-sant-ambrogio-tutto-pronto-per-la-festa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/santambrogio-ferentino.jpg\",\"datePublished\":\"2019-04-29T12:25:20+00:00\",\"dateModified\":\"2019-04-29T12:27:33+00:00\",\"description\":\"Il sindaco Antonio Pompeo ringrazia tutta la macchina organizzativa per l'ecceellente lavoro svolto in questi giorni. Attivate navette gratuite\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/29\\\/ferentino-sant-ambrogio-tutto-pronto-per-la-festa\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/29\\\/ferentino-sant-ambrogio-tutto-pronto-per-la-festa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/29\\\/ferentino-sant-ambrogio-tutto-pronto-per-la-festa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/santambrogio-ferentino.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/santambrogio-ferentino.jpg\",\"width\":745,\"height\":497},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/29\\\/ferentino-sant-ambrogio-tutto-pronto-per-la-festa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ferentino, Sant&#8217; Ambrogio: tutto pronto per la festa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/29\\\/ferentino-sant-ambrogio-tutto-pronto-per-la-festa\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/29\\\/ferentino-sant-ambrogio-tutto-pronto-per-la-festa\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/29\\\/ferentino-sant-ambrogio-tutto-pronto-per-la-festa\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ferentino, Sant' Ambrogio: tutto pronto per la festa - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Il sindaco Antonio Pompeo ringrazia tutta la macchina organizzativa per l'ecceellente lavoro svolto in questi giorni. Attivate navette gratuite","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/29\/ferentino-sant-ambrogio-tutto-pronto-per-la-festa\/","og_locale":"it_IT","og_type":"article","og_title":"Ferentino, Sant' Ambrogio: tutto pronto per la festa","og_description":"Il sindaco Antonio Pompeo ringrazia tutta la macchina organizzativa per l'ecceellente lavoro svolto in questi giorni. Attivate navette gratuite","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/29\/ferentino-sant-ambrogio-tutto-pronto-per-la-festa\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-04-29T12:25:20+00:00","article_modified_time":"2019-04-29T12:27:33+00:00","og_image":[{"width":745,"height":497,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/santambrogio-ferentino.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/29\/ferentino-sant-ambrogio-tutto-pronto-per-la-festa\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/29\/ferentino-sant-ambrogio-tutto-pronto-per-la-festa\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Ferentino, Sant&#8217; Ambrogio: tutto pronto per la festa","datePublished":"2019-04-29T12:25:20+00:00","dateModified":"2019-04-29T12:27:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/29\/ferentino-sant-ambrogio-tutto-pronto-per-la-festa\/"},"wordCount":456,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/29\/ferentino-sant-ambrogio-tutto-pronto-per-la-festa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/santambrogio-ferentino.jpg","keywords":["antonio pompeo","ferentino","Primo Maggio","Sant'Ambrogio"],"articleSection":["*PRIMO PIANO*"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/29\/ferentino-sant-ambrogio-tutto-pronto-per-la-festa\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/29\/ferentino-sant-ambrogio-tutto-pronto-per-la-festa\/","name":"Ferentino, Sant' Ambrogio: tutto pronto per la festa - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/29\/ferentino-sant-ambrogio-tutto-pronto-per-la-festa\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/29\/ferentino-sant-ambrogio-tutto-pronto-per-la-festa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/santambrogio-ferentino.jpg","datePublished":"2019-04-29T12:25:20+00:00","dateModified":"2019-04-29T12:27:33+00:00","description":"Il sindaco Antonio Pompeo ringrazia tutta la macchina organizzativa per l'ecceellente lavoro svolto in questi giorni. Attivate navette gratuite","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/29\/ferentino-sant-ambrogio-tutto-pronto-per-la-festa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/29\/ferentino-sant-ambrogio-tutto-pronto-per-la-festa\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/29\/ferentino-sant-ambrogio-tutto-pronto-per-la-festa\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/santambrogio-ferentino.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/santambrogio-ferentino.jpg","width":745,"height":497},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/29\/ferentino-sant-ambrogio-tutto-pronto-per-la-festa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Ferentino, Sant&#8217; Ambrogio: tutto pronto per la festa"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/29\/ferentino-sant-ambrogio-tutto-pronto-per-la-festa\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/29\/ferentino-sant-ambrogio-tutto-pronto-per-la-festa\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/29\/ferentino-sant-ambrogio-tutto-pronto-per-la-festa\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/10703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=10703"}],"version-history":[{"count":3,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/10703\/revisions"}],"predecessor-version":[{"id":10707,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/10703\/revisions\/10707"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/10704"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=10703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=10703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=10703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}