{"id":10685,"date":"2019-04-28T15:51:03","date_gmt":"2019-04-28T13:51:03","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=10685"},"modified":"2019-04-28T15:51:03","modified_gmt":"2019-04-28T13:51:03","slug":"ciacciarelli-fi-gioca-un-ruolo-decisivo-sui-territori-candidati-competenti","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/28\/ciacciarelli-fi-gioca-un-ruolo-decisivo-sui-territori-candidati-competenti\/","title":{"rendered":"Ciacciarelli: FI gioca un ruolo decisivo sui territori, candidati competenti"},"content":{"rendered":"<p><strong>\u201cInstancabile il lavoro<\/strong> che in queste ore hanno svolto militanti e dirigenti di Forza Italia per la presentazione delle liste elettorali \u00a0in attesa del voto per le amministrative. <strong>Alle urne andranno 39 comuni ciociari<\/strong>, circa un terzo dell\u2019intera popolazione della provincia sar\u00e0, quindi, chiamata a votare il rinnovo del consiglio comunale&#8221;.\u00a0Si \u00e8 espresso cos\u00ec il consigliere regionale di Forza Italia<strong> Pasquale Ciacciarelli<\/strong>.<\/p>\n<h2>I candidati<\/h2>\n<p>&#8220;Abbiamo svolto un ottimo lavoro sui territori &#8211; ha fatto notare &#8211; \u00a0schierando candidati capaci e competitivi.<strong> A Cassino il centrodestra ha trovato l\u2019unit\u00e0 attorno a una figura di spicco come quella di Mario Abbruzzese<\/strong>, che per la citt\u00e0 non ha varato soltanto un programma, ma un vero e proprio piano di sviluppo industriale. Ad <strong>Arnara<\/strong> abbiamo schierato il nostro<strong> Adriano Roma<\/strong>, ad<strong> Arce<\/strong> una professionista come l\u2019avvocato<strong> Sara Simone<\/strong>, a <strong>Paliano Tommaso Cenciarelli<\/strong>, <strong>Corte a Coreno e Moscone a Casalvier<\/strong>i. A\u00a0<strong>Strangolagalli<\/strong> c&#8217;\u00e8 il nostro giovane<strong> Cristian Viselli.\u00a0<\/strong>\u00a0Correr\u00e0 per la fascia tricolore anche un altro under 35,<strong> Francesco Lavalle<\/strong>, (30 anni),<strong> a San Giorgio a Lir<\/strong>i.<\/p>\n<h2>L&#8217;analisi<\/h2>\n<p>&#8220;Oggi candidarsi a sindaco &#8211; ha aggiunto &#8211; \u00e8 una sfida assai ardua, i problemi da affrontare sono molti e le risorse sempre troppo poche: un passo del genere denota amore per il proprio paese e per la propria comunit\u00e0. <strong>Rivolgo un grande in bocca al lupo a tutti i nostri candidati<\/strong> che correranno per la fascia tricolore, e a quelli che hanno deciso di metterci la faccia nelle liste e portare il loro contributo di idee e progetti, nella speranza di essere eletti e \u00a0sedere in consiglio comunale&#8221;.<\/p>\n<p>&#8220;Quella che ci aspetta &#8211; ha concluso Ciacciarelli &#8211;<strong> sar\u00e0 un\u2019altra grande avventura<\/strong>, che affronteremo con lo spirito e la dedizione di sempre. Forza Italia ha dimostrato di giocare un ruolo decisivo sui territori e di essere indispensabile alla coalizione di Centrodestra.\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cInstancabile il lavoro che in queste ore hanno svolto militanti e dirigenti di Forza Italia per la presentazione delle liste<\/p>\n","protected":false},"author":18,"featured_media":1056,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[2156,3899,80,1109,3651,1226,3900,3898,3163,3901],"class_list":["post-10685","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-adriano-roma","tag-corte-cenciarelli","tag-elezioni","tag-forza-italia","tag-lavalle","tag-mario-abbruzzese","tag-moscone","tag-pasquale-cicciarelli","tag-sara-simone","tag-viselli"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ciacciarelli: FI gioca un ruolo decisivo sui territori, candidati competenti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Il consigliere regionale di Forza Italia apprezza il lavoro svolto dagli uomini del partito e fa un in bocca al lupo a chi concorre.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/28\/ciacciarelli-fi-gioca-un-ruolo-decisivo-sui-territori-candidati-competenti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ciacciarelli: FI gioca un ruolo decisivo sui territori, candidati competenti\" \/>\n<meta property=\"og:description\" content=\"Il consigliere regionale di Forza Italia apprezza il lavoro svolto dagli uomini del partito e fa un in bocca al lupo a chi concorre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/28\/ciacciarelli-fi-gioca-un-ruolo-decisivo-sui-territori-candidati-competenti\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-28T13:51:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/Ciacciarelli-pasquale-regione.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1059\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/28\\\/ciacciarelli-fi-gioca-un-ruolo-decisivo-sui-territori-candidati-competenti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/28\\\/ciacciarelli-fi-gioca-un-ruolo-decisivo-sui-territori-candidati-competenti\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Ciacciarelli: FI gioca un ruolo decisivo sui territori, candidati competenti\",\"datePublished\":\"2019-04-28T13:51:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/28\\\/ciacciarelli-fi-gioca-un-ruolo-decisivo-sui-territori-candidati-competenti\\\/\"},\"wordCount\":315,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/28\\\/ciacciarelli-fi-gioca-un-ruolo-decisivo-sui-territori-candidati-competenti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/Ciacciarelli-pasquale-regione.jpg\",\"keywords\":[\"Adriano Roma\",\"Corte Cenciarelli\",\"Elezioni\",\"forza italia\",\"lavalle\",\"mario abbruzzese\",\"Moscone\",\"Pasquale Cicciarelli\",\"sara simone\",\"Viselli\"],\"articleSection\":[\"Evidenza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/28\\\/ciacciarelli-fi-gioca-un-ruolo-decisivo-sui-territori-candidati-competenti\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/28\\\/ciacciarelli-fi-gioca-un-ruolo-decisivo-sui-territori-candidati-competenti\\\/\",\"name\":\"Ciacciarelli: FI gioca un ruolo decisivo sui territori, candidati competenti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/28\\\/ciacciarelli-fi-gioca-un-ruolo-decisivo-sui-territori-candidati-competenti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/28\\\/ciacciarelli-fi-gioca-un-ruolo-decisivo-sui-territori-candidati-competenti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/Ciacciarelli-pasquale-regione.jpg\",\"datePublished\":\"2019-04-28T13:51:03+00:00\",\"description\":\"Il consigliere regionale di Forza Italia apprezza il lavoro svolto dagli uomini del partito e fa un in bocca al lupo a chi concorre.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/28\\\/ciacciarelli-fi-gioca-un-ruolo-decisivo-sui-territori-candidati-competenti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/28\\\/ciacciarelli-fi-gioca-un-ruolo-decisivo-sui-territori-candidati-competenti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/28\\\/ciacciarelli-fi-gioca-un-ruolo-decisivo-sui-territori-candidati-competenti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/Ciacciarelli-pasquale-regione.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/Ciacciarelli-pasquale-regione.jpg\",\"width\":1600,\"height\":1059},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/28\\\/ciacciarelli-fi-gioca-un-ruolo-decisivo-sui-territori-candidati-competenti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ciacciarelli: FI gioca un ruolo decisivo sui territori, candidati competenti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/28\\\/ciacciarelli-fi-gioca-un-ruolo-decisivo-sui-territori-candidati-competenti\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/28\\\/ciacciarelli-fi-gioca-un-ruolo-decisivo-sui-territori-candidati-competenti\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/28\\\/ciacciarelli-fi-gioca-un-ruolo-decisivo-sui-territori-candidati-competenti\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ciacciarelli: FI gioca un ruolo decisivo sui territori, candidati competenti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Il consigliere regionale di Forza Italia apprezza il lavoro svolto dagli uomini del partito e fa un in bocca al lupo a chi concorre.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/28\/ciacciarelli-fi-gioca-un-ruolo-decisivo-sui-territori-candidati-competenti\/","og_locale":"it_IT","og_type":"article","og_title":"Ciacciarelli: FI gioca un ruolo decisivo sui territori, candidati competenti","og_description":"Il consigliere regionale di Forza Italia apprezza il lavoro svolto dagli uomini del partito e fa un in bocca al lupo a chi concorre.","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/28\/ciacciarelli-fi-gioca-un-ruolo-decisivo-sui-territori-candidati-competenti\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-04-28T13:51:03+00:00","og_image":[{"width":1600,"height":1059,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/Ciacciarelli-pasquale-regione.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/28\/ciacciarelli-fi-gioca-un-ruolo-decisivo-sui-territori-candidati-competenti\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/28\/ciacciarelli-fi-gioca-un-ruolo-decisivo-sui-territori-candidati-competenti\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Ciacciarelli: FI gioca un ruolo decisivo sui territori, candidati competenti","datePublished":"2019-04-28T13:51:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/28\/ciacciarelli-fi-gioca-un-ruolo-decisivo-sui-territori-candidati-competenti\/"},"wordCount":315,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/28\/ciacciarelli-fi-gioca-un-ruolo-decisivo-sui-territori-candidati-competenti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/Ciacciarelli-pasquale-regione.jpg","keywords":["Adriano Roma","Corte Cenciarelli","Elezioni","forza italia","lavalle","mario abbruzzese","Moscone","Pasquale Cicciarelli","sara simone","Viselli"],"articleSection":["Evidenza"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/28\/ciacciarelli-fi-gioca-un-ruolo-decisivo-sui-territori-candidati-competenti\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/28\/ciacciarelli-fi-gioca-un-ruolo-decisivo-sui-territori-candidati-competenti\/","name":"Ciacciarelli: FI gioca un ruolo decisivo sui territori, candidati competenti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/28\/ciacciarelli-fi-gioca-un-ruolo-decisivo-sui-territori-candidati-competenti\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/28\/ciacciarelli-fi-gioca-un-ruolo-decisivo-sui-territori-candidati-competenti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/Ciacciarelli-pasquale-regione.jpg","datePublished":"2019-04-28T13:51:03+00:00","description":"Il consigliere regionale di Forza Italia apprezza il lavoro svolto dagli uomini del partito e fa un in bocca al lupo a chi concorre.","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/28\/ciacciarelli-fi-gioca-un-ruolo-decisivo-sui-territori-candidati-competenti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/28\/ciacciarelli-fi-gioca-un-ruolo-decisivo-sui-territori-candidati-competenti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/28\/ciacciarelli-fi-gioca-un-ruolo-decisivo-sui-territori-candidati-competenti\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/Ciacciarelli-pasquale-regione.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/Ciacciarelli-pasquale-regione.jpg","width":1600,"height":1059},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/28\/ciacciarelli-fi-gioca-un-ruolo-decisivo-sui-territori-candidati-competenti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Ciacciarelli: FI gioca un ruolo decisivo sui territori, candidati competenti"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/28\/ciacciarelli-fi-gioca-un-ruolo-decisivo-sui-territori-candidati-competenti\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/28\/ciacciarelli-fi-gioca-un-ruolo-decisivo-sui-territori-candidati-competenti\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/28\/ciacciarelli-fi-gioca-un-ruolo-decisivo-sui-territori-candidati-competenti\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/10685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=10685"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/10685\/revisions"}],"predecessor-version":[{"id":10686,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/10685\/revisions\/10686"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/1056"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=10685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=10685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=10685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}