{"id":10585,"date":"2019-04-27T15:28:11","date_gmt":"2019-04-27T13:28:11","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=10585"},"modified":"2019-04-28T14:41:54","modified_gmt":"2019-04-28T12:41:54","slug":"il-polo-civico-sbarca-a-cassino-e-fa-il-patto-con-petrarcone","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/27\/il-polo-civico-sbarca-a-cassino-e-fa-il-patto-con-petrarcone\/","title":{"rendered":"Il Polo Civico sbarca a Cassino e fa il patto con Petrarcone"},"content":{"rendered":"<p><strong>Il Polo Civico<\/strong>, la formazione che fa capo a Gianfranco Pizzutelli, e che a Frosinone conta un nutrito gruppo di consiglieri comunali di maggioranza, scende in campo anche a Cassino. Il coordinatore cittadino <strong>\u00e8 l&#8217;avvocato Francesco Malafronte.<\/strong><\/p>\n<figure id=\"attachment_10623\" aria-describedby=\"caption-attachment-10623\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10623\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/Gianfranco-Pizzutelli.jpg\" alt=\"Gianfranco Pizzutelli il corriere della provincia ciociaria frosinone\" width=\"640\" height=\"426\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/Gianfranco-Pizzutelli.jpg 640w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/Gianfranco-Pizzutelli-300x200.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/Gianfranco-Pizzutelli-500x333.jpg 500w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/Gianfranco-Pizzutelli-272x182.jpg 272w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-10623\" class=\"wp-caption-text\">Gianfranco Pizzutelli<\/figcaption><\/figure>\n<h2>Ecco la squadra<\/h2>\n<p>Armando Abronzini, Maurizio Bellico, Pino Candelaresi, Elisa Carcione, Manuel Colatosti, Sabrina D&#8217;Aniello, Marisa Del Greco, Ernesto Di Muccio, Guido Di Paolo, Maria Assunta Di Paolo, Maurizio Ghini, Francesca Ingino (detta Igino), Francesco Maddaloni, Robertino Marsella (detto &#8216;Roberto), Annamaria Palmieri, Marcello Pinchera, Velia Ragozzo, Barbara Rizza, Paolo Romito, Enrica Saggese, Saverio Spiridigliozzi (detto &#8216;Saverio), Francesco Talotti, Mirko Carlos Tong Meneses (detto Mirco), Alessandra Veseri.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Polo Civico, la formazione che fa capo a Gianfranco Pizzutelli, e che a Frosinone conta un nutrito gruppo di<\/p>\n","protected":false},"author":18,"featured_media":10587,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[216,80,1257,854],"class_list":["post-10585","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-cassino","tag-elezioni","tag-gianfranco-pizzutelli","tag-polo-civico"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Il Polo Civico sbarca a Cassino e fa il patto con Petrarcone - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"La lista ideata da Ginafranco Pizzutelli sbarca anche nella citt\u00e0 martire. La scelta \u00e8 quella di sostenere Giuseppe Golini Petrarcone\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/27\/il-polo-civico-sbarca-a-cassino-e-fa-il-patto-con-petrarcone\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il Polo Civico sbarca a Cassino e fa il patto con Petrarcone\" \/>\n<meta property=\"og:description\" content=\"La lista ideata da Ginafranco Pizzutelli sbarca anche nella citt\u00e0 martire. La scelta \u00e8 quella di sostenere Giuseppe Golini Petrarcone\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/27\/il-polo-civico-sbarca-a-cassino-e-fa-il-patto-con-petrarcone\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-27T13:28:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-28T12:41:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/Giuseppe-Golini-Petrarcone-il-corriere-della-provincia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"428\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/27\\\/il-polo-civico-sbarca-a-cassino-e-fa-il-patto-con-petrarcone\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/27\\\/il-polo-civico-sbarca-a-cassino-e-fa-il-patto-con-petrarcone\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Il Polo Civico sbarca a Cassino e fa il patto con Petrarcone\",\"datePublished\":\"2019-04-27T13:28:11+00:00\",\"dateModified\":\"2019-04-28T12:41:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/27\\\/il-polo-civico-sbarca-a-cassino-e-fa-il-patto-con-petrarcone\\\/\"},\"wordCount\":125,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/27\\\/il-polo-civico-sbarca-a-cassino-e-fa-il-patto-con-petrarcone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/Giuseppe-Golini-Petrarcone-il-corriere-della-provincia.jpg\",\"keywords\":[\"Cassino\",\"Elezioni\",\"gianfranco Pizzutelli\",\"polo civico\"],\"articleSection\":[\"News\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/27\\\/il-polo-civico-sbarca-a-cassino-e-fa-il-patto-con-petrarcone\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/27\\\/il-polo-civico-sbarca-a-cassino-e-fa-il-patto-con-petrarcone\\\/\",\"name\":\"Il Polo Civico sbarca a Cassino e fa il patto con Petrarcone - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/27\\\/il-polo-civico-sbarca-a-cassino-e-fa-il-patto-con-petrarcone\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/27\\\/il-polo-civico-sbarca-a-cassino-e-fa-il-patto-con-petrarcone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/Giuseppe-Golini-Petrarcone-il-corriere-della-provincia.jpg\",\"datePublished\":\"2019-04-27T13:28:11+00:00\",\"dateModified\":\"2019-04-28T12:41:54+00:00\",\"description\":\"La lista ideata da Ginafranco Pizzutelli sbarca anche nella citt\u00e0 martire. La scelta \u00e8 quella di sostenere Giuseppe Golini Petrarcone\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/27\\\/il-polo-civico-sbarca-a-cassino-e-fa-il-patto-con-petrarcone\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/27\\\/il-polo-civico-sbarca-a-cassino-e-fa-il-patto-con-petrarcone\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/27\\\/il-polo-civico-sbarca-a-cassino-e-fa-il-patto-con-petrarcone\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/Giuseppe-Golini-Petrarcone-il-corriere-della-provincia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/Giuseppe-Golini-Petrarcone-il-corriere-della-provincia.jpg\",\"width\":640,\"height\":428,\"caption\":\"Giuseppe Golini Petrarcone il corriere della provincia Cassino ciociaria frosinone\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/27\\\/il-polo-civico-sbarca-a-cassino-e-fa-il-patto-con-petrarcone\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il Polo Civico sbarca a Cassino e fa il patto con Petrarcone\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/27\\\/il-polo-civico-sbarca-a-cassino-e-fa-il-patto-con-petrarcone\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/27\\\/il-polo-civico-sbarca-a-cassino-e-fa-il-patto-con-petrarcone\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/27\\\/il-polo-civico-sbarca-a-cassino-e-fa-il-patto-con-petrarcone\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Il Polo Civico sbarca a Cassino e fa il patto con Petrarcone - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"La lista ideata da Ginafranco Pizzutelli sbarca anche nella citt\u00e0 martire. La scelta \u00e8 quella di sostenere Giuseppe Golini Petrarcone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/27\/il-polo-civico-sbarca-a-cassino-e-fa-il-patto-con-petrarcone\/","og_locale":"it_IT","og_type":"article","og_title":"Il Polo Civico sbarca a Cassino e fa il patto con Petrarcone","og_description":"La lista ideata da Ginafranco Pizzutelli sbarca anche nella citt\u00e0 martire. La scelta \u00e8 quella di sostenere Giuseppe Golini Petrarcone","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/27\/il-polo-civico-sbarca-a-cassino-e-fa-il-patto-con-petrarcone\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-04-27T13:28:11+00:00","article_modified_time":"2019-04-28T12:41:54+00:00","og_image":[{"width":640,"height":428,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/Giuseppe-Golini-Petrarcone-il-corriere-della-provincia.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/27\/il-polo-civico-sbarca-a-cassino-e-fa-il-patto-con-petrarcone\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/27\/il-polo-civico-sbarca-a-cassino-e-fa-il-patto-con-petrarcone\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Il Polo Civico sbarca a Cassino e fa il patto con Petrarcone","datePublished":"2019-04-27T13:28:11+00:00","dateModified":"2019-04-28T12:41:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/27\/il-polo-civico-sbarca-a-cassino-e-fa-il-patto-con-petrarcone\/"},"wordCount":125,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/27\/il-polo-civico-sbarca-a-cassino-e-fa-il-patto-con-petrarcone\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/Giuseppe-Golini-Petrarcone-il-corriere-della-provincia.jpg","keywords":["Cassino","Elezioni","gianfranco Pizzutelli","polo civico"],"articleSection":["News"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/27\/il-polo-civico-sbarca-a-cassino-e-fa-il-patto-con-petrarcone\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/27\/il-polo-civico-sbarca-a-cassino-e-fa-il-patto-con-petrarcone\/","name":"Il Polo Civico sbarca a Cassino e fa il patto con Petrarcone - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/27\/il-polo-civico-sbarca-a-cassino-e-fa-il-patto-con-petrarcone\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/27\/il-polo-civico-sbarca-a-cassino-e-fa-il-patto-con-petrarcone\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/Giuseppe-Golini-Petrarcone-il-corriere-della-provincia.jpg","datePublished":"2019-04-27T13:28:11+00:00","dateModified":"2019-04-28T12:41:54+00:00","description":"La lista ideata da Ginafranco Pizzutelli sbarca anche nella citt\u00e0 martire. La scelta \u00e8 quella di sostenere Giuseppe Golini Petrarcone","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/27\/il-polo-civico-sbarca-a-cassino-e-fa-il-patto-con-petrarcone\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/27\/il-polo-civico-sbarca-a-cassino-e-fa-il-patto-con-petrarcone\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/27\/il-polo-civico-sbarca-a-cassino-e-fa-il-patto-con-petrarcone\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/Giuseppe-Golini-Petrarcone-il-corriere-della-provincia.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/Giuseppe-Golini-Petrarcone-il-corriere-della-provincia.jpg","width":640,"height":428,"caption":"Giuseppe Golini Petrarcone il corriere della provincia Cassino ciociaria frosinone"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/27\/il-polo-civico-sbarca-a-cassino-e-fa-il-patto-con-petrarcone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Il Polo Civico sbarca a Cassino e fa il patto con Petrarcone"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/27\/il-polo-civico-sbarca-a-cassino-e-fa-il-patto-con-petrarcone\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/27\/il-polo-civico-sbarca-a-cassino-e-fa-il-patto-con-petrarcone\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/27\/il-polo-civico-sbarca-a-cassino-e-fa-il-patto-con-petrarcone\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/10585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=10585"}],"version-history":[{"count":4,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/10585\/revisions"}],"predecessor-version":[{"id":10624,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/10585\/revisions\/10624"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/10587"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=10585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=10585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=10585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}