{"id":10295,"date":"2019-04-20T09:30:18","date_gmt":"2019-04-20T07:30:18","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=10295"},"modified":"2019-04-20T03:53:09","modified_gmt":"2019-04-20T01:53:09","slug":"paliano-continuano-gli-interventi-per-il-decoro-urbano","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/20\/paliano-continuano-gli-interventi-per-il-decoro-urbano\/","title":{"rendered":"Paliano, continuano gli interventi per il decoro urbano"},"content":{"rendered":"<p>L&#8217;Amministrazione comunale prosegue gli <strong>interventi di pulizia nella citt\u00e0<\/strong>. Nella mattinata di ieri, in particolare, l&#8217;azione ha riguardato<strong> la fontana di piazza Marcantonio Colonna<\/strong> e il <strong>parcheggio di viale San Francesco d&#8217;Assisi<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_10300\" aria-describedby=\"caption-attachment-10300\" style=\"width: 632px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-10300 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/parcheggio-paliano-e1555725024247.jpg\" alt=\"parcheggio paliano piazza san francesco d'assisi il corriere della provincia\" width=\"632\" height=\"355\" \/><figcaption id=\"caption-attachment-10300\" class=\"wp-caption-text\">Il parcheggio di piazza San Francesco d&#8217;Assisi a Paliano<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h2>Le parole dell&#8217;assessore Marucci<\/h2>\n<p>&#8220;\u00c8 ormai diventata pratica abituale e periodica la pulizia dei monumenti e delle altre aree del comune \u2013 ha detto l&#8217;assessore al Servizio rifiuti solidi urbani, Simone Marucci &#8211; <strong>al fine di conservare e tutelare le opere in nostro possesso<\/strong> e <strong>garantire la pulizia dei diversi spazi<\/strong> offrendo agli abitanti un luogo pi\u00f9 vivibile e una citt\u00e0 bella agli occhi dei visitatori. Un ringraziamento al personale della Gea per l\u2019ottimo lavoro svolto&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_10296\" aria-describedby=\"caption-attachment-10296\" style=\"width: 632px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-10296 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/restauro-fontana-paliano-e1555724462105.jpg\" alt=\"fontana piazza marcantonio colonna paliano il corriere della provincia\" width=\"632\" height=\"487\" \/><figcaption id=\"caption-attachment-10296\" class=\"wp-caption-text\">L&#8217;intervento di pulizia della fontana di piazza Marcantonio Colonna<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;Amministrazione comunale prosegue gli interventi di pulizia nella citt\u00e0. Nella mattinata di ieri, in particolare, l&#8217;azione ha riguardato la fontana<\/p>\n","protected":false},"author":18,"featured_media":10301,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2236],"tags":[403,616,605,2358,3761,3762],"class_list":["post-10295","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-attualita","tag-fontana","tag-interventi","tag-paliano","tag-parcheggio","tag-piazza-marcantonio-colonna","tag-san-francesco-dassisi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Paliano, continuano gli interventi per il decoro urbano - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/20\/paliano-continuano-gli-interventi-per-il-decoro-urbano\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paliano, continuano gli interventi per il decoro urbano\" \/>\n<meta property=\"og:description\" content=\"L&#8217;Amministrazione comunale prosegue gli interventi di pulizia nella citt\u00e0. Nella mattinata di ieri, in particolare, l&#8217;azione ha riguardato la fontana\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/20\/paliano-continuano-gli-interventi-per-il-decoro-urbano\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-20T07:30:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/fontana-paliano-restauro-e1555725120940.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"418\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/20\\\/paliano-continuano-gli-interventi-per-il-decoro-urbano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/20\\\/paliano-continuano-gli-interventi-per-il-decoro-urbano\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Paliano, continuano gli interventi per il decoro urbano\",\"datePublished\":\"2019-04-20T07:30:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/20\\\/paliano-continuano-gli-interventi-per-il-decoro-urbano\\\/\"},\"wordCount\":157,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/20\\\/paliano-continuano-gli-interventi-per-il-decoro-urbano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/fontana-paliano-restauro-e1555725120940.jpg\",\"keywords\":[\"fontana\",\"interventi\",\"Paliano\",\"parcheggio\",\"piazza marcantonio colonna\",\"san francesco d'assisi\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/20\\\/paliano-continuano-gli-interventi-per-il-decoro-urbano\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/20\\\/paliano-continuano-gli-interventi-per-il-decoro-urbano\\\/\",\"name\":\"Paliano, continuano gli interventi per il decoro urbano - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/20\\\/paliano-continuano-gli-interventi-per-il-decoro-urbano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/20\\\/paliano-continuano-gli-interventi-per-il-decoro-urbano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/fontana-paliano-restauro-e1555725120940.jpg\",\"datePublished\":\"2019-04-20T07:30:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/20\\\/paliano-continuano-gli-interventi-per-il-decoro-urbano\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/20\\\/paliano-continuano-gli-interventi-per-il-decoro-urbano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/20\\\/paliano-continuano-gli-interventi-per-il-decoro-urbano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/fontana-paliano-restauro-e1555725120940.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/fontana-paliano-restauro-e1555725120940.jpg\",\"width\":632,\"height\":418,\"caption\":\"La fontana di piazza Marcantonio Colonna a Paliano\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/20\\\/paliano-continuano-gli-interventi-per-il-decoro-urbano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paliano, continuano gli interventi per il decoro urbano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/20\\\/paliano-continuano-gli-interventi-per-il-decoro-urbano\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/20\\\/paliano-continuano-gli-interventi-per-il-decoro-urbano\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/20\\\/paliano-continuano-gli-interventi-per-il-decoro-urbano\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Paliano, continuano gli interventi per il decoro urbano - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/20\/paliano-continuano-gli-interventi-per-il-decoro-urbano\/","og_locale":"it_IT","og_type":"article","og_title":"Paliano, continuano gli interventi per il decoro urbano","og_description":"L&#8217;Amministrazione comunale prosegue gli interventi di pulizia nella citt\u00e0. Nella mattinata di ieri, in particolare, l&#8217;azione ha riguardato la fontana","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/20\/paliano-continuano-gli-interventi-per-il-decoro-urbano\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-04-20T07:30:18+00:00","og_image":[{"width":632,"height":418,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/fontana-paliano-restauro-e1555725120940.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/20\/paliano-continuano-gli-interventi-per-il-decoro-urbano\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/20\/paliano-continuano-gli-interventi-per-il-decoro-urbano\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Paliano, continuano gli interventi per il decoro urbano","datePublished":"2019-04-20T07:30:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/20\/paliano-continuano-gli-interventi-per-il-decoro-urbano\/"},"wordCount":157,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/20\/paliano-continuano-gli-interventi-per-il-decoro-urbano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/fontana-paliano-restauro-e1555725120940.jpg","keywords":["fontana","interventi","Paliano","parcheggio","piazza marcantonio colonna","san francesco d'assisi"],"articleSection":["*PRIMO PIANO*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/20\/paliano-continuano-gli-interventi-per-il-decoro-urbano\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/20\/paliano-continuano-gli-interventi-per-il-decoro-urbano\/","name":"Paliano, continuano gli interventi per il decoro urbano - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/20\/paliano-continuano-gli-interventi-per-il-decoro-urbano\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/20\/paliano-continuano-gli-interventi-per-il-decoro-urbano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/fontana-paliano-restauro-e1555725120940.jpg","datePublished":"2019-04-20T07:30:18+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/20\/paliano-continuano-gli-interventi-per-il-decoro-urbano\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/20\/paliano-continuano-gli-interventi-per-il-decoro-urbano\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/20\/paliano-continuano-gli-interventi-per-il-decoro-urbano\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/fontana-paliano-restauro-e1555725120940.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/fontana-paliano-restauro-e1555725120940.jpg","width":632,"height":418,"caption":"La fontana di piazza Marcantonio Colonna a Paliano"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/20\/paliano-continuano-gli-interventi-per-il-decoro-urbano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Paliano, continuano gli interventi per il decoro urbano"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/20\/paliano-continuano-gli-interventi-per-il-decoro-urbano\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/20\/paliano-continuano-gli-interventi-per-il-decoro-urbano\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/20\/paliano-continuano-gli-interventi-per-il-decoro-urbano\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/10295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=10295"}],"version-history":[{"count":3,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/10295\/revisions"}],"predecessor-version":[{"id":10302,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/10295\/revisions\/10302"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/10301"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=10295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=10295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=10295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}