{"id":10268,"date":"2019-04-19T00:18:01","date_gmt":"2019-04-18T22:18:01","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=10268"},"modified":"2019-04-20T07:50:44","modified_gmt":"2019-04-20T05:50:44","slug":"iannarilli-aderisce-a-fdi-meloni-la-sua-esperienza-e-un-valore-aggiunto","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/19\/iannarilli-aderisce-a-fdi-meloni-la-sua-esperienza-e-un-valore-aggiunto\/","title":{"rendered":"Iannarilli aderisce a Fdi. Meloni: la sua esperienza \u00e8 un valore aggiunto"},"content":{"rendered":"<p>&#8220;<strong>La famiglia di Fratelli d&#8217;Italia continua a crescere<\/strong> e accoglie con entusiasmo l&#8217;adesione di\u00a0Antonello Iannarilli: da sempre un punto di riferimento per i cittadini e per il centrodestra nel\u00a0Lazio. La sua lunga esperienza politica, da amministratore locale prima e parlamentare poi, e il suo\u00a0forte radicamento sul territorio saranno un valore aggiunto per il nostro movimento&#8221;. \u00c8\u00a0quanto dichiara il presidente di Fratelli d&#8217;Italia,<strong> Giorgia Meloni.<\/strong><\/p>\n<h2>L&#8217;intervento<\/h2>\n<p>&#8220;Dopo 26 anni di militanza in Forza Italia e dopo un periodo di profonda e sofferta riflessione\u00a0personale &#8211; evidenzia Antonello Iannarilli &#8211; <strong>\u00a0ho deciso di continuare a fare politica ma, questa\u00a0volta, a modo mio<\/strong> e con la tenacia e la caparbiet\u00e0 che mi distingue.\u00a0In questi ultimi anni, non per mia scelta, ho fatto poca politica, mi sono allontanato dalla\u00a0partecipazione attiva in Forza Italia perch\u00e9 non ho accettato e condiviso le &#8216;scelte locali&#8217; indicate\u00a0dai vertici nazionali e regionali per la mia provincia; ho provato pi\u00f9 volte a contrastare il sistema,\u00a0sottolineando la forza dell\u2019elettorato di questo territorio e del diverso modus operandi ma, non\u00a0riuscendoci, ho preferito non farmi condizionare da decisioni prive di trasparenza e di virtuoso\u00a0attivismo civico&#8221;.<\/p>\n<h2>Le motivazioni<\/h2>\n<p>&#8220;La scelta, per me e per molti miei colleghi, che si sono allontanati dalle prime fila del Partito, \u00e8\u00a0stata sofferta perch\u00e9, ad oggi, \u00e8 chiaro ed evidente a tutti, ch<strong>e il Partito \u00e8 stato violentato,\u00a0mortificato e bistrattato<\/strong> da irresponsabili privi di ideali ed attratti dal proprio &#8216;io&#8217;; non esiste pi\u00f9 il\u00a0Partito che ho fondato in questa Provincia e per il quale ho lottato andando contro tutto e tutti.<\/p>\n<p>&#8220;Dopo qualche mese dalla mia dichiarazione di distacco dalle fila di Forza Italia, avvenuto a\u00a0dicembre 2018, <strong>sono stato contattato dall\u2019amico Alfredo, l\u2019onorevole Antoniozzi<\/strong>, gi\u00e0\u00a0parlamentare europeo, per propormi di valutare il nuovo progetto politico di Giorgia Meloni,\u00a0leader indiscussa di Fratelli d\u2019Italia, ispirato ad una concezione della politica e delle istituzioni che\u00a0sostiene i territori e che garantisce concrete risposte ai disagi ed alle difficolt\u00e0 di una Italia in\u00a0affanno, lottando per il lavoro, per costruire una opportunit\u00e0 ai tanti che l\u2019hanno presa o che non\u00a0l\u2019hanno mai trovata, sostenendo quegli imprenditori che ogni giorno si confrontano con una crisi\u00a0che li sta soffocando&#8221;.<\/p>\n<h2>L&#8217;obiettivo<\/h2>\n<p>&#8220;<strong>Serve rivoluzionare l\u2019Italia, la mia Provincia, la mia Regione<\/strong>, serve cio\u00e8 cambiare una classe politica\u00a0perch\u00e9 si rischia di perdere forze preziose e minare quel patto tra generazioni su cui si deve\u00a0fondare un progetto comunitario, ma per merito, laboriosit\u00e0, passione civica, competenza e\u00a0soprattutto onest\u00e0. \u00a0Vogliamo tutti rigenerare un\u2019Italia all\u2019altezza delle criticit\u00e0 del nostro tempo.\u00a0Tutti noi pretendiamo che la politica torni ad essere impegno civico, passione per le idee e per la\u00a0loro affermazione, volont\u00e0 di costruire un modello sociale compatibile con i valori per cui ci si\u00a0batte a difesa dei pi\u00f9 deboli.<\/p>\n<p>&#8220;La mia scelta \u00e8 stata volutamente fatta in un periodo storico nazionale molto particolare e\u00a0delicato; <strong>la gente \u00e8 scontenta, delusa, amareggiata, sofferente, stanca dei continui sacrifici<\/strong>.\u00a0Non ho accettato poltrone comode o incarichi prestigiosi; non sono salito sul &#8216;carro del vincitore&#8217;.\u00a0Mi \u00e8 stata data, dagli onorevoli Giorgia Meloni ed Alfredo Antoniozzi la possibilit\u00e0 reale e concreta\u00a0di difendere e lottare per i diritti dei cittadini tutti, con la forza e la passione che sempre ha\u00a0caratterizzato il mio agire&#8221;.<\/p>\n<p>&#8220;<strong>Ho accettato perch\u00e9 il progetto politico delineato dall\u2019onorevole Meloni trova fondamento nei valori<\/strong> che\u00a0costituiscono patrimonio comune di tanti e perch\u00e9 il percorso che mi \u00e8 stato proposto corrisponde\u00a0al mio ideale di fare politica: contribuire, con tenacia, lealt\u00e0 e determinazione alla difesa dei diritti\u00a0della gente tutta, nessuno escluso&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;La famiglia di Fratelli d&#8217;Italia continua a crescere e accoglie con entusiasmo l&#8217;adesione di\u00a0Antonello Iannarilli: da sempre un punto di<\/p>\n","protected":false},"author":18,"featured_media":10269,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,28],"tags":[3754,3529,1109,1012,3559],"class_list":["post-10268","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-politica","tag-alfredo-antoniozzi","tag-antonello-iannarilli","tag-forza-italia","tag-fratelli-ditalia","tag-giorgia-meloni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Iannarilli aderisce a Fdi. Meloni: la sua esperienza \u00e8 un valore aggiunto - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Antonello Iannarilli torna in campo e aderisce a Fratelli d&#039;Italia. Guarda al futuro e spiega le motivazioni di una scelta sofferta.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/19\/iannarilli-aderisce-a-fdi-meloni-la-sua-esperienza-e-un-valore-aggiunto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Iannarilli aderisce a Fdi. Meloni: la sua esperienza \u00e8 un valore aggiunto\" \/>\n<meta property=\"og:description\" content=\"Antonello Iannarilli torna in campo e aderisce a Fratelli d&#039;Italia. Guarda al futuro e spiega le motivazioni di una scelta sofferta.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/19\/iannarilli-aderisce-a-fdi-meloni-la-sua-esperienza-e-un-valore-aggiunto\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-18T22:18:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-20T05:50:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/iannarilli-meloni-il-corriere-della-provincia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1066\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/19\\\/iannarilli-aderisce-a-fdi-meloni-la-sua-esperienza-e-un-valore-aggiunto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/19\\\/iannarilli-aderisce-a-fdi-meloni-la-sua-esperienza-e-un-valore-aggiunto\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Iannarilli aderisce a Fdi. Meloni: la sua esperienza \u00e8 un valore aggiunto\",\"datePublished\":\"2019-04-18T22:18:01+00:00\",\"dateModified\":\"2019-04-20T05:50:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/19\\\/iannarilli-aderisce-a-fdi-meloni-la-sua-esperienza-e-un-valore-aggiunto\\\/\"},\"wordCount\":615,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/19\\\/iannarilli-aderisce-a-fdi-meloni-la-sua-esperienza-e-un-valore-aggiunto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/iannarilli-meloni-il-corriere-della-provincia.jpg\",\"keywords\":[\"Alfredo Antoniozzi\",\"antonello iannarilli\",\"forza italia\",\"Fratelli d'Italia\",\"giorgia meloni\"],\"articleSection\":[\"*SLIDE*\",\"Evidenza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/19\\\/iannarilli-aderisce-a-fdi-meloni-la-sua-esperienza-e-un-valore-aggiunto\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/19\\\/iannarilli-aderisce-a-fdi-meloni-la-sua-esperienza-e-un-valore-aggiunto\\\/\",\"name\":\"Iannarilli aderisce a Fdi. Meloni: la sua esperienza \u00e8 un valore aggiunto - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/19\\\/iannarilli-aderisce-a-fdi-meloni-la-sua-esperienza-e-un-valore-aggiunto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/19\\\/iannarilli-aderisce-a-fdi-meloni-la-sua-esperienza-e-un-valore-aggiunto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/iannarilli-meloni-il-corriere-della-provincia.jpg\",\"datePublished\":\"2019-04-18T22:18:01+00:00\",\"dateModified\":\"2019-04-20T05:50:44+00:00\",\"description\":\"Antonello Iannarilli torna in campo e aderisce a Fratelli d'Italia. Guarda al futuro e spiega le motivazioni di una scelta sofferta.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/19\\\/iannarilli-aderisce-a-fdi-meloni-la-sua-esperienza-e-un-valore-aggiunto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/19\\\/iannarilli-aderisce-a-fdi-meloni-la-sua-esperienza-e-un-valore-aggiunto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/19\\\/iannarilli-aderisce-a-fdi-meloni-la-sua-esperienza-e-un-valore-aggiunto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/iannarilli-meloni-il-corriere-della-provincia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/iannarilli-meloni-il-corriere-della-provincia.jpg\",\"width\":1600,\"height\":1066,\"caption\":\"iannarilli meloni il corriere della provincia frosinone ciociaria\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/19\\\/iannarilli-aderisce-a-fdi-meloni-la-sua-esperienza-e-un-valore-aggiunto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Iannarilli aderisce a Fdi. Meloni: la sua esperienza \u00e8 un valore aggiunto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/19\\\/iannarilli-aderisce-a-fdi-meloni-la-sua-esperienza-e-un-valore-aggiunto\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/19\\\/iannarilli-aderisce-a-fdi-meloni-la-sua-esperienza-e-un-valore-aggiunto\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/19\\\/iannarilli-aderisce-a-fdi-meloni-la-sua-esperienza-e-un-valore-aggiunto\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Iannarilli aderisce a Fdi. Meloni: la sua esperienza \u00e8 un valore aggiunto - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Antonello Iannarilli torna in campo e aderisce a Fratelli d'Italia. Guarda al futuro e spiega le motivazioni di una scelta sofferta.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/19\/iannarilli-aderisce-a-fdi-meloni-la-sua-esperienza-e-un-valore-aggiunto\/","og_locale":"it_IT","og_type":"article","og_title":"Iannarilli aderisce a Fdi. Meloni: la sua esperienza \u00e8 un valore aggiunto","og_description":"Antonello Iannarilli torna in campo e aderisce a Fratelli d'Italia. Guarda al futuro e spiega le motivazioni di una scelta sofferta.","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/19\/iannarilli-aderisce-a-fdi-meloni-la-sua-esperienza-e-un-valore-aggiunto\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-04-18T22:18:01+00:00","article_modified_time":"2019-04-20T05:50:44+00:00","og_image":[{"width":1600,"height":1066,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/iannarilli-meloni-il-corriere-della-provincia.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/19\/iannarilli-aderisce-a-fdi-meloni-la-sua-esperienza-e-un-valore-aggiunto\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/19\/iannarilli-aderisce-a-fdi-meloni-la-sua-esperienza-e-un-valore-aggiunto\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Iannarilli aderisce a Fdi. Meloni: la sua esperienza \u00e8 un valore aggiunto","datePublished":"2019-04-18T22:18:01+00:00","dateModified":"2019-04-20T05:50:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/19\/iannarilli-aderisce-a-fdi-meloni-la-sua-esperienza-e-un-valore-aggiunto\/"},"wordCount":615,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/19\/iannarilli-aderisce-a-fdi-meloni-la-sua-esperienza-e-un-valore-aggiunto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/iannarilli-meloni-il-corriere-della-provincia.jpg","keywords":["Alfredo Antoniozzi","antonello iannarilli","forza italia","Fratelli d'Italia","giorgia meloni"],"articleSection":["*SLIDE*","Evidenza"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/19\/iannarilli-aderisce-a-fdi-meloni-la-sua-esperienza-e-un-valore-aggiunto\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/19\/iannarilli-aderisce-a-fdi-meloni-la-sua-esperienza-e-un-valore-aggiunto\/","name":"Iannarilli aderisce a Fdi. Meloni: la sua esperienza \u00e8 un valore aggiunto - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/19\/iannarilli-aderisce-a-fdi-meloni-la-sua-esperienza-e-un-valore-aggiunto\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/19\/iannarilli-aderisce-a-fdi-meloni-la-sua-esperienza-e-un-valore-aggiunto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/iannarilli-meloni-il-corriere-della-provincia.jpg","datePublished":"2019-04-18T22:18:01+00:00","dateModified":"2019-04-20T05:50:44+00:00","description":"Antonello Iannarilli torna in campo e aderisce a Fratelli d'Italia. Guarda al futuro e spiega le motivazioni di una scelta sofferta.","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/19\/iannarilli-aderisce-a-fdi-meloni-la-sua-esperienza-e-un-valore-aggiunto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/19\/iannarilli-aderisce-a-fdi-meloni-la-sua-esperienza-e-un-valore-aggiunto\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/19\/iannarilli-aderisce-a-fdi-meloni-la-sua-esperienza-e-un-valore-aggiunto\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/iannarilli-meloni-il-corriere-della-provincia.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/iannarilli-meloni-il-corriere-della-provincia.jpg","width":1600,"height":1066,"caption":"iannarilli meloni il corriere della provincia frosinone ciociaria"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/19\/iannarilli-aderisce-a-fdi-meloni-la-sua-esperienza-e-un-valore-aggiunto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Iannarilli aderisce a Fdi. Meloni: la sua esperienza \u00e8 un valore aggiunto"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/19\/iannarilli-aderisce-a-fdi-meloni-la-sua-esperienza-e-un-valore-aggiunto\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/19\/iannarilli-aderisce-a-fdi-meloni-la-sua-esperienza-e-un-valore-aggiunto\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/19\/iannarilli-aderisce-a-fdi-meloni-la-sua-esperienza-e-un-valore-aggiunto\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/10268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=10268"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/10268\/revisions"}],"predecessor-version":[{"id":10270,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/10268\/revisions\/10270"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/10269"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=10268"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=10268"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=10268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}